{"id":186,"date":"2020-07-13T11:53:57","date_gmt":"2020-07-13T15:53:57","guid":{"rendered":"http:\/\/54.87.247.144\/?page_id=186"},"modified":"2026-05-05T08:46:54","modified_gmt":"2026-05-05T12:46:54","slug":"inicio","status":"publish","type":"page","link":"https:\/\/ducasseindustrial.com\/ar\/","title":{"rendered":"Inicio"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"186\" class=\"elementor elementor-186\" data-elementor-post-type=\"page\">\n\t\t\t\t\t\t<section data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-section elementor-top-section elementor-element elementor-element-2b23f01 elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"2b23f01\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-f2133e8\" data-id=\"f2133e8\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-5be2c0a elementor-widget elementor-widget-bdt-slideshow\" data-id=\"5be2c0a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"bdt-slideshow.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div data-bdt-slideshow=\"{&quot;animation&quot;:&quot;slide&quot;,&quot;ratio&quot;:&quot;16:9&quot;,&quot;min-height&quot;:&quot;500&quot;,&quot;autoplay&quot;:true,&quot;autoplay-interval&quot;:&quot;5000&quot;,&quot;pause-on-hover&quot;:false,&quot;velocity&quot;:1}\" class=\"bdt-dots-align-bottom-center\">\n\t\t\t<div class=\"bdt-position-relative bdt-visible-toggle\">\n\n\t\t\t\t\n\t\t\t\t<ul class=\"bdt-slideshow-items\">\n\t\t\t\t\t\t    \n\t        <li class=\"bdt-slideshow-item elementor-repeater-item-5cefe38\">\n\t\t        \n\t\t            \t\t\t            <img decoding=\"async\" src=\"https:\/\/ducasseindustrial.com\/ar\/wp-content\/uploads\/sites\/17\/2026\/05\/ducasse_tecnologia.jpg\" alt=\"Inicio\" bdt-cover=\"\">\t\t\t        \n\t\t        \n\t\t        \n\t                    <div class=\"bdt-slideshow-content-wrapper bdt-position-z-index bdt-position-center bdt-position-large bdt-text-center\">\n        \t\n\t\t\t\n\t\t\t\n\t\t\t\n\t\t\t\t\t<\/div>\n\n\t\t\t        <\/li>\n\n\t\t\t\t\t\t    \n\t        <li class=\"bdt-slideshow-item elementor-repeater-item-ddf7f60\">\n\t\t        \n\t\t            \t\t\t            <img decoding=\"async\" src=\"https:\/\/ducasseindustrial.com\/ar\/wp-content\/uploads\/sites\/17\/2026\/05\/banner_HD-scaled-1.jpg\" alt=\"Inicio\" bdt-cover=\"\">\t\t\t        \n\t\t        \n\t\t        \n\t                    <div class=\"bdt-slideshow-content-wrapper bdt-position-z-index bdt-position-center bdt-position-large bdt-text-center\">\n        \t\t\t\t\t<div><h4 class=\"bdt-slideshow-pre-title bdt-display-inline-block\" >L\u00ednea Heavy Duty<\/h4><\/div>\n\t\t\t\n\t\t\t\t\t\t\t<div><h2 class=\"bdt-slideshow-title bdt-display-inline-block\" >Seguridad y eficiencia Sistemas para portones de alto peso.<\/h2><\/div>\n\t\t\t\n\t\t\t\n\t\t\t\n\t\t\t\t\t<\/div>\n\n\t\t\t        <\/li>\n\n\t\t\t\t\t\t    \n\t        <li class=\"bdt-slideshow-item elementor-repeater-item-6d4c747\">\n\t\t        \n\t\t            \t\t\t            <img decoding=\"async\" src=\"https:\/\/ducasseindustrial.com\/ar\/wp-content\/uploads\/sites\/17\/2026\/05\/03-slider-linea-mobile.jpg\" alt=\"Inicio\" bdt-cover=\"\">\t\t\t        \n\t\t        \n\t\t        \n\t                    <div class=\"bdt-slideshow-content-wrapper bdt-position-z-index bdt-position-center bdt-position-large bdt-text-center\">\n        \t\t\t\t\t<div><h4 class=\"bdt-slideshow-pre-title bdt-display-inline-block\" >L\u00ednea Mobile <\/h4><\/div>\n\t\t\t\n\t\t\t\t\t\t\t<div><h2 class=\"bdt-slideshow-title bdt-display-inline-block\" >Dise\u00f1o y funcionalidad Sistemas corredizos para muebles<\/h2><\/div>\n\t\t\t\n\t\t\t\n\t\t\t\n\t\t\t\t\t<\/div>\n\n\t\t\t        <\/li>\n\n\t\t\t\t\t\t    \n\t        <li class=\"bdt-slideshow-item elementor-repeater-item-7ffb37b\">\n\t\t        \n\t\t            \t\t\t            <img decoding=\"async\" src=\"https:\/\/ducasseindustrial.com\/ar\/wp-content\/uploads\/sites\/17\/2026\/05\/banner_SEGMENTA-scaled-1.jpg\" alt=\"Inicio\" bdt-cover=\"\">\t\t\t        \n\t\t        \n\t\t        \n\t                    <div class=\"bdt-slideshow-content-wrapper bdt-position-z-index bdt-position-center bdt-position-large bdt-text-center\">\n        \t\t\t\t\t<div><h4 class=\"bdt-slideshow-pre-title bdt-display-inline-block\" >L\u00ednea Segmenta<\/h4><\/div>\n\t\t\t\n\t\t\t\t\t\t\t<div><h2 class=\"bdt-slideshow-title bdt-display-inline-block\" >Dise\u00f1o e innovaci\u00f3n para la transformaci\u00f3n de espacios<\/h2><\/div>\n\t\t\t\n\t\t\t\n\t\t\t\n\t\t\t\t\t<\/div>\n\n\t\t\t        <\/li>\n\n\t\t\t\t\t\t    \n\t        <li class=\"bdt-slideshow-item elementor-repeater-item-df5ba8b\">\n\t\t        \n\t\t            \t\t\t            <img decoding=\"async\" src=\"https:\/\/ducasseindustrial.com\/ar\/wp-content\/uploads\/sites\/17\/2026\/05\/banner_organiza-scaled-1.jpg\" alt=\"Inicio\" bdt-cover=\"\">\t\t\t        \n\t\t        \n\t\t        \n\t                    <div class=\"bdt-slideshow-content-wrapper bdt-position-z-index bdt-position-center bdt-position-large bdt-text-center\">\n        \t\t\t\t\t<div><h4 class=\"bdt-slideshow-pre-title bdt-display-inline-block\" >Organiza<\/h4><\/div>\n\t\t\t\n\t\t\t\t\t\t\t<div><h2 class=\"bdt-slideshow-title bdt-display-inline-block\" >Dise\u00f1o e Innovaci\u00f3n Funcional<\/h2><\/div>\n\t\t\t\n\t\t\t\n\t\t\t\n\t\t\t\t\t\t\t<div><a href=\"https:\/\/www.mercadolibre.com.ar\/pagina\/organiza\" target=\"_self\" class=\"bdt-slideshow-button bdt-display-inline-block\" rel=\"noreferrer\" >Visitar\t\t\t\t\t\n\t\t\t\t\t\n\t\t\t\t<\/a><\/div>\n\t\t\t\t\t<\/div>\n\n\t\t\t        <\/li>\n\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t<div class=\"bdt-position-z-index bdt-position-bottom-center\">\n\t\t\t<div class=\"bdt-dotnav-wrapper bdt-dots-container\">\n\t\t\t\t<ul class=\"bdt-dotnav bdt-flex-center\">\n\n\t\t\t\t    <li class=\"bdt-slideshow-dotnav bdt-active\" bdt-slideshow-item=\"0\"><a href=\"#\"><\/a><\/li><li class=\"bdt-slideshow-dotnav bdt-active\" bdt-slideshow-item=\"1\"><a href=\"#\"><\/a><\/li><li class=\"bdt-slideshow-dotnav bdt-active\" bdt-slideshow-item=\"2\"><a href=\"#\"><\/a><\/li><li class=\"bdt-slideshow-dotnav bdt-active\" bdt-slideshow-item=\"3\"><a href=\"#\"><\/a><\/li><li class=\"bdt-slideshow-dotnav bdt-active\" bdt-slideshow-item=\"4\"><a href=\"#\"><\/a><\/li>\n\t\t\t\t<\/ul>\n\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-364e83d elementor-widget elementor-widget-image\" data-id=\"364e83d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/ducasseindustrial.com\/ar\/wp-content\/uploads\/sites\/17\/2026\/05\/logo_ducasse_2025_color_v2.svg\" title=\"logo_ducasse_2025_color_v2.svg\" alt=\"logo_ducasse_2025_color_v2.svg\" loading=\"lazy\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e7cbbdd elementor-widget elementor-widget-heading\" data-id=\"e7cbbdd\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Soluciones confiables que\ntransforman espacios<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-section elementor-top-section elementor-element elementor-element-518da94 elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"518da94\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-07811a7\" data-id=\"07811a7\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-e11173a elementor-widget elementor-widget-image\" data-id=\"e11173a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/ducasseindustrial.com\/ar\/product-category\/productos\/placard\/\">\n\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"1000\" height=\"900\" src=\"https:\/\/ducasseindustrial.com\/ar\/wp-content\/uploads\/sites\/17\/2026\/05\/LINEA-PRODUCTOS_01-1.jpg\" class=\"attachment-full size-full wp-image-28703\" alt=\"\" srcset=\"https:\/\/ducasseindustrial.com\/ar\/wp-content\/uploads\/sites\/17\/2026\/05\/LINEA-PRODUCTOS_01-1.jpg 1000w, https:\/\/ducasseindustrial.com\/ar\/wp-content\/uploads\/sites\/17\/2026\/05\/LINEA-PRODUCTOS_01-1-600x540.jpg 600w, https:\/\/ducasseindustrial.com\/ar\/wp-content\/uploads\/sites\/17\/2026\/05\/LINEA-PRODUCTOS_01-1-768x691.jpg 768w, https:\/\/ducasseindustrial.com\/ar\/wp-content\/uploads\/sites\/17\/2026\/05\/LINEA-PRODUCTOS_01-1-500x450.jpg 500w, https:\/\/ducasseindustrial.com\/ar\/wp-content\/uploads\/sites\/17\/2026\/05\/LINEA-PRODUCTOS_01-1-800x720.jpg 800w\" sizes=\"(max-width: 1000px) 100vw, 1000px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-4062046\" data-id=\"4062046\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3afb3a4 elementor-widget elementor-widget-image\" data-id=\"3afb3a4\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t<figure class=\"wp-caption\">\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/ducasseindustrial.com\/product-category\/productos\/portones\">\n\t\t\t\t\t\t\t<img decoding=\"async\" width=\"1000\" height=\"900\" src=\"https:\/\/ducasseindustrial.com\/ar\/wp-content\/uploads\/sites\/17\/2026\/05\/LINEA-PRODUCTOS_03.jpg\" class=\"attachment-full size-full wp-image-28704\" alt=\"\" srcset=\"https:\/\/ducasseindustrial.com\/ar\/wp-content\/uploads\/sites\/17\/2026\/05\/LINEA-PRODUCTOS_03.jpg 1000w, https:\/\/ducasseindustrial.com\/ar\/wp-content\/uploads\/sites\/17\/2026\/05\/LINEA-PRODUCTOS_03-600x540.jpg 600w, https:\/\/ducasseindustrial.com\/ar\/wp-content\/uploads\/sites\/17\/2026\/05\/LINEA-PRODUCTOS_03-768x691.jpg 768w, https:\/\/ducasseindustrial.com\/ar\/wp-content\/uploads\/sites\/17\/2026\/05\/LINEA-PRODUCTOS_03-500x450.jpg 500w, https:\/\/ducasseindustrial.com\/ar\/wp-content\/uploads\/sites\/17\/2026\/05\/LINEA-PRODUCTOS_03-800x720.jpg 800w\" sizes=\"(max-width: 1000px) 100vw, 1000px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t<figcaption class=\"widget-image-caption wp-caption-text\"><\/figcaption>\n\t\t\t\t\t\t\t\t\t\t<\/figure>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-6b7a352\" data-id=\"6b7a352\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-8b800fb elementor-widget elementor-widget-image\" data-id=\"8b800fb\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t<figure class=\"wp-caption\">\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/ducasseindustrial.com\/ar\/product-category\/productos\/puertas-de-paso\/\">\n\t\t\t\t\t\t\t<img decoding=\"async\" width=\"1000\" height=\"900\" src=\"https:\/\/ducasseindustrial.com\/ar\/wp-content\/uploads\/sites\/17\/2026\/05\/LINEA-PRODUCTOS_02.jpg\" class=\"attachment-full size-full wp-image-28705\" alt=\"\" srcset=\"https:\/\/ducasseindustrial.com\/ar\/wp-content\/uploads\/sites\/17\/2026\/05\/LINEA-PRODUCTOS_02.jpg 1000w, https:\/\/ducasseindustrial.com\/ar\/wp-content\/uploads\/sites\/17\/2026\/05\/LINEA-PRODUCTOS_02-600x540.jpg 600w, https:\/\/ducasseindustrial.com\/ar\/wp-content\/uploads\/sites\/17\/2026\/05\/LINEA-PRODUCTOS_02-768x691.jpg 768w, https:\/\/ducasseindustrial.com\/ar\/wp-content\/uploads\/sites\/17\/2026\/05\/LINEA-PRODUCTOS_02-500x450.jpg 500w, https:\/\/ducasseindustrial.com\/ar\/wp-content\/uploads\/sites\/17\/2026\/05\/LINEA-PRODUCTOS_02-800x720.jpg 800w\" sizes=\"(max-width: 1000px) 100vw, 1000px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t<figcaption class=\"widget-image-caption wp-caption-text\"><\/figcaption>\n\t\t\t\t\t\t\t\t\t\t<\/figure>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-section elementor-top-section elementor-element elementor-element-5daead2 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"5daead2\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-section elementor-top-section elementor-element elementor-element-4ceb816 elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"4ceb816\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-bb1ec63\" data-id=\"bb1ec63\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-f63e2a2 elementor-widget elementor-widget-image\" data-id=\"f63e2a2\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/ducasseindustrial.com\/ar\/wp-content\/uploads\/sites\/17\/2026\/05\/LOGO_HEAVY_DUTY.svg\" title=\"LOGO_HEAVY_DUTY.svg\" alt=\"LOGO_HEAVY_DUTY.svg\" loading=\"lazy\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-fb49467 elementor-widget elementor-widget-text-editor\" data-id=\"fb49467\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<span style=\"color: #ffffff\">APLICACI\u00d3N DE DIMENSIONAMIENTO<\/span>\n<h1 style=\"font-size: 70px\"><b><span style=\"color: #ffffff\">PORT\u00d3N<\/span> CURVO<\/b><\/h1>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-85c1eea\" data-id=\"85c1eea\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-a82b991 elementor-widget elementor-widget-text-editor\" data-id=\"a82b991\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><strong>CONOCE<\/strong> nuestra <strong>APP<\/strong><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-950aff3 elementor-widget elementor-widget-eael-creative-button\" data-id=\"950aff3\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"eael-creative-button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t        <div class=\"eael-creative-button-wrapper\">\n\n            <a class=\"eael-creative-button eael-creative-button--default eael-cb-icon-position-left\" href=\"https:\/\/dimensionado.ducasseindustrial.com\/\" data-text=\"Go!\">\n            \t    \n                <div class=\"creative-button-inner\">\n\n                                            <span class=\"eael-creative-button-icon-left\"><i aria-hidden=\"true\" class=\"fas fa-external-link-alt\"><\/i><\/span>                    \n                    <span class=\"cretive-button-text\">IR A LA APP<\/span>\n\n                                    <\/div>\n\t                        <\/a>\n        <\/div>\n        \t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-621deaf elementor-widget elementor-widget-eael-creative-button\" data-id=\"621deaf\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"eael-creative-button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t        <div class=\"eael-creative-button-wrapper\">\n\n            <a class=\"eael-creative-button eael-creative-button--default eael-cb-icon-position-left\" href=\"http:\/\/34.198.76.237:8334\/s\/IIqZvUm\" data-text=\"Go!\">\n            \t    \n                <div class=\"creative-button-inner\">\n\n                                            <span class=\"eael-creative-button-icon-left\"><i aria-hidden=\"true\" class=\"fas fa-download\"><\/i><\/span>                    \n                    <span class=\"cretive-button-text\">DESCARGAR CAT\u00c1LOGO<\/span>\n\n                                    <\/div>\n\t                        <\/a>\n        <\/div>\n        \t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-section elementor-top-section elementor-element elementor-element-9c650dd elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"9c650dd\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-41ad141\" data-id=\"41ad141\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-d6f0299 elementor-widget elementor-widget-image\" data-id=\"d6f0299\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t<figure class=\"wp-caption\">\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/organizastore.cl\/products\/proyecto-cocina\">\n\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"2000\" height=\"901\" src=\"https:\/\/ducasseindustrial.com\/ar\/wp-content\/uploads\/sites\/17\/2026\/05\/banner_cocina_organiza.jpg\" class=\"attachment-full size-full wp-image-28707\" alt=\"\" srcset=\"https:\/\/ducasseindustrial.com\/ar\/wp-content\/uploads\/sites\/17\/2026\/05\/banner_cocina_organiza.jpg 2000w, https:\/\/ducasseindustrial.com\/ar\/wp-content\/uploads\/sites\/17\/2026\/05\/banner_cocina_organiza-600x270.jpg 600w, https:\/\/ducasseindustrial.com\/ar\/wp-content\/uploads\/sites\/17\/2026\/05\/banner_cocina_organiza-1024x461.jpg 1024w, https:\/\/ducasseindustrial.com\/ar\/wp-content\/uploads\/sites\/17\/2026\/05\/banner_cocina_organiza-768x346.jpg 768w, https:\/\/ducasseindustrial.com\/ar\/wp-content\/uploads\/sites\/17\/2026\/05\/banner_cocina_organiza-1536x692.jpg 1536w, https:\/\/ducasseindustrial.com\/ar\/wp-content\/uploads\/sites\/17\/2026\/05\/banner_cocina_organiza-500x225.jpg 500w, https:\/\/ducasseindustrial.com\/ar\/wp-content\/uploads\/sites\/17\/2026\/05\/banner_cocina_organiza-800x360.jpg 800w, https:\/\/ducasseindustrial.com\/ar\/wp-content\/uploads\/sites\/17\/2026\/05\/banner_cocina_organiza-1280x577.jpg 1280w, https:\/\/ducasseindustrial.com\/ar\/wp-content\/uploads\/sites\/17\/2026\/05\/banner_cocina_organiza-1920x865.jpg 1920w\" sizes=\"(max-width: 2000px) 100vw, 2000px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t<figcaption class=\"widget-image-caption wp-caption-text\"><\/figcaption>\n\t\t\t\t\t\t\t\t\t\t<\/figure>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-6d4c2f6\" data-id=\"6d4c2f6\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-f2b0230 elementor-widget elementor-widget-text-editor\" data-id=\"f2b0230\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h4><strong><span style=\"color: #333300\">SOLUCIONES PARA LA ORGANIZACI\u00d3N DEL HOGAR<\/span><\/strong><\/h4><p>Organiza es una marca de Ducasse Industrial enfocada a la organizaci\u00f3n de espacios.\u00a0<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3c73c8e elementor-align-center elementor-widget elementor-widget-button\" data-id=\"3c73c8e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/www.mercadolibre.com.ar\/pagina\/organiza\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Visitar web<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-section elementor-top-section elementor-element elementor-element-2f9f631 elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"2f9f631\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-d6a0a46\" data-id=\"d6a0a46\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-7f881e7 elementor-widget elementor-widget-video\" data-id=\"7f881e7\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;youtube_url&quot;:&quot;https:\\\/\\\/www.youtube.com\\\/watch?v=YmpfzXF233M&quot;,&quot;start&quot;:&quot;2&quot;,&quot;video_type&quot;:&quot;youtube&quot;}\" data-widget_type=\"video.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-wrapper elementor-open-inline\">\n\t\t\t<div class=\"elementor-video\"><\/div>\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-743ff86\" data-id=\"743ff86\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-47e510c elementor-widget elementor-widget-text-editor\" data-id=\"47e510c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>En Ducasse Industrial desarrollamos soluciones para el movimiento, con herrajes que transforman espacios con funcionalidad y dise\u00f1o. Somos expertos que combinan ingenier\u00eda y un soporte cercano para entregar soluciones innovadoras y accesibles, con calidad de nivel mundial y la cercan\u00eda de un socio local.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-section elementor-top-section elementor-element elementor-element-4d30750 elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"4d30750\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-93ea89b\" data-id=\"93ea89b\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-cecc7d1 elementor-widget elementor-widget-text-editor\" data-id=\"cecc7d1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Cada producto de Segmenta responde a las exigencias de proyectos modernos, donde el aprovechamiento del espacio, la durabilidad y la experiencia de uso son clave.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-e85f7f5\" data-id=\"e85f7f5\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-fee9fe5 elementor-widget elementor-widget-video\" data-id=\"fee9fe5\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;youtube_url&quot;:&quot;https:\\\/\\\/www.youtube.com\\\/watch?v=OtQjwzFZUBQ&quot;,&quot;start&quot;:&quot;2&quot;,&quot;show_image_overlay&quot;:&quot;yes&quot;,&quot;image_overlay&quot;:{&quot;url&quot;:&quot;https:\\\/\\\/ducasseindustrial.com\\\/ar\\\/wp-content\\\/uploads\\\/sites\\\/17\\\/2026\\\/05\\\/portada_video.jpg&quot;,&quot;id&quot;:&quot;28709&quot;,&quot;size&quot;:&quot;&quot;},&quot;video_type&quot;:&quot;youtube&quot;}\" data-widget_type=\"video.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-wrapper elementor-open-inline\">\n\t\t\t<div class=\"elementor-video\"><\/div>\t\t\t\t<div class=\"elementor-custom-embed-image-overlay\" style=\"background-image: url(https:\/\/ducasseindustrial.com\/ar\/wp-content\/uploads\/sites\/17\/2026\/05\/portada_video.jpg);\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-custom-embed-play\" role=\"button\" aria-label=\"Reproducir v\u00eddeo\" tabindex=\"0\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"eicon-play\"><\/i>\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-section elementor-top-section elementor-element elementor-element-eedbe83 elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"eedbe83\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-c28d237\" data-id=\"c28d237\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-680bdb2 elementor-widget elementor-widget-image\" data-id=\"680bdb2\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"2000\" height=\"901\" src=\"https:\/\/ducasseindustrial.com\/ar\/wp-content\/uploads\/sites\/17\/2026\/05\/BANNER_EXTRAIBLES_2-1.jpg\" class=\"attachment-full size-full wp-image-28711\" alt=\"\" srcset=\"https:\/\/ducasseindustrial.com\/ar\/wp-content\/uploads\/sites\/17\/2026\/05\/BANNER_EXTRAIBLES_2-1.jpg 2000w, https:\/\/ducasseindustrial.com\/ar\/wp-content\/uploads\/sites\/17\/2026\/05\/BANNER_EXTRAIBLES_2-1-600x270.jpg 600w, https:\/\/ducasseindustrial.com\/ar\/wp-content\/uploads\/sites\/17\/2026\/05\/BANNER_EXTRAIBLES_2-1-1024x461.jpg 1024w, https:\/\/ducasseindustrial.com\/ar\/wp-content\/uploads\/sites\/17\/2026\/05\/BANNER_EXTRAIBLES_2-1-768x346.jpg 768w, https:\/\/ducasseindustrial.com\/ar\/wp-content\/uploads\/sites\/17\/2026\/05\/BANNER_EXTRAIBLES_2-1-1536x692.jpg 1536w, https:\/\/ducasseindustrial.com\/ar\/wp-content\/uploads\/sites\/17\/2026\/05\/BANNER_EXTRAIBLES_2-1-500x225.jpg 500w, https:\/\/ducasseindustrial.com\/ar\/wp-content\/uploads\/sites\/17\/2026\/05\/BANNER_EXTRAIBLES_2-1-800x360.jpg 800w, https:\/\/ducasseindustrial.com\/ar\/wp-content\/uploads\/sites\/17\/2026\/05\/BANNER_EXTRAIBLES_2-1-1280x577.jpg 1280w, https:\/\/ducasseindustrial.com\/ar\/wp-content\/uploads\/sites\/17\/2026\/05\/BANNER_EXTRAIBLES_2-1-1920x865.jpg 1920w\" sizes=\"(max-width: 2000px) 100vw, 2000px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-ff499d4\" data-id=\"ff499d4\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-71e1124 elementor-widget elementor-widget-text-editor\" data-id=\"71e1124\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><strong>EXTRA\u00cdBLES DE COCINA<\/strong><br \/>Convierte cada mueble en un espacio funcional con nuestros sistemas extra\u00edbles. Dise\u00f1ados para optimizar el interior de tus muebles, permiten acceder f\u00e1cilmente a utensilios, alimentos y accesorios sin esfuerzo.\u00a0<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-58d353c elementor-align-center elementor-widget elementor-widget-button\" data-id=\"58d353c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/ducasseindustrial.com\/ar\/product-category\/productos\/muebles-y-cajones\/extraibles-de-cocina\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Visitar<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-section elementor-top-section elementor-element elementor-element-5123470 elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"5123470\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-6de4416\" data-id=\"6de4416\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-a996e29 elementor-widget elementor-widget-text-editor\" data-id=\"a996e29\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Nuestros productos est\u00e1n dise\u00f1ados con alta tecnolog\u00eda para superar tus expectativas y brindarte resultados excepcionales en t\u00e9rminos de calidad, rendimiento y eficiencia.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-34ce6ff\" data-id=\"34ce6ff\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-042bd8f elementor-widget elementor-widget-video\" data-id=\"042bd8f\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;youtube_url&quot;:&quot;https:\\\/\\\/www.youtube.com\\\/watch?v=1rLlg9dd224&quot;,&quot;show_image_overlay&quot;:&quot;yes&quot;,&quot;image_overlay&quot;:{&quot;url&quot;:&quot;https:\\\/\\\/ducasseindustrial.com\\\/ar\\\/wp-content\\\/uploads\\\/sites\\\/17\\\/2026\\\/05\\\/caratula_carrosigma.jpg&quot;,&quot;id&quot;:&quot;28712&quot;,&quot;size&quot;:&quot;&quot;},&quot;video_type&quot;:&quot;youtube&quot;,&quot;controls&quot;:&quot;yes&quot;}\" data-widget_type=\"video.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-wrapper elementor-open-inline\">\n\t\t\t<div class=\"elementor-video\"><\/div>\t\t\t\t<div class=\"elementor-custom-embed-image-overlay\" style=\"background-image: url(https:\/\/ducasseindustrial.com\/ar\/wp-content\/uploads\/sites\/17\/2026\/05\/caratula_carrosigma.jpg);\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-custom-embed-play\" role=\"button\" aria-label=\"Reproducir v\u00eddeo\" tabindex=\"0\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"eicon-play\"><\/i>\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-section elementor-top-section elementor-element elementor-element-3ed0be8 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"3ed0be8\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-wider\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-top-column elementor-element elementor-element-63e4bee\" data-id=\"63e4bee\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-section elementor-inner-section elementor-element elementor-element-c7a6bc2 elementor-section-content-middle elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"c7a6bc2\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-622f0e7\" data-id=\"622f0e7\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-710b66f elementor-widget elementor-widget-image\" data-id=\"710b66f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/ducasseindustrial.com\/ar\/wp-content\/uploads\/sites\/17\/elementor\/thumbs\/13962-04-owmnyrf8pl2kdoekuk9yl0e6vj9qwhpxf79fy2c8z8.png\" title=\"13962-04\" alt=\"13962-04\" loading=\"lazy\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-8f78da3\" data-id=\"8f78da3\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-ddbc77e elementor-widget elementor-widget-text-editor\" data-id=\"ddbc77e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<a><u>@ducasseindustrial_herreros.ar<\/u><\/a>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-section elementor-inner-section elementor-element elementor-element-c8fe241 elementor-section-content-middle elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"c8fe241\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-5e72759\" data-id=\"5e72759\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-d20b147 elementor-widget elementor-widget-image\" data-id=\"d20b147\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/ducasseindustrial.com\/ar\/wp-content\/uploads\/sites\/17\/2022\/04\/Manual10-04-heavyduty.pdf\" target=\"_blank\">\n\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/ducasseindustrial.com\/ar\/wp-content\/uploads\/sites\/17\/elementor\/thumbs\/01-hd-01-01-owuzoztw72v0jht1jjf953sv1xcfadfpk7gf0ji7ks.jpg\" title=\"01-hd-01-01\" alt=\"01-hd-01-01\" loading=\"lazy\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1b887db elementor-view-framed elementor-shape-circle elementor-widget elementor-widget-icon\" data-id=\"1b887db\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-wrapper\">\n\t\t\t<a class=\"elementor-icon\" href=\"https:\/\/ducasseindustrial.com\/ar\/wp-content\/uploads\/sites\/17\/2022\/04\/Manual10-04-heavyduty.pdf\" target=\"_blank\">\n\t\t\t<i aria-hidden=\"true\" class=\"fas fa-download\"><\/i>\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2c86ada elementor-widget elementor-widget-text-editor\" data-id=\"2c86ada\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Descargar Cat\u00e1logo<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<div class=\"elementor-element elementor-element-1979abc btn-catalogos elementor-widget elementor-widget-image\" data-id=\"1979abc\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"226\" height=\"150\" src=\"https:\/\/ducasseindustrial.com\/ar\/wp-content\/uploads\/sites\/17\/2020\/08\/dwl-hd-01.png\" class=\"attachment-large size-large wp-image-1276\" alt=\"\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-top-column elementor-element elementor-element-ef4e553\" data-id=\"ef4e553\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-f9b5409 btn-catalogos elementor-widget elementor-widget-image\" data-id=\"f9b5409\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"226\" height=\"150\" src=\"https:\/\/ducasseindustrial.com\/ar\/wp-content\/uploads\/sites\/17\/2020\/08\/dwl-mobiie-01.png\" class=\"attachment-large size-large wp-image-1277\" alt=\"\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-section elementor-inner-section elementor-element elementor-element-18b141f elementor-section-content-middle elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"18b141f\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-09ede29\" data-id=\"09ede29\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-f093f41 elementor-widget elementor-widget-image\" data-id=\"f093f41\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/ducasseindustrial.com\/ar\/wp-content\/uploads\/sites\/17\/elementor\/thumbs\/13962-04-owmnyrf8pl2kdoekuk9yl0e6vj9qwhpxf79fy2c8z8.png\" title=\"13962-04\" alt=\"13962-04\" loading=\"lazy\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-79e268a\" data-id=\"79e268a\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-597d3f1 elementor-widget elementor-widget-text-editor\" data-id=\"597d3f1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><a href=\"https:\/\/www.instagram.com\/ducasseindustrial_carpinteros\">@ducasseindustrial_carpinteros<\/a><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-section elementor-inner-section elementor-element elementor-element-6361b7a elementor-section-content-middle elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"6361b7a\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-1f26097\" data-id=\"1f26097\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-e46f9d2 elementor-widget elementor-widget-image\" data-id=\"e46f9d2\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/ducasseindustrial.com\/ar\/wp-content\/uploads\/sites\/17\/2020\/10\/01-catalogo-mobile.pdf\" target=\"_blank\">\n\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/ducasseindustrial.com\/ar\/wp-content\/uploads\/sites\/17\/elementor\/thumbs\/02-mobile-01-owuybcypb0wxgrwkdl1gz4plsfzntrdz2jadpj3m58.jpg\" title=\"02-mobile-01\" alt=\"02-mobile-01\" loading=\"lazy\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-47be5ad elementor-view-framed elementor-shape-circle elementor-widget elementor-widget-icon\" data-id=\"47be5ad\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-wrapper\">\n\t\t\t<a class=\"elementor-icon\" href=\"https:\/\/ducasseindustrial.com\/ar\/wp-content\/uploads\/sites\/17\/2020\/10\/01-catalogo-mobile.pdf\" target=\"_blank\">\n\t\t\t<i aria-hidden=\"true\" class=\"fas fa-download\"><\/i>\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c249990 elementor-widget elementor-widget-text-editor\" data-id=\"c249990\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Descargar Cat\u00e1logo<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-top-column elementor-element elementor-element-34852d0\" data-id=\"34852d0\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-6b77f48 btn-catalogos elementor-widget elementor-widget-image\" data-id=\"6b77f48\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"226\" height=\"150\" src=\"https:\/\/ducasseindustrial.com\/ar\/wp-content\/uploads\/sites\/17\/2020\/08\/dwl-segmenta-01.png\" class=\"attachment-large size-large wp-image-1278\" alt=\"\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-section elementor-inner-section elementor-element elementor-element-8864562 elementor-section-content-middle elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"8864562\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-46d5c25\" data-id=\"46d5c25\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-a0e5394 elementor-widget elementor-widget-image\" data-id=\"a0e5394\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/ducasseindustrial.com\/ar\/wp-content\/uploads\/sites\/17\/elementor\/thumbs\/13962-04-owmnyrf8pl2kdoekuk9yl0e6vj9qwhpxf79fy2c8z8.png\" title=\"13962-04\" alt=\"13962-04\" loading=\"lazy\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-ecf941e\" data-id=\"ecf941e\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-b355377 elementor-widget elementor-widget-text-editor\" data-id=\"b355377\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<a style=\"color:#5b6770\" href=\"https:\/\/www.instagram.com\/ducasse.arq\/\"><u>@ducasseindustrial_arq.ar<\/u><\/a>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-section elementor-inner-section elementor-element elementor-element-700bdd4 elementor-section-content-middle elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"700bdd4\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-c0db3c3\" data-id=\"c0db3c3\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-2ae9504 elementor-widget elementor-widget-image\" data-id=\"2ae9504\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/ducasseindustrial.com\/ar\/wp-content\/uploads\/sites\/17\/2021\/01\/02-catalogo-segmenta2.pdf\" target=\"_blank\">\n\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/ducasseindustrial.com\/ar\/wp-content\/uploads\/sites\/17\/elementor\/thumbs\/03-segmenta-01b-01-owuyb97cjors6c20zjeyp5nrewi6yyz1q0ofsf96u4.jpg\" title=\"03-segmenta-01b-01\" alt=\"03-segmenta-01b-01\" loading=\"lazy\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f9c0c8a elementor-view-framed elementor-shape-circle elementor-widget elementor-widget-icon\" data-id=\"f9c0c8a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-wrapper\">\n\t\t\t<a class=\"elementor-icon\" href=\"https:\/\/ducasseindustrial.com\/ar\/wp-content\/uploads\/sites\/17\/2021\/01\/02-catalogo-segmenta2.pdf\" target=\"_blank\">\n\t\t\t<i aria-hidden=\"true\" class=\"fas fa-download\"><\/i>\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c76c46c elementor-widget elementor-widget-text-editor\" data-id=\"c76c46c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Descargar Cat\u00e1logo<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-top-column elementor-element elementor-element-f9a79e7\" data-id=\"f9a79e7\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-f51a8a3 elementor-widget elementor-widget-image\" data-id=\"f51a8a3\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/ducasseindustrial.com\/ar\/product-category\/productos\/organizacion\/\">\n\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"226\" src=\"https:\/\/ducasseindustrial.com\/ar\/wp-content\/uploads\/sites\/17\/2020\/09\/descubre-organiza-copia.png\" class=\"attachment-large size-large wp-image-7939\" alt=\"\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-25812d0 elementor-widget elementor-widget-text-editor\" data-id=\"25812d0\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><span style=\"text-align: center\">Productos para la organizaci\u00f3n<\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e582b76 elementor-widget elementor-widget-text-editor\" data-id=\"e582b76\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><a style=\"color: #ffffff\" href=\"https:\/\/ducasseindustrial.com\/ar\/product-category\/productos\/organizacion\/\">DE ESPACIOS<\/a><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-section elementor-inner-section elementor-element elementor-element-a523fa5 elementor-section-content-middle elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"a523fa5\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-784b556\" data-id=\"784b556\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-7cda2a8 elementor-widget elementor-widget-image\" data-id=\"7cda2a8\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/ducasseindustrial.com\/ar\/wp-content\/uploads\/sites\/17\/elementor\/thumbs\/13962-04-owmnyrf8pl2kdoekuk9yl0e6vj9qwhpxf79fy2c8z8.png\" title=\"13962-04\" alt=\"13962-04\" loading=\"lazy\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-36fe528\" data-id=\"36fe528\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-fd65bd1 elementor-widget elementor-widget-text-editor\" data-id=\"fd65bd1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>@organiza_arg<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<div class=\"elementor-element elementor-element-31c83fb btn-catalogos elementor-widget elementor-widget-image\" data-id=\"31c83fb\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"226\" height=\"150\" src=\"https:\/\/ducasseindustrial.com\/ar\/wp-content\/uploads\/sites\/17\/2020\/08\/dwl-vento-organiza-01.png\" class=\"attachment-full size-full wp-image-1275\" alt=\"\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-section elementor-top-section elementor-element elementor-element-618fffe ig-lineas elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"618fffe\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-wider\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-20 elementor-top-column elementor-element elementor-element-77d3155\" data-id=\"77d3155\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-94e2809 elementor-widget__width-initial elementor-widget elementor-widget-image\" data-id=\"94e2809\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.instagram.com\/organiza_oficial\/\" target=\"_blank\">\n\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/ducasseindustrial.com\/ar\/wp-content\/uploads\/sites\/17\/elementor\/thumbs\/ioc-ig-1-owmnmq3n6yldpfw04uyy5jqp0wljc0xo3milpi6qo8.png\" title=\"ioc-ig\" alt=\"ioc-ig\" loading=\"lazy\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-bd360c3 elementor-widget__width-initial elementor-widget elementor-widget-text-editor\" data-id=\"bd360c3\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><a style=\"color: #5b6770\" href=\"https:\/\/www.instagram.com\/ducasseindustrial_herreros.ar\/\/\" target=\"_blank\" rel=\"noopener\">ducasseindustrial_herreros.ar\/<\/a><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-20 elementor-top-column elementor-element elementor-element-2050bc3\" data-id=\"2050bc3\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-d983c5b elementor-widget__width-initial elementor-widget elementor-widget-image\" data-id=\"d983c5b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.instagram.com\/organiza_oficial\/\" target=\"_blank\">\n\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/ducasseindustrial.com\/ar\/wp-content\/uploads\/sites\/17\/elementor\/thumbs\/ioc-ig-1-owmnmq3n6yldpfw04uyy5jqp0wljc0xo3milpi6qo8.png\" title=\"ioc-ig\" alt=\"ioc-ig\" loading=\"lazy\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b109622 elementor-widget__width-initial elementor-widget elementor-widget-text-editor\" data-id=\"b109622\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><a style=\"color: #5b6770\" href=\"https:\/\/www.instagram.com\/ducasseindustrial_herreros.ar\/\/\" target=\"_blank\" rel=\"noopener\">ducasseindustrial_herreros.ar\/<\/a><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-20 elementor-top-column elementor-element elementor-element-deb033e\" data-id=\"deb033e\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-8eabe85 elementor-widget__width-initial elementor-widget elementor-widget-image\" data-id=\"8eabe85\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.instagram.com\/organiza_oficial\/\" target=\"_blank\">\n\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/ducasseindustrial.com\/ar\/wp-content\/uploads\/sites\/17\/elementor\/thumbs\/ioc-ig-1-owmnmq3n6yldpfw04uyy5jqp0wljc0xo3milpi6qo8.png\" title=\"ioc-ig\" alt=\"ioc-ig\" loading=\"lazy\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-196db3c elementor-widget__width-initial elementor-widget elementor-widget-text-editor\" data-id=\"196db3c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><a style=\"color: #5b6770\" href=\"https:\/\/www.instagram.com\/ducasseindustrial_herreros.ar\/\/\" target=\"_blank\" rel=\"noopener\">ducasseindustrial_herreros.ar\/<\/a><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-20 elementor-top-column elementor-element elementor-element-df65db1\" data-id=\"df65db1\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-345f247 elementor-widget__width-initial elementor-widget elementor-widget-image\" data-id=\"345f247\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.instagram.com\/organiza_oficial\/\" target=\"_blank\">\n\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/ducasseindustrial.com\/ar\/wp-content\/uploads\/sites\/17\/elementor\/thumbs\/ioc-ig-1-owmnmq3n6yldpfw04uyy5jqp0wljc0xo3milpi6qo8.png\" title=\"ioc-ig\" alt=\"ioc-ig\" loading=\"lazy\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-dd13eba elementor-widget__width-initial elementor-widget elementor-widget-text-editor\" data-id=\"dd13eba\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><a style=\"color: #5b6770\" href=\"https:\/\/www.instagram.com\/ducasseindustrial_herreros.ar\/\/\" target=\"_blank\" rel=\"noopener\">ducasseindustrial_herreros.ar\/<\/a><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-20 elementor-top-column elementor-element elementor-element-5d805bd\" data-id=\"5d805bd\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-0f8833b elementor-widget__width-initial elementor-widget elementor-widget-image\" data-id=\"0f8833b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.instagram.com\/organiza_oficial\/\" target=\"_blank\">\n\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/ducasseindustrial.com\/ar\/wp-content\/uploads\/sites\/17\/elementor\/thumbs\/ioc-ig-1-owmnmq3n6yldpfw04uyy5jqp0wljc0xo3milpi6qo8.png\" title=\"ioc-ig\" alt=\"ioc-ig\" loading=\"lazy\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a4cb441 elementor-widget__width-initial elementor-widget elementor-widget-text-editor\" data-id=\"a4cb441\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><a style=\"color: #5b6770\" href=\"https:\/\/www.instagram.com\/ducasseindustrial_herreros.ar\/\/\" target=\"_blank\" rel=\"noopener\">ducasseindustrial_herreros.ar\/<\/a><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-section elementor-top-section elementor-element elementor-element-2279916 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"2279916\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-b475598\" data-id=\"b475598\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-section elementor-inner-section elementor-element elementor-element-eb0370e elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"eb0370e\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-fcf0602\" data-id=\"fcf0602\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-dc9caf0 elementor-widget elementor-widget-image\" data-id=\"dc9caf0\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.instagram.com\/ducasseindustrial\/\" target=\"_blank\">\n\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/ducasseindustrial.com\/ar\/wp-content\/uploads\/sites\/17\/elementor\/thumbs\/banner-ig-img01-owmnjbwoy7hu2yge42ivbclh3suob3xmvfw5kf4gns.jpg\" title=\"Web\" alt=\"Web\" loading=\"lazy\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-536188d\" data-id=\"536188d\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-476568f elementor-widget elementor-widget-text-editor\" data-id=\"476568f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>S\u00edguenos en nuestro<br \/>Instagram Oficial<\/p><p><a href=\"https:\/\/www.instagram.com\/ducasse.arq.ar\/\">@ducasse.arq.ar<\/a><\/p><p>\u00a0<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-0f699a4\" data-id=\"0f699a4\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-section elementor-inner-section elementor-element elementor-element-bcd271f elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"bcd271f\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-8dae2a8\" data-id=\"8dae2a8\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-d892eaf elementor-widget elementor-widget-image\" data-id=\"d892eaf\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.youtube.com\/channel\/UCnH67z1v3HLUgejr87aDODA\" target=\"_blank\">\n\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/ducasseindustrial.com\/ar\/wp-content\/uploads\/sites\/17\/elementor\/thumbs\/banner-youtube-img-owmnjp2flvzulhx9z87na99xf71tavdvl90yaaky7a.jpg\" title=\"Seguinos en Youtube\" alt=\"Seguinos en Youtube\" loading=\"lazy\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-936ddb5\" data-id=\"936ddb5\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-44ac313 elementor-widget elementor-widget-text-editor\" data-id=\"44ac313\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>\u00a0<\/p><p>Para saber m\u00e1s sobre nuestros productos s\u00edguenos en nuestro canal de videos<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-142bc8e elementor-widget elementor-widget-image\" data-id=\"142bc8e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.youtube.com\/channel\/UCnH67z1v3HLUgejr87aDODA\" target=\"_blank\">\n\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"100\" height=\"31\" src=\"https:\/\/ducasseindustrial.com\/ar\/wp-content\/uploads\/sites\/17\/2020\/08\/logo-youtube-01.jpg\" class=\"attachment-large size-large wp-image-1295\" alt=\"\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-section elementor-top-section elementor-element elementor-element-036f302 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"036f302\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-section elementor-top-section elementor-element elementor-element-aa45ba4 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"aa45ba4\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-e0bf91c\" data-id=\"e0bf91c\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-c256d65 elementor-hidden-phone elementor-view-default elementor-widget elementor-widget-icon\" data-id=\"c256d65\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-wrapper\">\n\t\t\t<div class=\"elementor-icon\">\n\t\t\t<i aria-hidden=\"true\" class=\"far fa-paper-plane\"><\/i>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-1952b00\" data-id=\"1952b00\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-0e98e29 elementor-widget elementor-widget-text-editor\" data-id=\"0e98e29\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<span style=\"color: #ff6a14\">NEWSLETTER &#8211; <\/span>Dejanos aqu\u00ed tu mail para recibir novedades\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-b417599\" data-id=\"b417599\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-5f619b4 elementor-widget elementor-widget-shortcode\" data-id=\"5f619b4\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"shortcode.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-shortcode\">\n<div class=\"wpcf7 no-js\" id=\"wpcf7-f1365-o1\" lang=\"es-CL\" dir=\"ltr\" data-wpcf7-id=\"1365\">\n<div class=\"screen-reader-response\"><p role=\"status\" aria-live=\"polite\" aria-atomic=\"true\"><\/p> <ul><\/ul><\/div>\n<form action=\"\/ar\/wp-json\/wp\/v2\/pages\/186#wpcf7-f1365-o1\" method=\"post\" class=\"wpcf7-form init\" aria-label=\"Formulario de contacto\" novalidate=\"novalidate\" data-status=\"init\">\n<fieldset class=\"hidden-fields-container\"><input type=\"hidden\" name=\"_wpcf7\" value=\"1365\" \/><input type=\"hidden\" name=\"_wpcf7_version\" value=\"6.1.7\" \/><input type=\"hidden\" name=\"_wpcf7_locale\" value=\"es_CL\" \/><input type=\"hidden\" name=\"_wpcf7_unit_tag\" value=\"wpcf7-f1365-o1\" \/><input type=\"hidden\" name=\"_wpcf7_container_post\" value=\"0\" \/><input type=\"hidden\" name=\"_wpcf7_posted_data_hash\" value=\"\" \/><input type=\"hidden\" name=\"_wpcf7cf_hidden_group_fields\" value=\"[]\" \/><input type=\"hidden\" name=\"_wpcf7cf_hidden_groups\" value=\"[]\" \/><input type=\"hidden\" name=\"_wpcf7cf_visible_groups\" value=\"[]\" \/><input type=\"hidden\" name=\"_wpcf7cf_repeaters\" value=\"[]\" \/><input type=\"hidden\" name=\"_wpcf7cf_steps\" value=\"{}\" \/><input type=\"hidden\" name=\"_wpcf7cf_options\" value=\"{&quot;form_id&quot;:1365,&quot;conditions&quot;:[],&quot;settings&quot;:{&quot;animation&quot;:&quot;yes&quot;,&quot;animation_intime&quot;:200,&quot;animation_outtime&quot;:200,&quot;conditions_ui&quot;:&quot;normal&quot;,&quot;notice_dismissed&quot;:false,&quot;repeater_remove_button&quot;:&quot;bottom&quot;}}\" \/><input type=\"hidden\" name=\"_wpcf7_recaptcha_response\" value=\"\" \/>\n<\/fieldset>\n<p><label><span class=\"wpcf7-form-control-wrap\" data-name=\"nombre\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text\" aria-invalid=\"false\" placeholder=\"Nombre\" value=\"\" type=\"text\" name=\"nombre\" \/><\/span> <\/label>\n<\/p>\n<p><label><span class=\"wpcf7-form-control-wrap\" data-name=\"your-mail\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-email wpcf7-validates-as-required wpcf7-text wpcf7-validates-as-email\" aria-required=\"true\" aria-invalid=\"false\" placeholder=\"Email\" value=\"\" type=\"email\" name=\"your-mail\" \/><\/span> <\/label>\n<\/p>\n<p><input class=\"wpcf7-form-control wpcf7-submit has-spinner\" type=\"submit\" value=\"Enviar\" \/>\n<\/p><div class=\"wpcf7-response-output\" aria-hidden=\"true\"><\/div>\n<\/form>\n<\/div>\n<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-section elementor-top-section elementor-element elementor-element-d863870 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"d863870\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>L\u00ednea Heavy Duty Seguridad y eficiencia Sistemas para portones de alto peso. L\u00ednea Mobile Dise\u00f1o y funcionalidad Sistemas corredizos para muebles L\u00ednea Segmenta Dise\u00f1o e innovaci\u00f3n para la transformaci\u00f3n de espacios Organiza Dise\u00f1o e Innovaci\u00f3n Funcional Visitar Soluciones confiables que transforman espacios APLICACI\u00d3N DE DIMENSIONAMIENTO PORT\u00d3N CURVO CONOCE nuestra APP IR A LA APP DESCARGAR [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_uag_custom_page_level_css":"","site-sidebar-layout":"no-sidebar","site-content-layout":"page-builder","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"disabled","ast-breadcrumbs-content":"","ast-featured-img":"disabled","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"default","adv-header-id-meta":"","stick-header-meta":"default","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"default","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"_vp_format_video_url":"","_vp_image_focal_point":[],"footnotes":""},"class_list":["post-186","page","type-page","status-publish","hentry"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 5.0.0.1 - aioseo.com -->\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/ducasseindustrial.com\/ar\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 5.0.0.1\" \/>\n\t\t<meta property=\"og:locale\" content=\"es_ES\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Ducasse Industrial S.A. | Somos una empresa Chilena, con m\u00e1s de 50 a\u00f1os de experiencia en la fabricaci\u00f3n de herrajes para la industria del mueble y la construcci\u00f3n, satisfaciendo necesidades tanto en mercados locales como extranjeros.\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Ducasse Industrial S.A.\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/ducasseindustrial.com\/ar\/\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/ducasseindustrial.com\/ar\/wp-content\/uploads\/sites\/17\/2020\/09\/logoDucasse-svg-sin-margen-01.svg\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/ducasseindustrial.com\/ar\/wp-content\/uploads\/sites\/17\/2020\/09\/logoDucasse-svg-sin-margen-01.svg\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2020-07-13T15:53:57+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2026-05-05T12:46:54+00:00\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Ducasse Industrial S.A.\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/ducasseindustrial.com\/ar\/wp-content\/uploads\/sites\/17\/2020\/09\/logoDucasse-svg-sin-margen-01.svg\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/ducasseindustrial.com\\\/ar\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ducasseindustrial.com\\\/ar#listItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\\\/\\\/ducasseindustrial.com\\\/ar\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ducasseindustrial.com\\\/ar\\\/#listItem\",\"name\":\"Inicio\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ducasseindustrial.com\\\/ar\\\/#listItem\",\"position\":2,\"name\":\"Inicio\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ducasseindustrial.com\\\/ar#listItem\",\"name\":\"Inicio\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/ducasseindustrial.com\\\/ar\\\/#organization\",\"name\":\"Ducasse Industrial S.A.\",\"description\":\"Somos una empresa Chilena, con m\\u00e1s de 50 a\\u00f1os de experiencia en la fabricaci\\u00f3n de herrajes para la industria del mueble y la construcci\\u00f3n, satisfaciendo necesidades tanto en mercados locales como extranjeros.\",\"url\":\"https:\\\/\\\/ducasseindustrial.com\\\/ar\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/ducasseindustrial.com\\\/ar\\\/wp-content\\\/uploads\\\/sites\\\/17\\\/2020\\\/09\\\/logoDucasse-svg-sin-margen-01.svg\",\"@id\":\"https:\\\/\\\/ducasseindustrial.com\\\/ar\\\/#organizationLogo\",\"width\":400,\"height\":88},\"image\":{\"@id\":\"https:\\\/\\\/ducasseindustrial.com\\\/ar\\\/#organizationLogo\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/ducasseindustrial.com\\\/ar\\\/#webpage\",\"url\":\"https:\\\/\\\/ducasseindustrial.com\\\/ar\\\/#webpage\",\"name\":\"Ducasse Industrial S.A.\",\"inLanguage\":\"es-CL\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/ducasseindustrial.com\\\/ar\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/ducasseindustrial.com\\\/ar\\\/#webpage\"},\"datePublished\":\"2020-07-13T11:53:57-04:00\",\"dateModified\":\"2026-05-05T08:46:54-04:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/ducasseindustrial.com\\\/ar\\\/#website\",\"url\":\"https:\\\/\\\/ducasseindustrial.com\\\/ar\\\/\",\"name\":\"Ducasse Industrial S.A.\",\"description\":\"Somos una empresa Chilena, con m\\u00e1s de 50 a\\u00f1os de experiencia en la fabricaci\\u00f3n de herrajes para la industria del mueble y la construcci\\u00f3n, satisfaciendo necesidades tanto en mercados locales como extranjeros.\",\"inLanguage\":\"es-CL\",\"publisher\":{\"@id\":\"https:\\\/\\\/ducasseindustrial.com\\\/ar\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"Ducasse Industrial S.A.","description":"","canonical_url":"https:\/\/ducasseindustrial.com\/ar\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BreadcrumbList","@id":"https:\/\/ducasseindustrial.com\/ar\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/ducasseindustrial.com\/ar#listItem","position":1,"name":"Inicio","item":"https:\/\/ducasseindustrial.com\/ar","nextItem":{"@type":"ListItem","@id":"https:\/\/ducasseindustrial.com\/ar\/#listItem","name":"Inicio"}},{"@type":"ListItem","@id":"https:\/\/ducasseindustrial.com\/ar\/#listItem","position":2,"name":"Inicio","previousItem":{"@type":"ListItem","@id":"https:\/\/ducasseindustrial.com\/ar#listItem","name":"Inicio"}}]},{"@type":"Organization","@id":"https:\/\/ducasseindustrial.com\/ar\/#organization","name":"Ducasse Industrial S.A.","description":"Somos una empresa Chilena, con m\u00e1s de 50 a\u00f1os de experiencia en la fabricaci\u00f3n de herrajes para la industria del mueble y la construcci\u00f3n, satisfaciendo necesidades tanto en mercados locales como extranjeros.","url":"https:\/\/ducasseindustrial.com\/ar\/","logo":{"@type":"ImageObject","url":"https:\/\/ducasseindustrial.com\/ar\/wp-content\/uploads\/sites\/17\/2020\/09\/logoDucasse-svg-sin-margen-01.svg","@id":"https:\/\/ducasseindustrial.com\/ar\/#organizationLogo","width":400,"height":88},"image":{"@id":"https:\/\/ducasseindustrial.com\/ar\/#organizationLogo"}},{"@type":"WebPage","@id":"https:\/\/ducasseindustrial.com\/ar\/#webpage","url":"https:\/\/ducasseindustrial.com\/ar\/#webpage","name":"Ducasse Industrial S.A.","inLanguage":"es-CL","isPartOf":{"@id":"https:\/\/ducasseindustrial.com\/ar\/#website"},"breadcrumb":{"@id":"https:\/\/ducasseindustrial.com\/ar\/#webpage"},"datePublished":"2020-07-13T11:53:57-04:00","dateModified":"2026-05-05T08:46:54-04:00"},{"@type":"WebSite","@id":"https:\/\/ducasseindustrial.com\/ar\/#website","url":"https:\/\/ducasseindustrial.com\/ar\/","name":"Ducasse Industrial S.A.","description":"Somos una empresa Chilena, con m\u00e1s de 50 a\u00f1os de experiencia en la fabricaci\u00f3n de herrajes para la industria del mueble y la construcci\u00f3n, satisfaciendo necesidades tanto en mercados locales como extranjeros.","inLanguage":"es-CL","publisher":{"@id":"https:\/\/ducasseindustrial.com\/ar\/#organization"}}]},"og:locale":"es_ES","og:site_name":"Ducasse Industrial S.A. | Somos una empresa Chilena, con m\u00e1s de 50 a\u00f1os de experiencia en la fabricaci\u00f3n de herrajes para la industria del mueble y la construcci\u00f3n, satisfaciendo necesidades tanto en mercados locales como extranjeros.","og:type":"article","og:title":"Ducasse Industrial S.A.","og:url":"https:\/\/ducasseindustrial.com\/ar\/","og:image":"https:\/\/ducasseindustrial.com\/ar\/wp-content\/uploads\/sites\/17\/2020\/09\/logoDucasse-svg-sin-margen-01.svg","og:image:secure_url":"https:\/\/ducasseindustrial.com\/ar\/wp-content\/uploads\/sites\/17\/2020\/09\/logoDucasse-svg-sin-margen-01.svg","article:published_time":"2020-07-13T15:53:57+00:00","article:modified_time":"2026-05-05T12:46:54+00:00","twitter:card":"summary","twitter:title":"Ducasse Industrial S.A.","twitter:image":"https:\/\/ducasseindustrial.com\/ar\/wp-content\/uploads\/sites\/17\/2020\/09\/logoDucasse-svg-sin-margen-01.svg"},"aioseo_meta_data":{"post_id":"186","title":"#site_title","description":"#description","keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":null,"isEnabled":true},"graphs":[]},"schema_type":null,"schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","priority":null,"frequency":null,"local_seo":null,"limit_modified_date":false,"created":"2021-03-01 08:59:03","updated":"2026-05-05 12:52:01","focus_keyword":null,"additional_keywords":null,"truseo_locale":null,"ai":null,"breadcrumb_settings":null,"seo_analyzer_scan_date":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/ducasseindustrial.com\/ar\" title=\"Inicio\">Inicio<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tInicio\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Inicio","link":"https:\/\/ducasseindustrial.com\/ar"},{"label":"Inicio","link":"https:\/\/ducasseindustrial.com\/ar\/"}],"uagb_featured_image_src":{"full":false,"thumbnail":false,"medium":false,"medium_large":false,"large":false,"1536x1536":false,"2048x2048":false,"vp_sm":false,"vp_md":false,"vp_lg":false,"vp_xl":false,"vp_sm_popup":false,"vp_md_popup":false,"vp_xl_popup":false,"woocommerce_thumbnail":false,"woocommerce_single":false,"woocommerce_gallery_thumbnail":false,"variation_swatches_image_size":false,"variation_swatches_tooltip_size":false},"uagb_author_info":{"display_name":"user","author_link":"https:\/\/ducasseindustrial.com\/ar\/author\/user\/"},"uagb_comment_info":0,"uagb_excerpt":"L\u00ednea Heavy Duty Seguridad y eficiencia Sistemas para portones de alto peso. L\u00ednea Mobile Dise\u00f1o y funcionalidad Sistemas corredizos para muebles L\u00ednea Segmenta Dise\u00f1o e innovaci\u00f3n para la transformaci\u00f3n de espacios Organiza Dise\u00f1o e Innovaci\u00f3n Funcional Visitar Soluciones confiables que transforman espacios APLICACI\u00d3N DE DIMENSIONAMIENTO PORT\u00d3N CURVO CONOCE nuestra APP IR A LA APP DESCARGAR&hellip;","_links":{"self":[{"href":"https:\/\/ducasseindustrial.com\/ar\/wp-json\/wp\/v2\/pages\/186","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ducasseindustrial.com\/ar\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/ducasseindustrial.com\/ar\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/ducasseindustrial.com\/ar\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/ducasseindustrial.com\/ar\/wp-json\/wp\/v2\/comments?post=186"}],"version-history":[{"count":348,"href":"https:\/\/ducasseindustrial.com\/ar\/wp-json\/wp\/v2\/pages\/186\/revisions"}],"predecessor-version":[{"id":28740,"href":"https:\/\/ducasseindustrial.com\/ar\/wp-json\/wp\/v2\/pages\/186\/revisions\/28740"}],"wp:attachment":[{"href":"https:\/\/ducasseindustrial.com\/ar\/wp-json\/wp\/v2\/media?parent=186"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}