{"id":378,"count":3,"description":"","link":"https:\/\/ducasseindustrial.com\/ar\/product-category\/productos\/placard\/sistemas-plegables-placard\/","name":"SISTEMAS PLEGABLES","slug":"sistemas-plegables-placard","taxonomy":"product_cat","parent":355,"meta":[],"aioseo_head":"\n\t\t<!-- All in One SEO 5.0.0.1 - aioseo.com -->\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/ducasseindustrial.com\/ar\/product-category\/productos\/placard\/sistemas-plegables-placard\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 5.0.0.1\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/ducasseindustrial.com\\\/ar\\\/wp-json\\\/wp\\\/v2\\\/product_cat\\\/378\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ducasseindustrial.com\\\/ar#listItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\\\/\\\/ducasseindustrial.com\\\/ar\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ducasseindustrial.com\\\/ar\\\/shop-2\\\/#listItem\",\"name\":\"Shop\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ducasseindustrial.com\\\/ar\\\/shop-2\\\/#listItem\",\"position\":2,\"name\":\"Shop\",\"item\":\"https:\\\/\\\/ducasseindustrial.com\\\/ar\\\/shop-2\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ducasseindustrial.com\\\/ar\\\/product-category\\\/productos\\\/#listItem\",\"name\":\"Productos\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ducasseindustrial.com\\\/ar#listItem\",\"name\":\"Inicio\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ducasseindustrial.com\\\/ar\\\/product-category\\\/productos\\\/#listItem\",\"position\":3,\"name\":\"Productos\",\"item\":\"https:\\\/\\\/ducasseindustrial.com\\\/ar\\\/product-category\\\/productos\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ducasseindustrial.com\\\/ar\\\/product-category\\\/productos\\\/placard\\\/#listItem\",\"name\":\"PLACARD\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ducasseindustrial.com\\\/ar\\\/shop-2\\\/#listItem\",\"name\":\"Shop\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ducasseindustrial.com\\\/ar\\\/product-category\\\/productos\\\/placard\\\/#listItem\",\"position\":4,\"name\":\"PLACARD\",\"item\":\"https:\\\/\\\/ducasseindustrial.com\\\/ar\\\/product-category\\\/productos\\\/placard\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ducasseindustrial.com\\\/ar\\\/product-category\\\/productos\\\/placard\\\/sistemas-plegables-placard\\\/#listItem\",\"name\":\"SISTEMAS PLEGABLES\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ducasseindustrial.com\\\/ar\\\/product-category\\\/productos\\\/#listItem\",\"name\":\"Productos\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ducasseindustrial.com\\\/ar\\\/product-category\\\/productos\\\/placard\\\/sistemas-plegables-placard\\\/#listItem\",\"position\":5,\"name\":\"SISTEMAS PLEGABLES\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ducasseindustrial.com\\\/ar\\\/product-category\\\/productos\\\/placard\\\/#listItem\",\"name\":\"PLACARD\"}}]},{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/ducasseindustrial.com\\\/ar\\\/wp-json\\\/wp\\\/v2\\\/product_cat\\\/378\\\/#collectionpage\",\"url\":\"https:\\\/\\\/ducasseindustrial.com\\\/ar\\\/wp-json\\\/wp\\\/v2\\\/product_cat\\\/378\\\/#collectionpage\",\"name\":\"SISTEMAS PLEGABLES | Ducasse Industrial S.A.\",\"inLanguage\":\"es-CL\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/ducasseindustrial.com\\\/ar\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/ducasseindustrial.com\\\/ar\\\/wp-json\\\/wp\\\/v2\\\/product_cat\\\/378\\\/#collectionpage\"}},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/ducasseindustrial.com\\\/ar\\\/#organization\",\"name\":\"Ducasse Industrial S.A.\",\"description\":\"Somos una empresa Chilena, con m\\u00e1s de 50 a\\u00f1os de experiencia en la fabricaci\\u00f3n de herrajes para la industria del mueble y la construcci\\u00f3n, satisfaciendo necesidades tanto en mercados locales como extranjeros.\",\"url\":\"https:\\\/\\\/ducasseindustrial.com\\\/ar\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/ducasseindustrial.com\\\/ar\\\/wp-content\\\/uploads\\\/sites\\\/17\\\/2020\\\/09\\\/logoDucasse-svg-sin-margen-01.svg\",\"@id\":\"https:\\\/\\\/ducasseindustrial.com\\\/ar\\\/wp-json\\\/wp\\\/v2\\\/product_cat\\\/378\\\/#organizationLogo\",\"width\":400,\"height\":88},\"image\":{\"@id\":\"https:\\\/\\\/ducasseindustrial.com\\\/ar\\\/wp-json\\\/wp\\\/v2\\\/product_cat\\\/378\\\/#organizationLogo\"}},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/ducasseindustrial.com\\\/ar\\\/#website\",\"url\":\"https:\\\/\\\/ducasseindustrial.com\\\/ar\\\/\",\"name\":\"Ducasse Industrial S.A.\",\"description\":\"Somos una empresa Chilena, con m\\u00e1s de 50 a\\u00f1os de experiencia en la fabricaci\\u00f3n de herrajes para la industria del mueble y la construcci\\u00f3n, satisfaciendo necesidades tanto en mercados locales como extranjeros.\",\"inLanguage\":\"es-CL\",\"publisher\":{\"@id\":\"https:\\\/\\\/ducasseindustrial.com\\\/ar\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"SISTEMAS PLEGABLES | Ducasse Industrial S.A.","description":"","canonical_url":"https:\/\/ducasseindustrial.com\/ar\/product-category\/productos\/placard\/sistemas-plegables-placard\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BreadcrumbList","@id":"https:\/\/ducasseindustrial.com\/ar\/wp-json\/wp\/v2\/product_cat\/378\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/ducasseindustrial.com\/ar#listItem","position":1,"name":"Inicio","item":"https:\/\/ducasseindustrial.com\/ar","nextItem":{"@type":"ListItem","@id":"https:\/\/ducasseindustrial.com\/ar\/shop-2\/#listItem","name":"Shop"}},{"@type":"ListItem","@id":"https:\/\/ducasseindustrial.com\/ar\/shop-2\/#listItem","position":2,"name":"Shop","item":"https:\/\/ducasseindustrial.com\/ar\/shop-2\/","nextItem":{"@type":"ListItem","@id":"https:\/\/ducasseindustrial.com\/ar\/product-category\/productos\/#listItem","name":"Productos"},"previousItem":{"@type":"ListItem","@id":"https:\/\/ducasseindustrial.com\/ar#listItem","name":"Inicio"}},{"@type":"ListItem","@id":"https:\/\/ducasseindustrial.com\/ar\/product-category\/productos\/#listItem","position":3,"name":"Productos","item":"https:\/\/ducasseindustrial.com\/ar\/product-category\/productos\/","nextItem":{"@type":"ListItem","@id":"https:\/\/ducasseindustrial.com\/ar\/product-category\/productos\/placard\/#listItem","name":"PLACARD"},"previousItem":{"@type":"ListItem","@id":"https:\/\/ducasseindustrial.com\/ar\/shop-2\/#listItem","name":"Shop"}},{"@type":"ListItem","@id":"https:\/\/ducasseindustrial.com\/ar\/product-category\/productos\/placard\/#listItem","position":4,"name":"PLACARD","item":"https:\/\/ducasseindustrial.com\/ar\/product-category\/productos\/placard\/","nextItem":{"@type":"ListItem","@id":"https:\/\/ducasseindustrial.com\/ar\/product-category\/productos\/placard\/sistemas-plegables-placard\/#listItem","name":"SISTEMAS PLEGABLES"},"previousItem":{"@type":"ListItem","@id":"https:\/\/ducasseindustrial.com\/ar\/product-category\/productos\/#listItem","name":"Productos"}},{"@type":"ListItem","@id":"https:\/\/ducasseindustrial.com\/ar\/product-category\/productos\/placard\/sistemas-plegables-placard\/#listItem","position":5,"name":"SISTEMAS PLEGABLES","previousItem":{"@type":"ListItem","@id":"https:\/\/ducasseindustrial.com\/ar\/product-category\/productos\/placard\/#listItem","name":"PLACARD"}}]},{"@type":"CollectionPage","@id":"https:\/\/ducasseindustrial.com\/ar\/wp-json\/wp\/v2\/product_cat\/378\/#collectionpage","url":"https:\/\/ducasseindustrial.com\/ar\/wp-json\/wp\/v2\/product_cat\/378\/#collectionpage","name":"SISTEMAS PLEGABLES | Ducasse Industrial S.A.","inLanguage":"es-CL","isPartOf":{"@id":"https:\/\/ducasseindustrial.com\/ar\/#website"},"breadcrumb":{"@id":"https:\/\/ducasseindustrial.com\/ar\/wp-json\/wp\/v2\/product_cat\/378\/#collectionpage"}},{"@type":"Organization","@id":"https:\/\/ducasseindustrial.com\/ar\/#organization","name":"Ducasse Industrial S.A.","description":"Somos una empresa Chilena, con m\u00e1s de 50 a\u00f1os de experiencia en la fabricaci\u00f3n de herrajes para la industria del mueble y la construcci\u00f3n, satisfaciendo necesidades tanto en mercados locales como extranjeros.","url":"https:\/\/ducasseindustrial.com\/ar\/","logo":{"@type":"ImageObject","url":"https:\/\/ducasseindustrial.com\/ar\/wp-content\/uploads\/sites\/17\/2020\/09\/logoDucasse-svg-sin-margen-01.svg","@id":"https:\/\/ducasseindustrial.com\/ar\/wp-json\/wp\/v2\/product_cat\/378\/#organizationLogo","width":400,"height":88},"image":{"@id":"https:\/\/ducasseindustrial.com\/ar\/wp-json\/wp\/v2\/product_cat\/378\/#organizationLogo"}},{"@type":"WebSite","@id":"https:\/\/ducasseindustrial.com\/ar\/#website","url":"https:\/\/ducasseindustrial.com\/ar\/","name":"Ducasse Industrial S.A.","description":"Somos una empresa Chilena, con m\u00e1s de 50 a\u00f1os de experiencia en la fabricaci\u00f3n de herrajes para la industria del mueble y la construcci\u00f3n, satisfaciendo necesidades tanto en mercados locales como extranjeros.","inLanguage":"es-CL","publisher":{"@id":"https:\/\/ducasseindustrial.com\/ar\/#organization"}}]}},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/ducasseindustrial.com\/ar\" title=\"Inicio\">Inicio<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/ducasseindustrial.com\/ar\/shop-2\/\" title=\"Shop\">Shop<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/ducasseindustrial.com\/ar\/product-category\/productos\/\" title=\"Productos\">Productos<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/ducasseindustrial.com\/ar\/product-category\/productos\/placard\/\" title=\"PLACARD\">PLACARD<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tSISTEMAS PLEGABLES\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Inicio","link":"https:\/\/ducasseindustrial.com\/ar"},{"label":"Shop","link":"https:\/\/ducasseindustrial.com\/ar\/shop-2\/"},{"label":"Productos","link":"https:\/\/ducasseindustrial.com\/ar\/product-category\/productos\/"},{"label":"PLACARD","link":"https:\/\/ducasseindustrial.com\/ar\/product-category\/productos\/placard\/"},{"label":"SISTEMAS PLEGABLES","link":"https:\/\/ducasseindustrial.com\/ar\/product-category\/productos\/placard\/sistemas-plegables-placard\/"}],"_links":{"self":[{"href":"https:\/\/ducasseindustrial.com\/ar\/wp-json\/wp\/v2\/product_cat\/378","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ducasseindustrial.com\/ar\/wp-json\/wp\/v2\/product_cat"}],"about":[{"href":"https:\/\/ducasseindustrial.com\/ar\/wp-json\/wp\/v2\/taxonomies\/product_cat"}],"up":[{"embeddable":true,"href":"https:\/\/ducasseindustrial.com\/ar\/wp-json\/wp\/v2\/product_cat\/355"}],"wp:post_type":[{"href":"https:\/\/ducasseindustrial.com\/ar\/wp-json\/wp\/v2\/product?product_cat=378"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}