{"id":9658,"date":"2021-01-06T00:24:33","date_gmt":"2021-01-06T04:24:33","guid":{"rendered":"https:\/\/ducasseindustrial.com\/cl\/producto\/dn-80-oc-lt"},"modified":"2021-01-06T00:24:36","modified_gmt":"2021-01-06T04:24:36","slug":"dn-80-oc-lt","status":"publish","type":"product","link":"https:\/\/ducasseindustrial.com\/cl\/producto\/dn-80-oc-lt","title":{"rendered":"DN 80 OC LT"},"content":{"rendered":"<p>Sistema corredizo colgante de montaje embutido lateral para puertas de madera desde 50 hasta 80 KG., dise\u00f1ado para divisiones de ambiente, accesos o puertas de paso. Deslizamiento suave con m\u00ednimo esfuerzo tanto para la apertura como al cierre de la hoja. Desplazamiento silencioso, debido a la utilizaci\u00f3n de riel de aluminio y a rodamiento premium con pista rectificada. Freno incorporado evita el rebote de las puertas y entrega un cierre \u00f3ptimo. Su montaje es embutido en el marco de la puerta y regulaci\u00f3n lateral, lo que ayuda a disminuir el paso de la luz entre riel y puerta.<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Sistema corredizo colgante de montaje embutido lateral para puertas de madera desde 50 hasta 80 KG., dise\u00f1ado para divisiones de ambiente, accesos o puertas de paso. Deslizamiento suave con m\u00ednimo esfuerzo tanto para la apertura como al cierre de la hoja. Desplazamiento silencioso, debido a la utilizaci\u00f3n de riel de aluminio y a rodamiento premium [&hellip;]<\/p>\n","protected":false},"featured_media":3450,"comment_status":"closed","ping_status":"open","template":"","meta":{"_uag_custom_page_level_css":"","site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"default","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"_vp_format_video_url":"","_vp_image_focal_point":[]},"product_brand":[],"product_cat":[17,70,72],"product_tag":[198,214,215,217,216],"class_list":{"0":"post-9658","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-productos","7":"product_cat-puertas-de-paso","8":"product_cat-madera-puertas-de-paso","9":"product_tag-ducasse","10":"product_tag-puerta-corredera","11":"product_tag-puerta-corrediza","12":"product_tag-puerta-de-paso","13":"product_tag-sistema-corredero","14":"desktop-align-left","15":"tablet-align-left","16":"mobile-align-left","17":"ast-product-gallery-layout-horizontal","18":"ast-product-tabs-layout-horizontal","20":"first","21":"instock","22":"sold-individually","23":"purchasable","24":"product-type-simple"},"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 5.0.0.1 - aioseo.com -->\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/ducasseindustrial.com\/cl\/producto\/dn-80-oc-lt\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 5.0.0.1\" \/>\n\t\t<meta property=\"og:locale\" content=\"es_ES\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Ducasse Industrial S.A. | Somos una empresa Chilena, con m\u00e1s de 50 a\u00f1os de experiencia en la fabricaci\u00f3n de herrajes para la industria del mueble y la construcci\u00f3n, satisfaciendo necesidades tanto en mercados locales como extranjeros.\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"DN 80 OC LT | Ducasse Industrial S.A.\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/ducasseindustrial.com\/cl\/producto\/dn-80-oc-lt\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/ducasseindustrial.com\/cl\/wp-content\/uploads\/sites\/25\/2020\/09\/logoDucasse-svg-sin-margen-01.svg\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/ducasseindustrial.com\/cl\/wp-content\/uploads\/sites\/25\/2020\/09\/logoDucasse-svg-sin-margen-01.svg\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2021-01-06T04:24:33+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2021-01-06T04:24:36+00:00\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary\" \/>\n\t\t<meta name=\"twitter:title\" content=\"DN 80 OC LT | Ducasse Industrial S.A.\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/ducasseindustrial.com\/cl\/wp-content\/uploads\/sites\/25\/2020\/09\/logoDucasse-svg-sin-margen-01.svg\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/ducasseindustrial.com\\\/cl\\\/producto\\\/dn-80-oc-lt#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ducasseindustrial.com\\\/cl#listItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\\\/\\\/ducasseindustrial.com\\\/cl\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ducasseindustrial.com\\\/cl\\\/shop#listItem\",\"name\":\"Shop\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ducasseindustrial.com\\\/cl\\\/shop#listItem\",\"position\":2,\"name\":\"Shop\",\"item\":\"https:\\\/\\\/ducasseindustrial.com\\\/cl\\\/shop\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ducasseindustrial.com\\\/cl\\\/product-category\\\/productos#listItem\",\"name\":\"Productos\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ducasseindustrial.com\\\/cl#listItem\",\"name\":\"Inicio\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ducasseindustrial.com\\\/cl\\\/product-category\\\/productos#listItem\",\"position\":3,\"name\":\"Productos\",\"item\":\"https:\\\/\\\/ducasseindustrial.com\\\/cl\\\/product-category\\\/productos\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ducasseindustrial.com\\\/cl\\\/product-category\\\/productos\\\/puertas-de-paso#listItem\",\"name\":\"Puertas de Paso\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ducasseindustrial.com\\\/cl\\\/shop#listItem\",\"name\":\"Shop\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ducasseindustrial.com\\\/cl\\\/product-category\\\/productos\\\/puertas-de-paso#listItem\",\"position\":4,\"name\":\"Puertas de Paso\",\"item\":\"https:\\\/\\\/ducasseindustrial.com\\\/cl\\\/product-category\\\/productos\\\/puertas-de-paso\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ducasseindustrial.com\\\/cl\\\/product-category\\\/productos\\\/puertas-de-paso\\\/madera-puertas-de-paso#listItem\",\"name\":\"Madera\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ducasseindustrial.com\\\/cl\\\/product-category\\\/productos#listItem\",\"name\":\"Productos\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ducasseindustrial.com\\\/cl\\\/product-category\\\/productos\\\/puertas-de-paso\\\/madera-puertas-de-paso#listItem\",\"position\":5,\"name\":\"Madera\",\"item\":\"https:\\\/\\\/ducasseindustrial.com\\\/cl\\\/product-category\\\/productos\\\/puertas-de-paso\\\/madera-puertas-de-paso\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ducasseindustrial.com\\\/cl\\\/producto\\\/dn-80-oc-lt#listItem\",\"name\":\"DN 80 OC LT\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ducasseindustrial.com\\\/cl\\\/product-category\\\/productos\\\/puertas-de-paso#listItem\",\"name\":\"Puertas de Paso\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ducasseindustrial.com\\\/cl\\\/producto\\\/dn-80-oc-lt#listItem\",\"position\":6,\"name\":\"DN 80 OC LT\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ducasseindustrial.com\\\/cl\\\/product-category\\\/productos\\\/puertas-de-paso\\\/madera-puertas-de-paso#listItem\",\"name\":\"Madera\"}}]},{\"@type\":\"ItemPage\",\"@id\":\"https:\\\/\\\/ducasseindustrial.com\\\/cl\\\/producto\\\/dn-80-oc-lt#itempage\",\"url\":\"https:\\\/\\\/ducasseindustrial.com\\\/cl\\\/producto\\\/dn-80-oc-lt\",\"name\":\"DN 80 OC LT | Ducasse Industrial S.A.\",\"inLanguage\":\"es-CL\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/ducasseindustrial.com\\\/cl\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/ducasseindustrial.com\\\/cl\\\/producto\\\/dn-80-oc-lt#breadcrumblist\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/ducasseindustrial.com\\\/cl\\\/wp-content\\\/uploads\\\/sites\\\/25\\\/2020\\\/09\\\/CL_10100217473_IMG_PROD1_BL.jpg\",\"@id\":\"https:\\\/\\\/ducasseindustrial.com\\\/cl\\\/producto\\\/dn-80-oc-lt\\\/#mainImage\",\"width\":1920,\"height\":1080},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/ducasseindustrial.com\\\/cl\\\/producto\\\/dn-80-oc-lt#mainImage\"},\"datePublished\":\"2021-01-06T00:24:33-04:00\",\"dateModified\":\"2021-01-06T00:24:36-04:00\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/ducasseindustrial.com\\\/cl\\\/#organization\",\"name\":\"Ducasse Industrial S.A.\",\"description\":\"Somos una empresa Chilena, con m\\u00e1s de 50 a\\u00f1os de experiencia en la fabricaci\\u00f3n de herrajes para la industria del mueble y la construcci\\u00f3n, satisfaciendo necesidades tanto en mercados locales como extranjeros.\",\"url\":\"https:\\\/\\\/ducasseindustrial.com\\\/cl\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/ducasseindustrial.com\\\/cl\\\/wp-content\\\/uploads\\\/sites\\\/25\\\/2020\\\/09\\\/logoDucasse-svg-sin-margen-01.svg\",\"@id\":\"https:\\\/\\\/ducasseindustrial.com\\\/cl\\\/producto\\\/dn-80-oc-lt\\\/#organizationLogo\",\"width\":400,\"height\":88},\"image\":{\"@id\":\"https:\\\/\\\/ducasseindustrial.com\\\/cl\\\/producto\\\/dn-80-oc-lt\\\/#organizationLogo\"}},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/ducasseindustrial.com\\\/cl\\\/#website\",\"url\":\"https:\\\/\\\/ducasseindustrial.com\\\/cl\\\/\",\"name\":\"Ducasse Industrial S.A.\",\"description\":\"Somos una empresa Chilena, con m\\u00e1s de 50 a\\u00f1os de experiencia en la fabricaci\\u00f3n de herrajes para la industria del mueble y la construcci\\u00f3n, satisfaciendo necesidades tanto en mercados locales como extranjeros.\",\"inLanguage\":\"es-CL\",\"publisher\":{\"@id\":\"https:\\\/\\\/ducasseindustrial.com\\\/cl\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"DN 80 OC LT | Ducasse Industrial S.A.","description":"","canonical_url":"https:\/\/ducasseindustrial.com\/cl\/producto\/dn-80-oc-lt","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BreadcrumbList","@id":"https:\/\/ducasseindustrial.com\/cl\/producto\/dn-80-oc-lt#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/ducasseindustrial.com\/cl#listItem","position":1,"name":"Inicio","item":"https:\/\/ducasseindustrial.com\/cl","nextItem":{"@type":"ListItem","@id":"https:\/\/ducasseindustrial.com\/cl\/shop#listItem","name":"Shop"}},{"@type":"ListItem","@id":"https:\/\/ducasseindustrial.com\/cl\/shop#listItem","position":2,"name":"Shop","item":"https:\/\/ducasseindustrial.com\/cl\/shop","nextItem":{"@type":"ListItem","@id":"https:\/\/ducasseindustrial.com\/cl\/product-category\/productos#listItem","name":"Productos"},"previousItem":{"@type":"ListItem","@id":"https:\/\/ducasseindustrial.com\/cl#listItem","name":"Inicio"}},{"@type":"ListItem","@id":"https:\/\/ducasseindustrial.com\/cl\/product-category\/productos#listItem","position":3,"name":"Productos","item":"https:\/\/ducasseindustrial.com\/cl\/product-category\/productos","nextItem":{"@type":"ListItem","@id":"https:\/\/ducasseindustrial.com\/cl\/product-category\/productos\/puertas-de-paso#listItem","name":"Puertas de Paso"},"previousItem":{"@type":"ListItem","@id":"https:\/\/ducasseindustrial.com\/cl\/shop#listItem","name":"Shop"}},{"@type":"ListItem","@id":"https:\/\/ducasseindustrial.com\/cl\/product-category\/productos\/puertas-de-paso#listItem","position":4,"name":"Puertas de Paso","item":"https:\/\/ducasseindustrial.com\/cl\/product-category\/productos\/puertas-de-paso","nextItem":{"@type":"ListItem","@id":"https:\/\/ducasseindustrial.com\/cl\/product-category\/productos\/puertas-de-paso\/madera-puertas-de-paso#listItem","name":"Madera"},"previousItem":{"@type":"ListItem","@id":"https:\/\/ducasseindustrial.com\/cl\/product-category\/productos#listItem","name":"Productos"}},{"@type":"ListItem","@id":"https:\/\/ducasseindustrial.com\/cl\/product-category\/productos\/puertas-de-paso\/madera-puertas-de-paso#listItem","position":5,"name":"Madera","item":"https:\/\/ducasseindustrial.com\/cl\/product-category\/productos\/puertas-de-paso\/madera-puertas-de-paso","nextItem":{"@type":"ListItem","@id":"https:\/\/ducasseindustrial.com\/cl\/producto\/dn-80-oc-lt#listItem","name":"DN 80 OC LT"},"previousItem":{"@type":"ListItem","@id":"https:\/\/ducasseindustrial.com\/cl\/product-category\/productos\/puertas-de-paso#listItem","name":"Puertas de Paso"}},{"@type":"ListItem","@id":"https:\/\/ducasseindustrial.com\/cl\/producto\/dn-80-oc-lt#listItem","position":6,"name":"DN 80 OC LT","previousItem":{"@type":"ListItem","@id":"https:\/\/ducasseindustrial.com\/cl\/product-category\/productos\/puertas-de-paso\/madera-puertas-de-paso#listItem","name":"Madera"}}]},{"@type":"ItemPage","@id":"https:\/\/ducasseindustrial.com\/cl\/producto\/dn-80-oc-lt#itempage","url":"https:\/\/ducasseindustrial.com\/cl\/producto\/dn-80-oc-lt","name":"DN 80 OC LT | Ducasse Industrial S.A.","inLanguage":"es-CL","isPartOf":{"@id":"https:\/\/ducasseindustrial.com\/cl\/#website"},"breadcrumb":{"@id":"https:\/\/ducasseindustrial.com\/cl\/producto\/dn-80-oc-lt#breadcrumblist"},"image":{"@type":"ImageObject","url":"https:\/\/ducasseindustrial.com\/cl\/wp-content\/uploads\/sites\/25\/2020\/09\/CL_10100217473_IMG_PROD1_BL.jpg","@id":"https:\/\/ducasseindustrial.com\/cl\/producto\/dn-80-oc-lt\/#mainImage","width":1920,"height":1080},"primaryImageOfPage":{"@id":"https:\/\/ducasseindustrial.com\/cl\/producto\/dn-80-oc-lt#mainImage"},"datePublished":"2021-01-06T00:24:33-04:00","dateModified":"2021-01-06T00:24:36-04:00"},{"@type":"Organization","@id":"https:\/\/ducasseindustrial.com\/cl\/#organization","name":"Ducasse Industrial S.A.","description":"Somos una empresa Chilena, con m\u00e1s de 50 a\u00f1os de experiencia en la fabricaci\u00f3n de herrajes para la industria del mueble y la construcci\u00f3n, satisfaciendo necesidades tanto en mercados locales como extranjeros.","url":"https:\/\/ducasseindustrial.com\/cl\/","logo":{"@type":"ImageObject","url":"https:\/\/ducasseindustrial.com\/cl\/wp-content\/uploads\/sites\/25\/2020\/09\/logoDucasse-svg-sin-margen-01.svg","@id":"https:\/\/ducasseindustrial.com\/cl\/producto\/dn-80-oc-lt\/#organizationLogo","width":400,"height":88},"image":{"@id":"https:\/\/ducasseindustrial.com\/cl\/producto\/dn-80-oc-lt\/#organizationLogo"}},{"@type":"WebSite","@id":"https:\/\/ducasseindustrial.com\/cl\/#website","url":"https:\/\/ducasseindustrial.com\/cl\/","name":"Ducasse Industrial S.A.","description":"Somos una empresa Chilena, con m\u00e1s de 50 a\u00f1os de experiencia en la fabricaci\u00f3n de herrajes para la industria del mueble y la construcci\u00f3n, satisfaciendo necesidades tanto en mercados locales como extranjeros.","inLanguage":"es-CL","publisher":{"@id":"https:\/\/ducasseindustrial.com\/cl\/#organization"}}]},"og:locale":"es_ES","og:site_name":"Ducasse Industrial S.A. | Somos una empresa Chilena, con m\u00e1s de 50 a\u00f1os de experiencia en la fabricaci\u00f3n de herrajes para la industria del mueble y la construcci\u00f3n, satisfaciendo necesidades tanto en mercados locales como extranjeros.","og:type":"article","og:title":"DN 80 OC LT | Ducasse Industrial S.A.","og:url":"https:\/\/ducasseindustrial.com\/cl\/producto\/dn-80-oc-lt","og:image":"https:\/\/ducasseindustrial.com\/cl\/wp-content\/uploads\/sites\/25\/2020\/09\/logoDucasse-svg-sin-margen-01.svg","og:image:secure_url":"https:\/\/ducasseindustrial.com\/cl\/wp-content\/uploads\/sites\/25\/2020\/09\/logoDucasse-svg-sin-margen-01.svg","article:published_time":"2021-01-06T04:24:33+00:00","article:modified_time":"2021-01-06T04:24:36+00:00","twitter:card":"summary","twitter:title":"DN 80 OC LT | Ducasse Industrial S.A.","twitter:image":"https:\/\/ducasseindustrial.com\/cl\/wp-content\/uploads\/sites\/25\/2020\/09\/logoDucasse-svg-sin-margen-01.svg"},"aioseo_meta_data":{"post_id":"9658","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":null,"isEnabled":true},"graphs":[]},"schema_type":null,"schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","priority":null,"frequency":null,"local_seo":null,"breadcrumb_settings":null,"limit_modified_date":false,"ai":null,"created":"2021-03-01 11:23:02","updated":"2025-11-01 00:39:56","focus_keyword":null,"additional_keywords":null,"truseo_locale":null,"seo_analyzer_scan_date":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/ducasseindustrial.com\/cl\" title=\"Inicio\">Inicio<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">\u00bb<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/ducasseindustrial.com\/cl\/shop\" title=\"Shop\">Shop<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">\u00bb<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/ducasseindustrial.com\/cl\/product-category\/productos\" title=\"Productos\">Productos<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">\u00bb<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/ducasseindustrial.com\/cl\/product-category\/productos\/puertas-de-paso\" title=\"Puertas de Paso\">Puertas de Paso<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">\u00bb<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/ducasseindustrial.com\/cl\/product-category\/productos\/puertas-de-paso\/madera-puertas-de-paso\" title=\"Madera\">Madera<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">\u00bb<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tDN 80 OC LT\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Inicio","link":"https:\/\/ducasseindustrial.com\/cl"},{"label":"Shop","link":"https:\/\/ducasseindustrial.com\/cl\/shop"},{"label":"Productos","link":"https:\/\/ducasseindustrial.com\/cl\/product-category\/productos"},{"label":"Puertas de Paso","link":"https:\/\/ducasseindustrial.com\/cl\/product-category\/productos\/puertas-de-paso"},{"label":"Madera","link":"https:\/\/ducasseindustrial.com\/cl\/product-category\/productos\/puertas-de-paso\/madera-puertas-de-paso"},{"label":"DN 80 OC LT","link":"https:\/\/ducasseindustrial.com\/cl\/producto\/dn-80-oc-lt"}],"uagb_featured_image_src":{"full":["https:\/\/ducasseindustrial.com\/cl\/wp-content\/uploads\/sites\/25\/2020\/09\/CL_10100217473_IMG_PROD1_BL.jpg",1920,1080,false],"thumbnail":["https:\/\/ducasseindustrial.com\/cl\/wp-content\/uploads\/sites\/25\/2020\/09\/CL_10100217473_IMG_PROD1_BL-300x300.jpg",300,300,true],"medium":["https:\/\/ducasseindustrial.com\/cl\/wp-content\/uploads\/sites\/25\/2020\/09\/CL_10100217473_IMG_PROD1_BL-600x338.jpg",600,338,true],"medium_large":["https:\/\/ducasseindustrial.com\/cl\/wp-content\/uploads\/sites\/25\/2020\/09\/CL_10100217473_IMG_PROD1_BL-768x432.jpg",768,432,true],"large":["https:\/\/ducasseindustrial.com\/cl\/wp-content\/uploads\/sites\/25\/2020\/09\/CL_10100217473_IMG_PROD1_BL-1024x576.jpg",1024,576,true],"1536x1536":["https:\/\/ducasseindustrial.com\/cl\/wp-content\/uploads\/sites\/25\/2020\/09\/CL_10100217473_IMG_PROD1_BL-1536x864.jpg",1536,864,true],"2048x2048":["https:\/\/ducasseindustrial.com\/cl\/wp-content\/uploads\/sites\/25\/2020\/09\/CL_10100217473_IMG_PROD1_BL.jpg",1920,1080,false],"vp_sm":["https:\/\/ducasseindustrial.com\/cl\/wp-content\/uploads\/sites\/25\/2020\/09\/CL_10100217473_IMG_PROD1_BL-500x281.jpg",500,281,true],"vp_md":["https:\/\/ducasseindustrial.com\/cl\/wp-content\/uploads\/sites\/25\/2020\/09\/CL_10100217473_IMG_PROD1_BL-800x450.jpg",800,450,true],"vp_lg":["https:\/\/ducasseindustrial.com\/cl\/wp-content\/uploads\/sites\/25\/2020\/09\/CL_10100217473_IMG_PROD1_BL-1280x720.jpg",1280,720,true],"vp_xl":["https:\/\/ducasseindustrial.com\/cl\/wp-content\/uploads\/sites\/25\/2020\/09\/CL_10100217473_IMG_PROD1_BL.jpg",1920,1080,false],"vp_sm_popup":["https:\/\/ducasseindustrial.com\/cl\/wp-content\/uploads\/sites\/25\/2020\/09\/CL_10100217473_IMG_PROD1_BL-500x281.jpg",500,281,true],"vp_md_popup":["https:\/\/ducasseindustrial.com\/cl\/wp-content\/uploads\/sites\/25\/2020\/09\/CL_10100217473_IMG_PROD1_BL-800x450.jpg",800,450,true],"vp_xl_popup":["https:\/\/ducasseindustrial.com\/cl\/wp-content\/uploads\/sites\/25\/2020\/09\/CL_10100217473_IMG_PROD1_BL.jpg",1920,1080,false],"woocommerce_thumbnail":["https:\/\/ducasseindustrial.com\/cl\/wp-content\/uploads\/sites\/25\/2020\/09\/CL_10100217473_IMG_PROD1_BL-300x300.jpg",300,300,true],"woocommerce_single":["https:\/\/ducasseindustrial.com\/cl\/wp-content\/uploads\/sites\/25\/2020\/09\/CL_10100217473_IMG_PROD1_BL-1024x576.jpg",1024,576,true],"woocommerce_gallery_thumbnail":["https:\/\/ducasseindustrial.com\/cl\/wp-content\/uploads\/sites\/25\/2020\/09\/CL_10100217473_IMG_PROD1_BL-100x100.jpg",100,100,true],"variation_swatches_image_size":["https:\/\/ducasseindustrial.com\/cl\/wp-content\/uploads\/sites\/25\/2020\/09\/CL_10100217473_IMG_PROD1_BL.jpg",50,28,false],"variation_swatches_tooltip_size":["https:\/\/ducasseindustrial.com\/cl\/wp-content\/uploads\/sites\/25\/2020\/09\/CL_10100217473_IMG_PROD1_BL.jpg",100,56,false]},"uagb_author_info":{"display_name":"user","author_link":"https:\/\/ducasseindustrial.com\/cl\/archivo\/author"},"uagb_comment_info":0,"uagb_excerpt":"Sistema corredizo colgante de montaje embutido lateral para puertas de madera desde 50 hasta 80 KG., dise\u00f1ado para divisiones de ambiente, accesos o puertas de paso. Deslizamiento suave con m\u00ednimo esfuerzo tanto para la apertura como al cierre de la hoja. Desplazamiento silencioso, debido a la utilizaci\u00f3n de riel de aluminio y a rodamiento premium&hellip;","_links":{"self":[{"href":"https:\/\/ducasseindustrial.com\/cl\/wp-json\/wp\/v2\/product\/9658","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ducasseindustrial.com\/cl\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/ducasseindustrial.com\/cl\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/ducasseindustrial.com\/cl\/wp-json\/wp\/v2\/comments?post=9658"}],"version-history":[{"count":2,"href":"https:\/\/ducasseindustrial.com\/cl\/wp-json\/wp\/v2\/product\/9658\/revisions"}],"predecessor-version":[{"id":16006,"href":"https:\/\/ducasseindustrial.com\/cl\/wp-json\/wp\/v2\/product\/9658\/revisions\/16006"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ducasseindustrial.com\/cl\/wp-json\/wp\/v2\/media\/3450"}],"wp:attachment":[{"href":"https:\/\/ducasseindustrial.com\/cl\/wp-json\/wp\/v2\/media?parent=9658"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/ducasseindustrial.com\/cl\/wp-json\/wp\/v2\/product_brand?post=9658"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/ducasseindustrial.com\/cl\/wp-json\/wp\/v2\/product_cat?post=9658"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/ducasseindustrial.com\/cl\/wp-json\/wp\/v2\/product_tag?post=9658"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}