{"id":10299,"date":"2020-10-30T11:55:21","date_gmt":"2020-10-30T15:55:21","guid":{"rendered":"https:\/\/ducasseindustrial.com\/co\/soluciones"},"modified":"2020-10-30T11:55:21","modified_gmt":"2020-10-30T15:55:21","slug":"soluciones","status":"publish","type":"page","link":"https:\/\/ducasseindustrial.com\/co\/soluciones\/","title":{"rendered":"Soluciones"},"content":{"rendered":"<p><\/p>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":5,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_uag_custom_page_level_css":"","site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"default","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"_vp_format_video_url":"","_vp_image_focal_point":[],"footnotes":""},"class_list":["post-10299","page","type-page","status-publish","hentry"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 5.0.0.1 - aioseo.com -->\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/ducasseindustrial.com\/co\/soluciones\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 5.0.0.1\" \/>\n\t\t<meta property=\"og:locale\" content=\"es_ES\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Ducasse Industrial S.A. | Somos una empresa Chilena, con m\u00e1s de 50 a\u00f1os de experiencia en la fabricaci\u00f3n de herrajes para la industria del mueble y la construcci\u00f3n, satisfaciendo necesidades tanto en mercados locales como extranjeros.\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Soluciones | Ducasse Industrial S.A.\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/ducasseindustrial.com\/co\/soluciones\/\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/ducasseindustrial.com\/co\/wp-content\/uploads\/sites\/19\/2024\/09\/logo_web_ducasse.svg\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/ducasseindustrial.com\/co\/wp-content\/uploads\/sites\/19\/2024\/09\/logo_web_ducasse.svg\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2020-10-30T15:55:21+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2020-10-30T15:55:21+00:00\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Soluciones | Ducasse Industrial S.A.\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/ducasseindustrial.com\/co\/wp-content\/uploads\/sites\/19\/2024\/09\/logo_web_ducasse.svg\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/ducasseindustrial.com\\\/co\\\/soluciones\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ducasseindustrial.com\\\/co#listItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\\\/\\\/ducasseindustrial.com\\\/co\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ducasseindustrial.com\\\/co\\\/soluciones\\\/#listItem\",\"name\":\"Soluciones\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ducasseindustrial.com\\\/co\\\/soluciones\\\/#listItem\",\"position\":2,\"name\":\"Soluciones\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ducasseindustrial.com\\\/co#listItem\",\"name\":\"Inicio\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/ducasseindustrial.com\\\/co\\\/#organization\",\"name\":\"Ducasse Industrial S.A.\",\"description\":\"Somos una empresa Chilena, con m\\u00e1s de 50 a\\u00f1os de experiencia en la fabricaci\\u00f3n de herrajes para la industria del mueble y la construcci\\u00f3n, satisfaciendo necesidades tanto en mercados locales como extranjeros.\",\"url\":\"https:\\\/\\\/ducasseindustrial.com\\\/co\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/ducasseindustrial.com\\\/co\\\/wp-content\\\/uploads\\\/sites\\\/19\\\/2024\\\/09\\\/logo_web_ducasse.svg\",\"@id\":\"https:\\\/\\\/ducasseindustrial.com\\\/co\\\/soluciones\\\/#organizationLogo\",\"width\":1004,\"height\":294},\"image\":{\"@id\":\"https:\\\/\\\/ducasseindustrial.com\\\/co\\\/soluciones\\\/#organizationLogo\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/ducasseindustrial.com\\\/co\\\/soluciones\\\/#webpage\",\"url\":\"https:\\\/\\\/ducasseindustrial.com\\\/co\\\/soluciones\\\/#webpage\",\"name\":\"Soluciones | Ducasse Industrial S.A.\",\"inLanguage\":\"es-CL\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/ducasseindustrial.com\\\/co\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/ducasseindustrial.com\\\/co\\\/soluciones\\\/#webpage\"},\"datePublished\":\"2020-10-30T11:55:21-04:00\",\"dateModified\":\"2020-10-30T11:55:21-04:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/ducasseindustrial.com\\\/co\\\/#website\",\"url\":\"https:\\\/\\\/ducasseindustrial.com\\\/co\\\/\",\"name\":\"Ducasse Industrial S.A.\",\"description\":\"Somos una empresa Chilena, con m\\u00e1s de 50 a\\u00f1os de experiencia en la fabricaci\\u00f3n de herrajes para la industria del mueble y la construcci\\u00f3n, satisfaciendo necesidades tanto en mercados locales como extranjeros.\",\"inLanguage\":\"es-CL\",\"publisher\":{\"@id\":\"https:\\\/\\\/ducasseindustrial.com\\\/co\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"Soluciones | Ducasse Industrial S.A.","description":"","canonical_url":"https:\/\/ducasseindustrial.com\/co\/soluciones\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BreadcrumbList","@id":"https:\/\/ducasseindustrial.com\/co\/soluciones\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/ducasseindustrial.com\/co#listItem","position":1,"name":"Inicio","item":"https:\/\/ducasseindustrial.com\/co","nextItem":{"@type":"ListItem","@id":"https:\/\/ducasseindustrial.com\/co\/soluciones\/#listItem","name":"Soluciones"}},{"@type":"ListItem","@id":"https:\/\/ducasseindustrial.com\/co\/soluciones\/#listItem","position":2,"name":"Soluciones","previousItem":{"@type":"ListItem","@id":"https:\/\/ducasseindustrial.com\/co#listItem","name":"Inicio"}}]},{"@type":"Organization","@id":"https:\/\/ducasseindustrial.com\/co\/#organization","name":"Ducasse Industrial S.A.","description":"Somos una empresa Chilena, con m\u00e1s de 50 a\u00f1os de experiencia en la fabricaci\u00f3n de herrajes para la industria del mueble y la construcci\u00f3n, satisfaciendo necesidades tanto en mercados locales como extranjeros.","url":"https:\/\/ducasseindustrial.com\/co\/","logo":{"@type":"ImageObject","url":"https:\/\/ducasseindustrial.com\/co\/wp-content\/uploads\/sites\/19\/2024\/09\/logo_web_ducasse.svg","@id":"https:\/\/ducasseindustrial.com\/co\/soluciones\/#organizationLogo","width":1004,"height":294},"image":{"@id":"https:\/\/ducasseindustrial.com\/co\/soluciones\/#organizationLogo"}},{"@type":"WebPage","@id":"https:\/\/ducasseindustrial.com\/co\/soluciones\/#webpage","url":"https:\/\/ducasseindustrial.com\/co\/soluciones\/#webpage","name":"Soluciones | Ducasse Industrial S.A.","inLanguage":"es-CL","isPartOf":{"@id":"https:\/\/ducasseindustrial.com\/co\/#website"},"breadcrumb":{"@id":"https:\/\/ducasseindustrial.com\/co\/soluciones\/#webpage"},"datePublished":"2020-10-30T11:55:21-04:00","dateModified":"2020-10-30T11:55:21-04:00"},{"@type":"WebSite","@id":"https:\/\/ducasseindustrial.com\/co\/#website","url":"https:\/\/ducasseindustrial.com\/co\/","name":"Ducasse Industrial S.A.","description":"Somos una empresa Chilena, con m\u00e1s de 50 a\u00f1os de experiencia en la fabricaci\u00f3n de herrajes para la industria del mueble y la construcci\u00f3n, satisfaciendo necesidades tanto en mercados locales como extranjeros.","inLanguage":"es-CL","publisher":{"@id":"https:\/\/ducasseindustrial.com\/co\/#organization"}}]},"og:locale":"es_ES","og:site_name":"Ducasse Industrial S.A. | Somos una empresa Chilena, con m\u00e1s de 50 a\u00f1os de experiencia en la fabricaci\u00f3n de herrajes para la industria del mueble y la construcci\u00f3n, satisfaciendo necesidades tanto en mercados locales como extranjeros.","og:type":"article","og:title":"Soluciones | Ducasse Industrial S.A.","og:url":"https:\/\/ducasseindustrial.com\/co\/soluciones\/","og:image":"https:\/\/ducasseindustrial.com\/co\/wp-content\/uploads\/sites\/19\/2024\/09\/logo_web_ducasse.svg","og:image:secure_url":"https:\/\/ducasseindustrial.com\/co\/wp-content\/uploads\/sites\/19\/2024\/09\/logo_web_ducasse.svg","article:published_time":"2020-10-30T15:55:21+00:00","article:modified_time":"2020-10-30T15:55:21+00:00","twitter:card":"summary","twitter:title":"Soluciones | Ducasse Industrial S.A.","twitter:image":"https:\/\/ducasseindustrial.com\/co\/wp-content\/uploads\/sites\/19\/2024\/09\/logo_web_ducasse.svg"},"aioseo_meta_data":{"post_id":"10299","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"WebPage","isEnabled":true},"graphs":[]},"schema_type":null,"schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","priority":null,"frequency":null,"local_seo":null,"breadcrumb_settings":null,"limit_modified_date":false,"ai":null,"created":"2021-06-04 13:00:32","updated":"2025-11-01 00:37:49","focus_keyword":null,"additional_keywords":null,"truseo_locale":null,"seo_analyzer_scan_date":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/ducasseindustrial.com\/co\" title=\"Inicio\">Inicio<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tSoluciones\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Inicio","link":"https:\/\/ducasseindustrial.com\/co"},{"label":"Soluciones","link":"https:\/\/ducasseindustrial.com\/co\/soluciones\/"}],"uagb_featured_image_src":{"full":false,"thumbnail":false,"medium":false,"medium_large":false,"large":false,"1536x1536":false,"2048x2048":false,"vp_sm":false,"vp_md":false,"vp_lg":false,"vp_xl":false,"vp_sm_popup":false,"vp_md_popup":false,"vp_xl_popup":false,"woocommerce_thumbnail":false,"woocommerce_single":false,"woocommerce_gallery_thumbnail":false,"variation_swatches_image_size":false,"variation_swatches_tooltip_size":false},"uagb_author_info":{"display_name":"operador","author_link":"https:\/\/ducasseindustrial.com\/co\/author\/operador\/"},"uagb_comment_info":0,"uagb_excerpt":null,"_links":{"self":[{"href":"https:\/\/ducasseindustrial.com\/co\/wp-json\/wp\/v2\/pages\/10299","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ducasseindustrial.com\/co\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/ducasseindustrial.com\/co\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/ducasseindustrial.com\/co\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/ducasseindustrial.com\/co\/wp-json\/wp\/v2\/comments?post=10299"}],"version-history":[{"count":0,"href":"https:\/\/ducasseindustrial.com\/co\/wp-json\/wp\/v2\/pages\/10299\/revisions"}],"wp:attachment":[{"href":"https:\/\/ducasseindustrial.com\/co\/wp-json\/wp\/v2\/media?parent=10299"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}