{"id":9676,"date":"2020-11-10T07:08:59","date_gmt":"2020-11-10T11:08:59","guid":{"rendered":"https:\/\/ducasseindustrial.com\/co\/product\/guia-pg-35\/"},"modified":"2020-11-10T07:09:00","modified_gmt":"2020-11-10T11:09:00","slug":"guia-pg-35","status":"publish","type":"product","link":"https:\/\/ducasseindustrial.com\/co\/product\/guia-pg-35\/","title":{"rendered":"GU\u00cdA PG 35"},"content":{"rendered":"<p>Gu\u00eda inferior para portones colgantes. Fabricada en acero con cabezal de bronce de di\u00e1metro 35. Se puede fijar al port\u00f3n o al piso. Permite guiar el recorrido de un port\u00f3n colgante a trav\u00e9s de un canal inferior, asegurando la correcta funcionalidad de la hoja en apertura o cierre. Se puede usar en portones residenciales, comerciales e industriales. Se usa con perfil gu\u00eda de 40mm<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Gu\u00eda inferior para portones colgantes. Fabricada en acero con cabezal de bronce de di\u00e1metro 35. Se puede fijar al port\u00f3n o al piso. Permite guiar el recorrido de un port\u00f3n colgante a trav\u00e9s de un canal inferior, asegurando la correcta funcionalidad de la hoja en apertura o cierre. Se puede usar en portones residenciales, comerciales [&hellip;]<\/p>\n","protected":false},"featured_media":9679,"comment_status":"closed","ping_status":"open","template":"","meta":{"_uag_custom_page_level_css":"","site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"default","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"_vp_format_video_url":"","_vp_image_focal_point":[]},"product_brand":[],"product_cat":[304,303,17],"product_tag":[198,323,306,311],"class_list":{"0":"post-9676","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-accesorios-portones","7":"product_cat-portones","8":"product_cat-productos","9":"product_tag-ducasse","10":"product_tag-guia-porton","11":"product_tag-porton","12":"product_tag-portones","13":"desktop-align-left","14":"tablet-align-left","15":"mobile-align-left","16":"ast-product-gallery-layout-horizontal","17":"ast-product-gallery-with-no-image","18":"ast-product-tabs-layout-horizontal","20":"first","21":"instock","22":"sold-individually","23":"purchasable","24":"product-type-simple"},"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 5.0.0.1 - aioseo.com -->\n\t<meta name=\"description\" content=\"Gu\u00eda inferior para portones colgantes. Fabricada en acero con cabezal de bronce de di\u00e1metro 35. Se puede fijar al port\u00f3n o al piso. Permite guiar el recorrido de un port\u00f3n colgante a trav\u00e9s de un canal inferior, asegurando la correcta funcionalidad de la hoja en apertura o cierre. Se puede usar en portones residenciales, comerciales\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/ducasseindustrial.com\/co\/product\/guia-pg-35\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 5.0.0.1\" \/>\n\t\t<meta property=\"og:locale\" content=\"es_ES\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Ducasse Industrial S.A. | Somos una empresa Chilena, con m\u00e1s de 50 a\u00f1os de experiencia en la fabricaci\u00f3n de herrajes para la industria del mueble y la construcci\u00f3n, satisfaciendo necesidades tanto en mercados locales como extranjeros.\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"GU\u00cdA PG 35 | Ducasse Industrial S.A.\" \/>\n\t\t<meta property=\"og:description\" content=\"Gu\u00eda inferior para portones colgantes. Fabricada en acero con cabezal de bronce de di\u00e1metro 35. Se puede fijar al port\u00f3n o al piso. Permite guiar el recorrido de un port\u00f3n colgante a trav\u00e9s de un canal inferior, asegurando la correcta funcionalidad de la hoja en apertura o cierre. Se puede usar en portones residenciales, comerciales\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/ducasseindustrial.com\/co\/product\/guia-pg-35\/\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/ducasseindustrial.com\/co\/wp-content\/uploads\/sites\/19\/2024\/09\/logo_web_ducasse.svg\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/ducasseindustrial.com\/co\/wp-content\/uploads\/sites\/19\/2024\/09\/logo_web_ducasse.svg\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2020-11-10T11:08:59+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2020-11-10T11:09:00+00:00\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary\" \/>\n\t\t<meta name=\"twitter:title\" content=\"GU\u00cdA PG 35 | Ducasse Industrial S.A.\" \/>\n\t\t<meta name=\"twitter:description\" content=\"Gu\u00eda inferior para portones colgantes. Fabricada en acero con cabezal de bronce de di\u00e1metro 35. Se puede fijar al port\u00f3n o al piso. Permite guiar el recorrido de un port\u00f3n colgante a trav\u00e9s de un canal inferior, asegurando la correcta funcionalidad de la hoja en apertura o cierre. Se puede usar en portones residenciales, comerciales\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/ducasseindustrial.com\/co\/wp-content\/uploads\/sites\/19\/2024\/09\/logo_web_ducasse.svg\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/ducasseindustrial.com\\\/co\\\/product\\\/guia-pg-35\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ducasseindustrial.com\\\/co#listItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\\\/\\\/ducasseindustrial.com\\\/co\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ducasseindustrial.com\\\/co\\\/shop-2\\\/#listItem\",\"name\":\"Shop\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ducasseindustrial.com\\\/co\\\/shop-2\\\/#listItem\",\"position\":2,\"name\":\"Shop\",\"item\":\"https:\\\/\\\/ducasseindustrial.com\\\/co\\\/shop-2\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ducasseindustrial.com\\\/co\\\/product-category\\\/productos\\\/#listItem\",\"name\":\"Productos\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ducasseindustrial.com\\\/co#listItem\",\"name\":\"Inicio\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ducasseindustrial.com\\\/co\\\/product-category\\\/productos\\\/#listItem\",\"position\":3,\"name\":\"Productos\",\"item\":\"https:\\\/\\\/ducasseindustrial.com\\\/co\\\/product-category\\\/productos\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ducasseindustrial.com\\\/co\\\/product-category\\\/productos\\\/portones\\\/#listItem\",\"name\":\"PORTONES\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ducasseindustrial.com\\\/co\\\/shop-2\\\/#listItem\",\"name\":\"Shop\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ducasseindustrial.com\\\/co\\\/product-category\\\/productos\\\/portones\\\/#listItem\",\"position\":4,\"name\":\"PORTONES\",\"item\":\"https:\\\/\\\/ducasseindustrial.com\\\/co\\\/product-category\\\/productos\\\/portones\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ducasseindustrial.com\\\/co\\\/product-category\\\/productos\\\/portones\\\/accesorios-portones\\\/#listItem\",\"name\":\"ACCESORIOS\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ducasseindustrial.com\\\/co\\\/product-category\\\/productos\\\/#listItem\",\"name\":\"Productos\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ducasseindustrial.com\\\/co\\\/product-category\\\/productos\\\/portones\\\/accesorios-portones\\\/#listItem\",\"position\":5,\"name\":\"ACCESORIOS\",\"item\":\"https:\\\/\\\/ducasseindustrial.com\\\/co\\\/product-category\\\/productos\\\/portones\\\/accesorios-portones\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ducasseindustrial.com\\\/co\\\/product\\\/guia-pg-35\\\/#listItem\",\"name\":\"GU\\u00cdA PG 35\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ducasseindustrial.com\\\/co\\\/product-category\\\/productos\\\/portones\\\/#listItem\",\"name\":\"PORTONES\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ducasseindustrial.com\\\/co\\\/product\\\/guia-pg-35\\\/#listItem\",\"position\":6,\"name\":\"GU\\u00cdA PG 35\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ducasseindustrial.com\\\/co\\\/product-category\\\/productos\\\/portones\\\/accesorios-portones\\\/#listItem\",\"name\":\"ACCESORIOS\"}}]},{\"@type\":\"ItemPage\",\"@id\":\"https:\\\/\\\/ducasseindustrial.com\\\/co\\\/product\\\/guia-pg-35\\\/#itempage\",\"url\":\"https:\\\/\\\/ducasseindustrial.com\\\/co\\\/product\\\/guia-pg-35\\\/\",\"name\":\"GU\\u00cdA PG 35 | Ducasse Industrial S.A.\",\"description\":\"Gu\\u00eda inferior para portones colgantes. Fabricada en acero con cabezal de bronce de di\\u00e1metro 35. Se puede fijar al port\\u00f3n o al piso. Permite guiar el recorrido de un port\\u00f3n colgante a trav\\u00e9s de un canal inferior, asegurando la correcta funcionalidad de la hoja en apertura o cierre. Se puede usar en portones residenciales, comerciales\",\"inLanguage\":\"es-CL\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/ducasseindustrial.com\\\/co\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/ducasseindustrial.com\\\/co\\\/product\\\/guia-pg-35\\\/#breadcrumblist\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/ducasseindustrial.com\\\/co\\\/wp-content\\\/uploads\\\/sites\\\/19\\\/2020\\\/11\\\/CO_10101105501_IMG_PROD1_BL.jpg\",\"@id\":\"https:\\\/\\\/ducasseindustrial.com\\\/co\\\/product\\\/guia-pg-35\\\/#mainImage\",\"width\":1920,\"height\":1080},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/ducasseindustrial.com\\\/co\\\/product\\\/guia-pg-35\\\/#mainImage\"},\"datePublished\":\"2020-11-10T07:08:59-04:00\",\"dateModified\":\"2020-11-10T07:09:00-04:00\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/ducasseindustrial.com\\\/co\\\/#organization\",\"name\":\"Ducasse Industrial S.A.\",\"description\":\"Somos una empresa Chilena, con m\\u00e1s de 50 a\\u00f1os de experiencia en la fabricaci\\u00f3n de herrajes para la industria del mueble y la construcci\\u00f3n, satisfaciendo necesidades tanto en mercados locales como extranjeros.\",\"url\":\"https:\\\/\\\/ducasseindustrial.com\\\/co\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/ducasseindustrial.com\\\/co\\\/wp-content\\\/uploads\\\/sites\\\/19\\\/2024\\\/09\\\/logo_web_ducasse.svg\",\"@id\":\"https:\\\/\\\/ducasseindustrial.com\\\/co\\\/product\\\/guia-pg-35\\\/#organizationLogo\",\"width\":1004,\"height\":294},\"image\":{\"@id\":\"https:\\\/\\\/ducasseindustrial.com\\\/co\\\/product\\\/guia-pg-35\\\/#organizationLogo\"}},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/ducasseindustrial.com\\\/co\\\/#website\",\"url\":\"https:\\\/\\\/ducasseindustrial.com\\\/co\\\/\",\"name\":\"Ducasse Industrial S.A.\",\"description\":\"Somos una empresa Chilena, con m\\u00e1s de 50 a\\u00f1os de experiencia en la fabricaci\\u00f3n de herrajes para la industria del mueble y la construcci\\u00f3n, satisfaciendo necesidades tanto en mercados locales como extranjeros.\",\"inLanguage\":\"es-CL\",\"publisher\":{\"@id\":\"https:\\\/\\\/ducasseindustrial.com\\\/co\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"GU\u00cdA PG 35 | Ducasse Industrial S.A.","description":"Gu\u00eda inferior para portones colgantes. Fabricada en acero con cabezal de bronce de di\u00e1metro 35. Se puede fijar al port\u00f3n o al piso. Permite guiar el recorrido de un port\u00f3n colgante a trav\u00e9s de un canal inferior, asegurando la correcta funcionalidad de la hoja en apertura o cierre. Se puede usar en portones residenciales, comerciales","canonical_url":"https:\/\/ducasseindustrial.com\/co\/product\/guia-pg-35\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BreadcrumbList","@id":"https:\/\/ducasseindustrial.com\/co\/product\/guia-pg-35\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/ducasseindustrial.com\/co#listItem","position":1,"name":"Inicio","item":"https:\/\/ducasseindustrial.com\/co","nextItem":{"@type":"ListItem","@id":"https:\/\/ducasseindustrial.com\/co\/shop-2\/#listItem","name":"Shop"}},{"@type":"ListItem","@id":"https:\/\/ducasseindustrial.com\/co\/shop-2\/#listItem","position":2,"name":"Shop","item":"https:\/\/ducasseindustrial.com\/co\/shop-2\/","nextItem":{"@type":"ListItem","@id":"https:\/\/ducasseindustrial.com\/co\/product-category\/productos\/#listItem","name":"Productos"},"previousItem":{"@type":"ListItem","@id":"https:\/\/ducasseindustrial.com\/co#listItem","name":"Inicio"}},{"@type":"ListItem","@id":"https:\/\/ducasseindustrial.com\/co\/product-category\/productos\/#listItem","position":3,"name":"Productos","item":"https:\/\/ducasseindustrial.com\/co\/product-category\/productos\/","nextItem":{"@type":"ListItem","@id":"https:\/\/ducasseindustrial.com\/co\/product-category\/productos\/portones\/#listItem","name":"PORTONES"},"previousItem":{"@type":"ListItem","@id":"https:\/\/ducasseindustrial.com\/co\/shop-2\/#listItem","name":"Shop"}},{"@type":"ListItem","@id":"https:\/\/ducasseindustrial.com\/co\/product-category\/productos\/portones\/#listItem","position":4,"name":"PORTONES","item":"https:\/\/ducasseindustrial.com\/co\/product-category\/productos\/portones\/","nextItem":{"@type":"ListItem","@id":"https:\/\/ducasseindustrial.com\/co\/product-category\/productos\/portones\/accesorios-portones\/#listItem","name":"ACCESORIOS"},"previousItem":{"@type":"ListItem","@id":"https:\/\/ducasseindustrial.com\/co\/product-category\/productos\/#listItem","name":"Productos"}},{"@type":"ListItem","@id":"https:\/\/ducasseindustrial.com\/co\/product-category\/productos\/portones\/accesorios-portones\/#listItem","position":5,"name":"ACCESORIOS","item":"https:\/\/ducasseindustrial.com\/co\/product-category\/productos\/portones\/accesorios-portones\/","nextItem":{"@type":"ListItem","@id":"https:\/\/ducasseindustrial.com\/co\/product\/guia-pg-35\/#listItem","name":"GU\u00cdA PG 35"},"previousItem":{"@type":"ListItem","@id":"https:\/\/ducasseindustrial.com\/co\/product-category\/productos\/portones\/#listItem","name":"PORTONES"}},{"@type":"ListItem","@id":"https:\/\/ducasseindustrial.com\/co\/product\/guia-pg-35\/#listItem","position":6,"name":"GU\u00cdA PG 35","previousItem":{"@type":"ListItem","@id":"https:\/\/ducasseindustrial.com\/co\/product-category\/productos\/portones\/accesorios-portones\/#listItem","name":"ACCESORIOS"}}]},{"@type":"ItemPage","@id":"https:\/\/ducasseindustrial.com\/co\/product\/guia-pg-35\/#itempage","url":"https:\/\/ducasseindustrial.com\/co\/product\/guia-pg-35\/","name":"GU\u00cdA PG 35 | Ducasse Industrial S.A.","description":"Gu\u00eda inferior para portones colgantes. Fabricada en acero con cabezal de bronce de di\u00e1metro 35. Se puede fijar al port\u00f3n o al piso. Permite guiar el recorrido de un port\u00f3n colgante a trav\u00e9s de un canal inferior, asegurando la correcta funcionalidad de la hoja en apertura o cierre. Se puede usar en portones residenciales, comerciales","inLanguage":"es-CL","isPartOf":{"@id":"https:\/\/ducasseindustrial.com\/co\/#website"},"breadcrumb":{"@id":"https:\/\/ducasseindustrial.com\/co\/product\/guia-pg-35\/#breadcrumblist"},"image":{"@type":"ImageObject","url":"https:\/\/ducasseindustrial.com\/co\/wp-content\/uploads\/sites\/19\/2020\/11\/CO_10101105501_IMG_PROD1_BL.jpg","@id":"https:\/\/ducasseindustrial.com\/co\/product\/guia-pg-35\/#mainImage","width":1920,"height":1080},"primaryImageOfPage":{"@id":"https:\/\/ducasseindustrial.com\/co\/product\/guia-pg-35\/#mainImage"},"datePublished":"2020-11-10T07:08:59-04:00","dateModified":"2020-11-10T07:09:00-04:00"},{"@type":"Organization","@id":"https:\/\/ducasseindustrial.com\/co\/#organization","name":"Ducasse Industrial S.A.","description":"Somos una empresa Chilena, con m\u00e1s de 50 a\u00f1os de experiencia en la fabricaci\u00f3n de herrajes para la industria del mueble y la construcci\u00f3n, satisfaciendo necesidades tanto en mercados locales como extranjeros.","url":"https:\/\/ducasseindustrial.com\/co\/","logo":{"@type":"ImageObject","url":"https:\/\/ducasseindustrial.com\/co\/wp-content\/uploads\/sites\/19\/2024\/09\/logo_web_ducasse.svg","@id":"https:\/\/ducasseindustrial.com\/co\/product\/guia-pg-35\/#organizationLogo","width":1004,"height":294},"image":{"@id":"https:\/\/ducasseindustrial.com\/co\/product\/guia-pg-35\/#organizationLogo"}},{"@type":"WebSite","@id":"https:\/\/ducasseindustrial.com\/co\/#website","url":"https:\/\/ducasseindustrial.com\/co\/","name":"Ducasse Industrial S.A.","description":"Somos una empresa Chilena, con m\u00e1s de 50 a\u00f1os de experiencia en la fabricaci\u00f3n de herrajes para la industria del mueble y la construcci\u00f3n, satisfaciendo necesidades tanto en mercados locales como extranjeros.","inLanguage":"es-CL","publisher":{"@id":"https:\/\/ducasseindustrial.com\/co\/#organization"}}]},"og:locale":"es_ES","og:site_name":"Ducasse Industrial S.A. | Somos una empresa Chilena, con m\u00e1s de 50 a\u00f1os de experiencia en la fabricaci\u00f3n de herrajes para la industria del mueble y la construcci\u00f3n, satisfaciendo necesidades tanto en mercados locales como extranjeros.","og:type":"article","og:title":"GU\u00cdA PG 35 | Ducasse Industrial S.A.","og:description":"Gu\u00eda inferior para portones colgantes. Fabricada en acero con cabezal de bronce de di\u00e1metro 35. Se puede fijar al port\u00f3n o al piso. Permite guiar el recorrido de un port\u00f3n colgante a trav\u00e9s de un canal inferior, asegurando la correcta funcionalidad de la hoja en apertura o cierre. Se puede usar en portones residenciales, comerciales","og:url":"https:\/\/ducasseindustrial.com\/co\/product\/guia-pg-35\/","og:image":"https:\/\/ducasseindustrial.com\/co\/wp-content\/uploads\/sites\/19\/2024\/09\/logo_web_ducasse.svg","og:image:secure_url":"https:\/\/ducasseindustrial.com\/co\/wp-content\/uploads\/sites\/19\/2024\/09\/logo_web_ducasse.svg","article:published_time":"2020-11-10T11:08:59+00:00","article:modified_time":"2020-11-10T11:09:00+00:00","twitter:card":"summary","twitter:title":"GU\u00cdA PG 35 | Ducasse Industrial S.A.","twitter:description":"Gu\u00eda inferior para portones colgantes. Fabricada en acero con cabezal de bronce de di\u00e1metro 35. Se puede fijar al port\u00f3n o al piso. Permite guiar el recorrido de un port\u00f3n colgante a trav\u00e9s de un canal inferior, asegurando la correcta funcionalidad de la hoja en apertura o cierre. Se puede usar en portones residenciales, comerciales","twitter:image":"https:\/\/ducasseindustrial.com\/co\/wp-content\/uploads\/sites\/19\/2024\/09\/logo_web_ducasse.svg"},"aioseo_meta_data":{"post_id":"9676","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"ItemPage","isEnabled":true},"graphs":[]},"schema_type":null,"schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","priority":null,"frequency":null,"local_seo":null,"breadcrumb_settings":null,"limit_modified_date":false,"ai":null,"created":"2021-03-01 09:14:07","updated":"2025-11-01 01:03:39","focus_keyword":null,"additional_keywords":null,"truseo_locale":null,"seo_analyzer_scan_date":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/ducasseindustrial.com\/co\" title=\"Inicio\">Inicio<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/ducasseindustrial.com\/co\/shop-2\/\" title=\"Shop\">Shop<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/ducasseindustrial.com\/co\/product-category\/productos\/\" title=\"Productos\">Productos<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/ducasseindustrial.com\/co\/product-category\/productos\/portones\/\" title=\"PORTONES\">PORTONES<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/ducasseindustrial.com\/co\/product-category\/productos\/portones\/accesorios-portones\/\" title=\"ACCESORIOS\">ACCESORIOS<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tGU\u00cdA PG 35\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Inicio","link":"https:\/\/ducasseindustrial.com\/co"},{"label":"Shop","link":"https:\/\/ducasseindustrial.com\/co\/shop-2\/"},{"label":"Productos","link":"https:\/\/ducasseindustrial.com\/co\/product-category\/productos\/"},{"label":"PORTONES","link":"https:\/\/ducasseindustrial.com\/co\/product-category\/productos\/portones\/"},{"label":"ACCESORIOS","link":"https:\/\/ducasseindustrial.com\/co\/product-category\/productos\/portones\/accesorios-portones\/"},{"label":"GU\u00cdA PG 35","link":"https:\/\/ducasseindustrial.com\/co\/product\/guia-pg-35\/"}],"uagb_featured_image_src":{"full":["https:\/\/ducasseindustrial.com\/co\/wp-content\/uploads\/sites\/19\/2020\/11\/CO_10101105501_IMG_PROD1_BL.jpg",1920,1080,false],"thumbnail":["https:\/\/ducasseindustrial.com\/co\/wp-content\/uploads\/sites\/19\/2020\/11\/CO_10101105501_IMG_PROD1_BL-300x300.jpg",300,300,true],"medium":["https:\/\/ducasseindustrial.com\/co\/wp-content\/uploads\/sites\/19\/2020\/11\/CO_10101105501_IMG_PROD1_BL-600x338.jpg",600,338,true],"medium_large":["https:\/\/ducasseindustrial.com\/co\/wp-content\/uploads\/sites\/19\/2020\/11\/CO_10101105501_IMG_PROD1_BL-768x432.jpg",768,432,true],"large":["https:\/\/ducasseindustrial.com\/co\/wp-content\/uploads\/sites\/19\/2020\/11\/CO_10101105501_IMG_PROD1_BL-1024x576.jpg",1024,576,true],"1536x1536":["https:\/\/ducasseindustrial.com\/co\/wp-content\/uploads\/sites\/19\/2020\/11\/CO_10101105501_IMG_PROD1_BL-1536x864.jpg",1536,864,true],"2048x2048":["https:\/\/ducasseindustrial.com\/co\/wp-content\/uploads\/sites\/19\/2020\/11\/CO_10101105501_IMG_PROD1_BL.jpg",1920,1080,false],"vp_sm":["https:\/\/ducasseindustrial.com\/co\/wp-content\/uploads\/sites\/19\/2020\/11\/CO_10101105501_IMG_PROD1_BL-500x281.jpg",500,281,true],"vp_md":["https:\/\/ducasseindustrial.com\/co\/wp-content\/uploads\/sites\/19\/2020\/11\/CO_10101105501_IMG_PROD1_BL-800x450.jpg",800,450,true],"vp_lg":["https:\/\/ducasseindustrial.com\/co\/wp-content\/uploads\/sites\/19\/2020\/11\/CO_10101105501_IMG_PROD1_BL-1280x720.jpg",1280,720,true],"vp_xl":["https:\/\/ducasseindustrial.com\/co\/wp-content\/uploads\/sites\/19\/2020\/11\/CO_10101105501_IMG_PROD1_BL.jpg",1920,1080,false],"vp_sm_popup":["https:\/\/ducasseindustrial.com\/co\/wp-content\/uploads\/sites\/19\/2020\/11\/CO_10101105501_IMG_PROD1_BL-500x281.jpg",500,281,true],"vp_md_popup":["https:\/\/ducasseindustrial.com\/co\/wp-content\/uploads\/sites\/19\/2020\/11\/CO_10101105501_IMG_PROD1_BL-800x450.jpg",800,450,true],"vp_xl_popup":["https:\/\/ducasseindustrial.com\/co\/wp-content\/uploads\/sites\/19\/2020\/11\/CO_10101105501_IMG_PROD1_BL.jpg",1920,1080,false],"woocommerce_thumbnail":["https:\/\/ducasseindustrial.com\/co\/wp-content\/uploads\/sites\/19\/2020\/11\/CO_10101105501_IMG_PROD1_BL-300x300.jpg",300,300,true],"woocommerce_single":["https:\/\/ducasseindustrial.com\/co\/wp-content\/uploads\/sites\/19\/2020\/11\/CO_10101105501_IMG_PROD1_BL-1024x576.jpg",1024,576,true],"woocommerce_gallery_thumbnail":["https:\/\/ducasseindustrial.com\/co\/wp-content\/uploads\/sites\/19\/2020\/11\/CO_10101105501_IMG_PROD1_BL-100x100.jpg",100,100,true],"variation_swatches_image_size":["https:\/\/ducasseindustrial.com\/co\/wp-content\/uploads\/sites\/19\/2020\/11\/CO_10101105501_IMG_PROD1_BL.jpg",50,28,false],"variation_swatches_tooltip_size":["https:\/\/ducasseindustrial.com\/co\/wp-content\/uploads\/sites\/19\/2020\/11\/CO_10101105501_IMG_PROD1_BL.jpg",100,56,false]},"uagb_author_info":{"display_name":"user","author_link":"https:\/\/ducasseindustrial.com\/co\/author\/"},"uagb_comment_info":0,"uagb_excerpt":"Gu\u00eda inferior para portones colgantes. Fabricada en acero con cabezal de bronce de di\u00e1metro 35. Se puede fijar al port\u00f3n o al piso. Permite guiar el recorrido de un port\u00f3n colgante a trav\u00e9s de un canal inferior, asegurando la correcta funcionalidad de la hoja en apertura o cierre. Se puede usar en portones residenciales, comerciales&hellip;","_links":{"self":[{"href":"https:\/\/ducasseindustrial.com\/co\/wp-json\/wp\/v2\/product\/9676","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ducasseindustrial.com\/co\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/ducasseindustrial.com\/co\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/ducasseindustrial.com\/co\/wp-json\/wp\/v2\/comments?post=9676"}],"version-history":[{"count":1,"href":"https:\/\/ducasseindustrial.com\/co\/wp-json\/wp\/v2\/product\/9676\/revisions"}],"predecessor-version":[{"id":9677,"href":"https:\/\/ducasseindustrial.com\/co\/wp-json\/wp\/v2\/product\/9676\/revisions\/9677"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ducasseindustrial.com\/co\/wp-json\/wp\/v2\/media\/9679"}],"wp:attachment":[{"href":"https:\/\/ducasseindustrial.com\/co\/wp-json\/wp\/v2\/media?parent=9676"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/ducasseindustrial.com\/co\/wp-json\/wp\/v2\/product_brand?post=9676"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/ducasseindustrial.com\/co\/wp-json\/wp\/v2\/product_cat?post=9676"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/ducasseindustrial.com\/co\/wp-json\/wp\/v2\/product_tag?post=9676"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}