{"id":256,"count":0,"description":"","link":"https:\/\/ducasseindustrial.com\/co\/product-category\/productos\/muebles-y-cajones\/rieles-muebles-y-cajones\/","name":"RIELES","slug":"rieles-muebles-y-cajones","taxonomy":"product_cat","parent":235,"meta":[],"aioseo_head":"\n\t\t<!-- All in One SEO 5.0.0.1 - aioseo.com -->\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/ducasseindustrial.com\/co\/product-category\/productos\/muebles-y-cajones\/rieles-muebles-y-cajones\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 5.0.0.1\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/ducasseindustrial.com\\\/co\\\/wp-json\\\/wp\\\/v2\\\/product_cat\\\/256\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ducasseindustrial.com\\\/co#listItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\\\/\\\/ducasseindustrial.com\\\/co\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ducasseindustrial.com\\\/co\\\/shop-2\\\/#listItem\",\"name\":\"Shop\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ducasseindustrial.com\\\/co\\\/shop-2\\\/#listItem\",\"position\":2,\"name\":\"Shop\",\"item\":\"https:\\\/\\\/ducasseindustrial.com\\\/co\\\/shop-2\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ducasseindustrial.com\\\/co\\\/product-category\\\/productos\\\/#listItem\",\"name\":\"Productos\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ducasseindustrial.com\\\/co#listItem\",\"name\":\"Inicio\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ducasseindustrial.com\\\/co\\\/product-category\\\/productos\\\/#listItem\",\"position\":3,\"name\":\"Productos\",\"item\":\"https:\\\/\\\/ducasseindustrial.com\\\/co\\\/product-category\\\/productos\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ducasseindustrial.com\\\/co\\\/product-category\\\/productos\\\/muebles-y-cajones\\\/#listItem\",\"name\":\"MUEBLES Y CAJONES\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ducasseindustrial.com\\\/co\\\/shop-2\\\/#listItem\",\"name\":\"Shop\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ducasseindustrial.com\\\/co\\\/product-category\\\/productos\\\/muebles-y-cajones\\\/#listItem\",\"position\":4,\"name\":\"MUEBLES Y CAJONES\",\"item\":\"https:\\\/\\\/ducasseindustrial.com\\\/co\\\/product-category\\\/productos\\\/muebles-y-cajones\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ducasseindustrial.com\\\/co\\\/product-category\\\/productos\\\/muebles-y-cajones\\\/rieles-muebles-y-cajones\\\/#listItem\",\"name\":\"RIELES\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ducasseindustrial.com\\\/co\\\/product-category\\\/productos\\\/#listItem\",\"name\":\"Productos\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ducasseindustrial.com\\\/co\\\/product-category\\\/productos\\\/muebles-y-cajones\\\/rieles-muebles-y-cajones\\\/#listItem\",\"position\":5,\"name\":\"RIELES\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ducasseindustrial.com\\\/co\\\/product-category\\\/productos\\\/muebles-y-cajones\\\/#listItem\",\"name\":\"MUEBLES Y CAJONES\"}}]},{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/ducasseindustrial.com\\\/co\\\/wp-json\\\/wp\\\/v2\\\/product_cat\\\/256\\\/#collectionpage\",\"url\":\"https:\\\/\\\/ducasseindustrial.com\\\/co\\\/wp-json\\\/wp\\\/v2\\\/product_cat\\\/256\\\/#collectionpage\",\"name\":\"RIELES | Ducasse Industrial S.A.\",\"inLanguage\":\"es-CL\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/ducasseindustrial.com\\\/co\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/ducasseindustrial.com\\\/co\\\/wp-json\\\/wp\\\/v2\\\/product_cat\\\/256\\\/#collectionpage\"}},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/ducasseindustrial.com\\\/co\\\/#organization\",\"name\":\"Ducasse Industrial S.A.\",\"description\":\"Somos una empresa Chilena, con m\\u00e1s de 50 a\\u00f1os de experiencia en la fabricaci\\u00f3n de herrajes para la industria del mueble y la construcci\\u00f3n, satisfaciendo necesidades tanto en mercados locales como extranjeros.\",\"url\":\"https:\\\/\\\/ducasseindustrial.com\\\/co\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/ducasseindustrial.com\\\/co\\\/wp-content\\\/uploads\\\/sites\\\/19\\\/2024\\\/09\\\/logo_web_ducasse.svg\",\"@id\":\"https:\\\/\\\/ducasseindustrial.com\\\/co\\\/wp-json\\\/wp\\\/v2\\\/product_cat\\\/256\\\/#organizationLogo\",\"width\":1004,\"height\":294},\"image\":{\"@id\":\"https:\\\/\\\/ducasseindustrial.com\\\/co\\\/wp-json\\\/wp\\\/v2\\\/product_cat\\\/256\\\/#organizationLogo\"}},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/ducasseindustrial.com\\\/co\\\/#website\",\"url\":\"https:\\\/\\\/ducasseindustrial.com\\\/co\\\/\",\"name\":\"Ducasse Industrial S.A.\",\"description\":\"Somos una empresa Chilena, con m\\u00e1s de 50 a\\u00f1os de experiencia en la fabricaci\\u00f3n de herrajes para la industria del mueble y la construcci\\u00f3n, satisfaciendo necesidades tanto en mercados locales como extranjeros.\",\"inLanguage\":\"es-CL\",\"publisher\":{\"@id\":\"https:\\\/\\\/ducasseindustrial.com\\\/co\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"RIELES | Ducasse Industrial S.A.","description":"","canonical_url":"https:\/\/ducasseindustrial.com\/co\/product-category\/productos\/muebles-y-cajones\/rieles-muebles-y-cajones\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BreadcrumbList","@id":"https:\/\/ducasseindustrial.com\/co\/wp-json\/wp\/v2\/product_cat\/256\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/ducasseindustrial.com\/co#listItem","position":1,"name":"Inicio","item":"https:\/\/ducasseindustrial.com\/co","nextItem":{"@type":"ListItem","@id":"https:\/\/ducasseindustrial.com\/co\/shop-2\/#listItem","name":"Shop"}},{"@type":"ListItem","@id":"https:\/\/ducasseindustrial.com\/co\/shop-2\/#listItem","position":2,"name":"Shop","item":"https:\/\/ducasseindustrial.com\/co\/shop-2\/","nextItem":{"@type":"ListItem","@id":"https:\/\/ducasseindustrial.com\/co\/product-category\/productos\/#listItem","name":"Productos"},"previousItem":{"@type":"ListItem","@id":"https:\/\/ducasseindustrial.com\/co#listItem","name":"Inicio"}},{"@type":"ListItem","@id":"https:\/\/ducasseindustrial.com\/co\/product-category\/productos\/#listItem","position":3,"name":"Productos","item":"https:\/\/ducasseindustrial.com\/co\/product-category\/productos\/","nextItem":{"@type":"ListItem","@id":"https:\/\/ducasseindustrial.com\/co\/product-category\/productos\/muebles-y-cajones\/#listItem","name":"MUEBLES Y CAJONES"},"previousItem":{"@type":"ListItem","@id":"https:\/\/ducasseindustrial.com\/co\/shop-2\/#listItem","name":"Shop"}},{"@type":"ListItem","@id":"https:\/\/ducasseindustrial.com\/co\/product-category\/productos\/muebles-y-cajones\/#listItem","position":4,"name":"MUEBLES Y CAJONES","item":"https:\/\/ducasseindustrial.com\/co\/product-category\/productos\/muebles-y-cajones\/","nextItem":{"@type":"ListItem","@id":"https:\/\/ducasseindustrial.com\/co\/product-category\/productos\/muebles-y-cajones\/rieles-muebles-y-cajones\/#listItem","name":"RIELES"},"previousItem":{"@type":"ListItem","@id":"https:\/\/ducasseindustrial.com\/co\/product-category\/productos\/#listItem","name":"Productos"}},{"@type":"ListItem","@id":"https:\/\/ducasseindustrial.com\/co\/product-category\/productos\/muebles-y-cajones\/rieles-muebles-y-cajones\/#listItem","position":5,"name":"RIELES","previousItem":{"@type":"ListItem","@id":"https:\/\/ducasseindustrial.com\/co\/product-category\/productos\/muebles-y-cajones\/#listItem","name":"MUEBLES Y CAJONES"}}]},{"@type":"CollectionPage","@id":"https:\/\/ducasseindustrial.com\/co\/wp-json\/wp\/v2\/product_cat\/256\/#collectionpage","url":"https:\/\/ducasseindustrial.com\/co\/wp-json\/wp\/v2\/product_cat\/256\/#collectionpage","name":"RIELES | Ducasse Industrial S.A.","inLanguage":"es-CL","isPartOf":{"@id":"https:\/\/ducasseindustrial.com\/co\/#website"},"breadcrumb":{"@id":"https:\/\/ducasseindustrial.com\/co\/wp-json\/wp\/v2\/product_cat\/256\/#collectionpage"}},{"@type":"Organization","@id":"https:\/\/ducasseindustrial.com\/co\/#organization","name":"Ducasse Industrial S.A.","description":"Somos una empresa Chilena, con m\u00e1s de 50 a\u00f1os de experiencia en la fabricaci\u00f3n de herrajes para la industria del mueble y la construcci\u00f3n, satisfaciendo necesidades tanto en mercados locales como extranjeros.","url":"https:\/\/ducasseindustrial.com\/co\/","logo":{"@type":"ImageObject","url":"https:\/\/ducasseindustrial.com\/co\/wp-content\/uploads\/sites\/19\/2024\/09\/logo_web_ducasse.svg","@id":"https:\/\/ducasseindustrial.com\/co\/wp-json\/wp\/v2\/product_cat\/256\/#organizationLogo","width":1004,"height":294},"image":{"@id":"https:\/\/ducasseindustrial.com\/co\/wp-json\/wp\/v2\/product_cat\/256\/#organizationLogo"}},{"@type":"WebSite","@id":"https:\/\/ducasseindustrial.com\/co\/#website","url":"https:\/\/ducasseindustrial.com\/co\/","name":"Ducasse Industrial S.A.","description":"Somos una empresa Chilena, con m\u00e1s de 50 a\u00f1os de experiencia en la fabricaci\u00f3n de herrajes para la industria del mueble y la construcci\u00f3n, satisfaciendo necesidades tanto en mercados locales como extranjeros.","inLanguage":"es-CL","publisher":{"@id":"https:\/\/ducasseindustrial.com\/co\/#organization"}}]}},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/ducasseindustrial.com\/co\" title=\"Inicio\">Inicio<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/ducasseindustrial.com\/co\/shop-2\/\" title=\"Shop\">Shop<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/ducasseindustrial.com\/co\/product-category\/productos\/\" title=\"Productos\">Productos<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/ducasseindustrial.com\/co\/product-category\/productos\/muebles-y-cajones\/\" title=\"MUEBLES Y CAJONES\">MUEBLES Y CAJONES<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tRIELES\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Inicio","link":"https:\/\/ducasseindustrial.com\/co"},{"label":"Shop","link":"https:\/\/ducasseindustrial.com\/co\/shop-2\/"},{"label":"Productos","link":"https:\/\/ducasseindustrial.com\/co\/product-category\/productos\/"},{"label":"MUEBLES Y CAJONES","link":"https:\/\/ducasseindustrial.com\/co\/product-category\/productos\/muebles-y-cajones\/"},{"label":"RIELES","link":"https:\/\/ducasseindustrial.com\/co\/product-category\/productos\/muebles-y-cajones\/rieles-muebles-y-cajones\/"}],"_links":{"self":[{"href":"https:\/\/ducasseindustrial.com\/co\/wp-json\/wp\/v2\/product_cat\/256","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ducasseindustrial.com\/co\/wp-json\/wp\/v2\/product_cat"}],"about":[{"href":"https:\/\/ducasseindustrial.com\/co\/wp-json\/wp\/v2\/taxonomies\/product_cat"}],"up":[{"embeddable":true,"href":"https:\/\/ducasseindustrial.com\/co\/wp-json\/wp\/v2\/product_cat\/235"}],"wp:post_type":[{"href":"https:\/\/ducasseindustrial.com\/co\/wp-json\/wp\/v2\/product?product_cat=256"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}