{"id":18406,"date":"2020-10-29T11:53:13","date_gmt":"2020-10-29T15:53:13","guid":{"rendered":"https:\/\/ducasseindustrial.com\/testcl\/ar\/?page_id=18406"},"modified":"2020-11-12T11:19:24","modified_gmt":"2020-11-12T15:19:24","slug":"espacios-educativos","status":"publish","type":"page","link":"https:\/\/ducasseindustrial.com\/testcl\/arquitectura\/espacios-educativos","title":{"rendered":"Espacios Educativos"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"18406\" class=\"elementor elementor-18406\" data-elementor-post-type=\"page\">\n\t\t\t\t\t\t<section data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-section elementor-top-section elementor-element elementor-element-5fd3a70a elementor-section-height-min-height elementor-section-boxed elementor-section-height-default elementor-section-items-middle\" data-id=\"5fd3a70a\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-70e05ea0\" data-id=\"70e05ea0\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-section elementor-top-section elementor-element elementor-element-8a453c7 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"8a453c7\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-42327e6\" data-id=\"42327e6\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-6f85961 elementor-widget elementor-widget-shortcode\" data-id=\"6f85961\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"shortcode.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-shortcode\">\t\t<div data-elementor-type=\"archive\" data-elementor-id=\"19940\" class=\"elementor elementor-19940\" data-elementor-post-type=\"elementor_library\">\n\t\t\t\t\t<section data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-section elementor-inner-section elementor-element elementor-element-ca1dfdd elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"ca1dfdd\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-68cc1118\" data-id=\"68cc1118\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-114e4b55 elementor-widget__width-initial elementor-hidden-phone eael_advanced_menu_hamburger_disable_selected_menu_no eael-advanced-menu-hamburger-align-right eael-advanced-menu--no eael-hamburger--tablet elementor-widget elementor-widget-eael-advanced-menu\" data-id=\"114e4b55\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"eael-advanced-menu.skin-two\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<style>\n                        @media screen and (max-width: 1024px) {\n                            .eael-hamburger--tablet {\n                                .eael-advanced-menu-horizontal,\n                                .eael-advanced-menu-vertical {\n                                    display: none;\n                                }\n                            }\n                            .eael-hamburger--tablet {\n                                .eael-advanced-menu-container .eael-advanced-menu-toggle {\n                                    display: block;\n                                }\n                            }\n                        }\n                    <\/style>            <div data-hamburger-icon=\"&lt;i aria-hidden=&quot;true&quot; class=&quot;fas fa-bars&quot;&gt;&lt;\/i&gt;\" data-indicator-class=\"&lt;i aria-hidden=&quot;true&quot; class=&quot;fas fa-angle-down&quot;&gt;&lt;\/i&gt;\" data-dropdown-indicator-class=\"&lt;i aria-hidden=&quot;true&quot; class=&quot;fas fa-angle-down&quot;&gt;&lt;\/i&gt;\" class=\"eael-advanced-menu-container eael-advanced-menu-align-left eael-advanced-menu-dropdown-align-left\" data-hamburger-breakpoints=\"{&quot;mobile&quot;:&quot;M\\u00f3vil vertical (&gt; 767px)&quot;,&quot;tablet&quot;:&quot;Tableta vertical (&gt; 1024px)&quot;,&quot;desktop&quot;:&quot;Desktop (&gt; 2400px)&quot;,&quot;none&quot;:&quot;None&quot;}\" data-hamburger-device=\"tablet\">\n                <ul id=\"menu-arquitectura\" class=\"eael-advanced-menu eael-advanced-menu-dropdown-animate-zoom-in eael-advanced-menu-indicator eael-advanced-menu-vertical\"><li id=\"menu-item-19381\" class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-19381\"><a href=\"https:\/\/ducasseindustrial.com\/testcl\/arquitectura\" class=\"menu-link\">Arquitectura<\/a><\/li>\n<li id=\"menu-item-2935\" class=\"menu-item menu-item-type-custom menu-item-object-custom menu-item-has-children menu-item-2935\"><a aria-expanded=\"false\" href=\"#\" class=\"menu-link\">soluciones<\/a>\n<ul class=\"sub-menu\">\n\t<li id=\"menu-item-19394\" class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-19394\"><a href=\"https:\/\/ducasseindustrial.com\/testcl\/arquitectura\/quinchos-y-galerias\" class=\"menu-link\">quinchos y galer\u00edas<\/a><\/li>\n\t<li id=\"menu-item-19384\" class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-19384\"><a href=\"https:\/\/ducasseindustrial.com\/testcl\/arquitectura\/division-de-ambientes\" class=\"menu-link\">divisi\u00f3n de ambientes<\/a><\/li>\n\t<li id=\"menu-item-19392\" class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-19392\"><a href=\"https:\/\/ducasseindustrial.com\/testcl\/arquitectura\/puertas-de-paso\" class=\"menu-link\">Puertas de paso<\/a><\/li>\n\t<li id=\"menu-item-19385\" class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-19385\"><a href=\"https:\/\/ducasseindustrial.com\/testcl\/arquitectura\/espacios-corporativos\" class=\"menu-link\">Espacios Corporativos<\/a><\/li>\n\t<li id=\"menu-item-19393\" class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-19393\"><a href=\"https:\/\/ducasseindustrial.com\/testcl\/arquitectura\/soluciones-bancarias\" class=\"menu-link\">Soluciones Bancarias<\/a><\/li>\n\t<li id=\"menu-item-19383\" class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-19383\"><a href=\"https:\/\/ducasseindustrial.com\/testcl\/arquitectura\/arquitectura-hospitalaria\" class=\"menu-link\">Arquitectura Hospitalaria<\/a><\/li>\n\t<li id=\"menu-item-19387\" class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-19387\"><a href=\"https:\/\/ducasseindustrial.com\/testcl\/arquitectura\/espacios-educativos\" class=\"menu-link\">Espacios Educativos<\/a><\/li>\n\t<li id=\"menu-item-19389\" class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-19389\"><a href=\"https:\/\/ducasseindustrial.com\/testcl\/arquitectura\/frentes-comerciales\" class=\"menu-link\">Frentes Comerciales<\/a><\/li>\n\t<li id=\"menu-item-19395\" class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-19395\"><a href=\"https:\/\/ducasseindustrial.com\/testcl\/arquitectura\/usos-multiples\" class=\"menu-link\">Usos M\u00faltiples<\/a><\/li>\n\t<li id=\"menu-item-19391\" class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-19391\"><a href=\"https:\/\/ducasseindustrial.com\/testcl\/arquitectura\/parasoles\" class=\"menu-link\">Parasoles<\/a><\/li>\n\t<li id=\"menu-item-19390\" class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-19390\"><a href=\"https:\/\/ducasseindustrial.com\/testcl\/arquitectura\/hoteleria\" class=\"menu-link\">Hoteler\u00eda<\/a><\/li>\n\t<li id=\"menu-item-19382\" class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-19382\"><a href=\"https:\/\/ducasseindustrial.com\/testcl\/arquitectura\/arquitectura-deportiva\" class=\"menu-link\">Arquitectura Deportiva<\/a><\/li>\n\t<li id=\"menu-item-19386\" class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-19386\"><a href=\"https:\/\/ducasseindustrial.com\/testcl\/arquitectura\/espacios-culturales\" class=\"menu-link\">Espacios Culturales<\/a><\/li>\n<\/ul>\n<\/li>\n<li id=\"menu-item-19388\" class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-19388\"><a href=\"https:\/\/ducasseindustrial.com\/testcl\/arquitectura\/faqs\" class=\"menu-link\">FAQs<\/a><\/li>\n<\/ul>                <button class=\"eael-advanced-menu-toggle\" aria-label=\"Essential Addons Toggle Menu\">\n                    <i aria-hidden=\"true\" class=\"fas fa-bars\"><\/i>                <\/button>\n            <\/div>\n            \t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-266d8a56 elementor-widget__width-initial elementor-hidden-desktop elementor-hidden-tablet eael_advanced_menu_hamburger_disable_selected_menu_no eael-advanced-menu-hamburger-align-right eael-advanced-menu--no eael-hamburger--tablet elementor-widget elementor-widget-eael-advanced-menu\" data-id=\"266d8a56\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"eael-advanced-menu.skin-two\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<style>\n                        @media screen and (max-width: 1024px) {\n                            .eael-hamburger--tablet {\n                                .eael-advanced-menu-horizontal,\n                                .eael-advanced-menu-vertical {\n                                    display: none;\n                                }\n                            }\n                            .eael-hamburger--tablet {\n                                .eael-advanced-menu-container .eael-advanced-menu-toggle {\n                                    display: block;\n                                }\n                            }\n                        }\n                    <\/style>            <div data-hamburger-icon=\"&lt;i aria-hidden=&quot;true&quot; class=&quot;fas fa-bars&quot;&gt;&lt;\/i&gt;\" data-indicator-class=\"&lt;i aria-hidden=&quot;true&quot; class=&quot;fas fa-angle-down&quot;&gt;&lt;\/i&gt;\" data-dropdown-indicator-class=\"&lt;i aria-hidden=&quot;true&quot; class=&quot;fas fa-angle-down&quot;&gt;&lt;\/i&gt;\" class=\"eael-advanced-menu-container eael-advanced-menu-align-center eael-advanced-menu-dropdown-align-left\" data-hamburger-breakpoints=\"{&quot;mobile&quot;:&quot;M\\u00f3vil vertical (&gt; 767px)&quot;,&quot;tablet&quot;:&quot;Tableta vertical (&gt; 1024px)&quot;,&quot;desktop&quot;:&quot;Desktop (&gt; 2400px)&quot;,&quot;none&quot;:&quot;None&quot;}\" data-hamburger-device=\"tablet\">\n                <ul id=\"menu-arquitectura-1\" class=\"eael-advanced-menu eael-advanced-menu-dropdown-animate-zoom-in eael-advanced-menu-indicator eael-advanced-menu-vertical\"><li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-19381\"><a href=\"https:\/\/ducasseindustrial.com\/testcl\/arquitectura\" class=\"menu-link\">Arquitectura<\/a><\/li>\n<li class=\"menu-item menu-item-type-custom menu-item-object-custom menu-item-has-children menu-item-2935\"><a aria-expanded=\"false\" href=\"#\" class=\"menu-link\">soluciones<\/a>\n<ul class=\"sub-menu\">\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-19394\"><a href=\"https:\/\/ducasseindustrial.com\/testcl\/arquitectura\/quinchos-y-galerias\" class=\"menu-link\">quinchos y galer\u00edas<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-19384\"><a href=\"https:\/\/ducasseindustrial.com\/testcl\/arquitectura\/division-de-ambientes\" class=\"menu-link\">divisi\u00f3n de ambientes<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-19392\"><a href=\"https:\/\/ducasseindustrial.com\/testcl\/arquitectura\/puertas-de-paso\" class=\"menu-link\">Puertas de paso<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-19385\"><a href=\"https:\/\/ducasseindustrial.com\/testcl\/arquitectura\/espacios-corporativos\" class=\"menu-link\">Espacios Corporativos<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-19393\"><a href=\"https:\/\/ducasseindustrial.com\/testcl\/arquitectura\/soluciones-bancarias\" class=\"menu-link\">Soluciones Bancarias<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-19383\"><a href=\"https:\/\/ducasseindustrial.com\/testcl\/arquitectura\/arquitectura-hospitalaria\" class=\"menu-link\">Arquitectura Hospitalaria<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-19387\"><a href=\"https:\/\/ducasseindustrial.com\/testcl\/arquitectura\/espacios-educativos\" class=\"menu-link\">Espacios Educativos<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-19389\"><a href=\"https:\/\/ducasseindustrial.com\/testcl\/arquitectura\/frentes-comerciales\" class=\"menu-link\">Frentes Comerciales<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-19395\"><a href=\"https:\/\/ducasseindustrial.com\/testcl\/arquitectura\/usos-multiples\" class=\"menu-link\">Usos M\u00faltiples<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-19391\"><a href=\"https:\/\/ducasseindustrial.com\/testcl\/arquitectura\/parasoles\" class=\"menu-link\">Parasoles<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-19390\"><a href=\"https:\/\/ducasseindustrial.com\/testcl\/arquitectura\/hoteleria\" class=\"menu-link\">Hoteler\u00eda<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-19382\"><a href=\"https:\/\/ducasseindustrial.com\/testcl\/arquitectura\/arquitectura-deportiva\" class=\"menu-link\">Arquitectura Deportiva<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-19386\"><a href=\"https:\/\/ducasseindustrial.com\/testcl\/arquitectura\/espacios-culturales\" class=\"menu-link\">Espacios Culturales<\/a><\/li>\n<\/ul>\n<\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-19388\"><a href=\"https:\/\/ducasseindustrial.com\/testcl\/arquitectura\/faqs\" class=\"menu-link\">FAQs<\/a><\/li>\n<\/ul>                <button class=\"eael-advanced-menu-toggle\" aria-label=\"Essential Addons Toggle Menu\">\n                    <i aria-hidden=\"true\" class=\"fas fa-bars\"><\/i>                <\/button>\n            <\/div>\n            \t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-section elementor-inner-section elementor-element elementor-element-12e18af5 elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"12e18af5\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-3fc32064\" data-id=\"3fc32064\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-2cd0fc12 eael-dual-header-content-mobile-align-center elementor-widget elementor-widget-eael-dual-color-header\" data-id=\"2cd0fc12\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"eael-dual-color-header.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t<div class=\"eael-dual-header\">\n\t\t\t\t<span class=\"title eael-dch-title\"><span class=\"eael-dch-title-text eael-dch-title-lead lead solid-color\">\u00bfNecesit\u00e1s<\/span> <span class=\"eael-dch-title-text\">asesoramiento?<\/span><\/span>\t\t\t<\/div>\n\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4c22d574 elementor-button-align-start elementor-mobile-button-align-center elementor-widget elementor-widget-form\" data-id=\"4c22d574\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;step_next_label&quot;:&quot;Seguir&quot;,&quot;step_previous_label&quot;:&quot;Volver&quot;,&quot;button_width&quot;:&quot;50&quot;,&quot;step_type&quot;:&quot;number&quot;,&quot;step_icon_shape&quot;:&quot;circle&quot;}\" data-widget_type=\"form.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<form class=\"elementor-form\" method=\"post\" name=\"Arquitectura \" aria-label=\"Arquitectura \">\n\t\t\t<input type=\"hidden\" name=\"post_id\" value=\"19940\"\/>\n\t\t\t<input type=\"hidden\" name=\"form_id\" value=\"4c22d574\"\/>\n\t\t\t<input type=\"hidden\" name=\"referer_title\" value=\"Casa CG. | Test Chile\" \/>\n\n\t\t\t\t\t\t\t<input type=\"hidden\" name=\"queried_id\" value=\"19326\"\/>\n\t\t\t\n\t\t\t<div class=\"elementor-form-fields-wrapper elementor-labels-above\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-type-step elementor-field-group elementor-column elementor-field-group-field_46f88d1 elementor-col-100\">\n\t\t\t\t\t\t\t<div class=\"e-field-step elementor-hidden\" data-label=\"\" data-previousButton=\"\" data-nextButton=\"\" data-iconUrl=\"\" data-iconLibrary=\"fas fa-star\" data-icon=\"\" ><\/div>\n\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-type-text elementor-field-group elementor-column elementor-field-group-field_40b0d8d elementor-col-100 elementor-field-required elementor-mark-required\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<input size=\"1\" type=\"text\" name=\"form_fields[field_40b0d8d]\" id=\"form-field-field_40b0d8d\" class=\"elementor-field elementor-size-xs  elementor-field-textual\" placeholder=\"Nombre\" required=\"required\">\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-type-email elementor-field-group elementor-column elementor-field-group-email elementor-col-100 elementor-field-required elementor-mark-required\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<input size=\"1\" type=\"email\" name=\"form_fields[email]\" id=\"form-field-email\" class=\"elementor-field elementor-size-xs  elementor-field-textual\" placeholder=\"Email\" required=\"required\">\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-type-tel elementor-field-group elementor-column elementor-field-group-field_dcc9d34 elementor-col-100 elementor-field-required elementor-mark-required\">\n\t\t\t\t\t\t\t<input size=\"1\" type=\"tel\" name=\"form_fields[field_dcc9d34]\" id=\"form-field-field_dcc9d34\" class=\"elementor-field elementor-size-xs  elementor-field-textual\" placeholder=\"Tel\u00e9fono\" required=\"required\" pattern=\"[0-9()#&amp;+*-=.]+\" title=\"Only numbers and phone characters (#, -, *, etc) are accepted.\">\n\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-type-step elementor-field-group elementor-column elementor-field-group-field_15d101f elementor-col-100\">\n\t\t\t\t\t\t\t<div class=\"e-field-step elementor-hidden\" data-label=\"\" data-previousButton=\"\" data-nextButton=\"\" data-iconUrl=\"\" data-iconLibrary=\"fas fa-star\" data-icon=\"\" ><\/div>\n\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-type-select elementor-field-group elementor-column elementor-field-group-field_8fa11e1 elementor-col-100\">\n\t\t\t\t\t\t\t\t\t\t\t\t<label for=\"form-field-field_8fa11e1\" class=\"elementor-field-label\">\n\t\t\t\t\t\t\t\tTipo de emrpesa\t\t\t\t\t\t\t<\/label>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field elementor-select-wrapper remove-before \">\n\t\t\t<div class=\"select-caret-down-wrapper\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"eicon-caret-down\"><\/i>\t\t\t<\/div>\n\t\t\t<select name=\"form_fields[field_8fa11e1]\" id=\"form-field-field_8fa11e1\" class=\"elementor-field-textual elementor-size-xs\">\n\t\t\t\t\t\t\t\t\t<option value=\"Elija una opci\u00f3n -- - - &gt;\">Elija una opci\u00f3n -- - - &gt;<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"Estudio de Arquitectura\/Arquitecto\">Estudio de Arquitectura\/Arquitecto<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"Constructora \">Constructora <\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"Carpinter\u00eda de obra\/ Vidrier\u00eda\">Carpinter\u00eda de obra\/ Vidrier\u00eda<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"Carpinter\u00eda de obra\/ Madera\">Carpinter\u00eda de obra\/ Madera<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"Usuario final\">Usuario final<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"Otro\">Otro<\/option>\n\t\t\t\t\t\t\t<\/select>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-type-select elementor-field-group elementor-column elementor-field-group-field_3e7ed83 elementor-col-100\">\n\t\t\t\t\t\t\t\t\t\t\t\t<label for=\"form-field-field_3e7ed83\" class=\"elementor-field-label\">\n\t\t\t\t\t\t\t\t\u00bfC\u00f3mo nos conoci\u00f3?\t\t\t\t\t\t\t<\/label>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field elementor-select-wrapper remove-before \">\n\t\t\t<div class=\"select-caret-down-wrapper\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"eicon-caret-down\"><\/i>\t\t\t<\/div>\n\t\t\t<select name=\"form_fields[field_3e7ed83]\" id=\"form-field-field_3e7ed83\" class=\"elementor-field-textual elementor-size-xs\">\n\t\t\t\t\t\t\t\t\t<option value=\"Elija una opci\u00f3n -- - - &gt;\">Elija una opci\u00f3n -- - - &gt;<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"Google\">Google<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"Revista LIVING\">Revista LIVING<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"Otras Revista\">Otras Revista<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"Recomendaci\u00f3n\">Recomendaci\u00f3n<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"Redes sociales\">Redes sociales<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"Otro\">Otro<\/option>\n\t\t\t\t\t\t\t<\/select>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-type-step elementor-field-group elementor-column elementor-field-group-field_f625ad2 elementor-col-100\">\n\t\t\t\t\t\t\t<div class=\"e-field-step elementor-hidden\" data-label=\"\" data-previousButton=\"\" data-nextButton=\"\" data-iconUrl=\"\" data-iconLibrary=\"fas fa-star\" data-icon=\"\" ><\/div>\n\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-type-textarea elementor-field-group elementor-column elementor-field-group-field_023cbb7 elementor-col-100 elementor-field-required elementor-mark-required\">\n\t\t\t\t\t<textarea class=\"elementor-field-textual elementor-field  elementor-size-xs\" name=\"form_fields[field_023cbb7]\" id=\"form-field-field_023cbb7\" rows=\"4\" placeholder=\"Mensaje\" required=\"required\"><\/textarea>\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-group elementor-column elementor-field-type-submit elementor-col-50 e-form__buttons\">\n\t\t\t\t\t<button class=\"elementor-button elementor-size-md\" type=\"submit\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Enviar<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/button>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/form>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-b9e140c\" data-id=\"b9e140c\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;motion_fx_motion_fx_mouse&quot;:&quot;yes&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-04777d0 elementor-widget elementor-widget-heading\" data-id=\"04777d0\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h1 class=\"elementor-heading-title elementor-size-default\">Espacios Educativos<\/h1>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2f14d6d elementor-widget elementor-widget-heading\" data-id=\"2f14d6d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Sistemas corredizos para adaptar espacios educativos<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c10a3e4 elementor-invisible elementor-widget elementor-widget-text-editor\" data-id=\"c10a3e4\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInUp&quot;,&quot;_animation_delay&quot;:50}\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Configurar espacios educativos a partir de sistemas corredizos de vidrio o madera permite adaptar el entorno en un ambiente visualmente agradable. El uso de estos sistemas hace que los recintos puedan transformarse de manera muy simple y \u00e1gil, considerando la ultima tecnolog\u00eda utilizada en los sistemas para deslizamiento.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-0f5a262 elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"0f5a262\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-check\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Posibilidad de cubrir grandes luces permitiendo apertura total del vano.<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-check\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Versatilidad para la configuraci\u00f3n de espacio<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-check\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\"> Puede utilizarse con perfiler\u00eda met\u00e1lica y\/o paneles ac\u00fasticos.<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-check\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Est\u00e9tica muy cuidada que convive con el espacio.<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-check\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Excelente relaci\u00f3n precio\/calidad.<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2171f63 elementor-widget elementor-widget-visual-portfolio\" data-id=\"2171f63\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"visual-portfolio.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div\n\t\t\t\t\t>\n\t\t\t\t\t\t\t\n<div class=\"vp-portfolio vp-uid-031cf7f2 vp-id-18408 \"\n\tdata-vp-layout=\"tiles\" data-vp-content-source=\"post-based\" data-vp-items-style=\"fade\" data-vp-items-click-action=\"url\" data-vp-items-gap=\"10\" data-vp-items-gap-vertical=\"\" data-vp-pagination=\"infinite\" data-vp-next-page-url=\"\" data-vp-tiles-type=\"3|1,1|\" >\n\t<div class=\"vp-portfolio__preloader-wrap\">\n\t\t<div class=\"vp-portfolio__preloader\">\n\t\t\t<img decoding=\"async\" loading=\"eager\" src=\"https:\/\/ducasseindustrial.com\/testcl\/wp-content\/plugins\/visual-portfolio\/assets\/images\/logo-dark.svg\" alt=\"Visual Portfolio, Posts &amp; Image Gallery for WordPress\" width=\"20\" height=\"20\" data-skip-lazy>\n\t\t<\/div>\n\t<\/div>\n\t\t<div class=\"vp-portfolio__layout-elements vp-portfolio__layout-elements-top vp-portfolio__layout-elements-align-center\">\n\t\t\t\t<div class=\"vp-portfolio__filter-wrap\">\n\t\t\n<div class=\"vp-filter vp-filter__style-default\">\n\t\t\t<div class=\"vp-filter__item vp-filter__item-active\">\n\t\t\t<a href=\"https:\/\/ducasseindustrial.com\/testcl\/wp-json\/wp\/v2\/pages\/18406\" data-vp-filter=\"*\">\n\t\t\t\tVER TODO\n\t\t\t\t\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t<div class=\"vp-filter__item\">\n\t\t\t<a href=\"https:\/\/ducasseindustrial.com\/testcl\/wp-json\/wp\/v2\/pages\/18406?vp_filter=portfolio_category%3Amadera-espacios-educativos\" data-vp-filter=\"madera-espacios-educativos\">\n\t\t\t\tMadera\n\t\t\t\t\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t<div class=\"vp-filter__item\">\n\t\t\t<a href=\"https:\/\/ducasseindustrial.com\/testcl\/wp-json\/wp\/v2\/pages\/18406?vp_filter=portfolio_category%3Avidrio-espacios-educativos\" data-vp-filter=\"vidrio-espacios-educativos\">\n\t\t\t\tVidrio\n\t\t\t\t\t\t\t<\/a>\n\t\t<\/div>\n\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"vp-portfolio__items-wrap\">\n\t\t\t\n<div class=\"vp-portfolio__items vp-portfolio__items-style-fade vp-portfolio__items-show-overlay-hover\">\n\n\t\t<article\t\tclass=\"vp-portfolio__item-wrap post-18430 portfolio type-portfolio status-publish format-standard has-post-thumbnail hentry portfolio_category-vidrio-espacios-educativos portfolio_tag-apilable vp-portfolio__item-uid-4fdd8e90\" data-vp-filter=\"vidrio-espacios-educativos\" \t\t>\n\t\t\t\t\t\t\t\t\t<figure class=\"vp-portfolio__item\">\n\t\t\t\t\n<div class=\"vp-portfolio__item-img-wrap\">\n\t<div class=\"vp-portfolio__item-img\">\n\t\t\t<a\n\t\thref=\"https:\/\/ducasseindustrial.com\/testcl\/portfolio\/instituto-pinto\"\n\t\taria-label=\"Instituto Pinto\" \t>\n\t\n\t\t<noscript><img fetchpriority=\"high\" decoding=\"async\" width=\"1200\" height=\"800\" data-skip-lazy src=\"https:\/\/ducasseindustrial.com\/testcl\/wp-content\/uploads\/sites\/27\/2020\/11\/07-espacios-educativos-pinto-portada.jpg\" class=\"wp-image-19162\" alt=\"\" srcset=\"https:\/\/ducasseindustrial.com\/testcl\/wp-content\/uploads\/sites\/27\/2020\/11\/07-espacios-educativos-pinto-portada.jpg 1200w, https:\/\/ducasseindustrial.com\/testcl\/wp-content\/uploads\/sites\/27\/2020\/11\/07-espacios-educativos-pinto-portada-600x400.jpg 600w, https:\/\/ducasseindustrial.com\/testcl\/wp-content\/uploads\/sites\/27\/2020\/11\/07-espacios-educativos-pinto-portada-1024x683.jpg 1024w, https:\/\/ducasseindustrial.com\/testcl\/wp-content\/uploads\/sites\/27\/2020\/11\/07-espacios-educativos-pinto-portada-768x512.jpg 768w, https:\/\/ducasseindustrial.com\/testcl\/wp-content\/uploads\/sites\/27\/2020\/11\/07-espacios-educativos-pinto-portada-500x333.jpg 500w, https:\/\/ducasseindustrial.com\/testcl\/wp-content\/uploads\/sites\/27\/2020\/11\/07-espacios-educativos-pinto-portada-800x533.jpg 800w\" sizes=\"(max-width: 1200px) 100vw, 1200px\" \/><\/noscript><img decoding=\"async\" width=\"1200\" height=\"800\" src=\"https:\/\/ducasseindustrial.com\/testcl\/wp-content\/uploads\/sites\/27\/2020\/11\/07-espacios-educativos-pinto-portada.jpg\" class=\"wp-image-19162 vp-lazyload\" alt srcset=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMTIwMCIgaGVpZ2h0PSI4MDAiIHZpZXdCb3g9IjAgMCAxMjAwIDgwMCIgZmlsbD0ibm9uZSIgeG1sbnM9Imh0dHA6Ly93d3cudzMub3JnLzIwMDAvc3ZnIj48L3N2Zz4=\" data-src=\"https:\/\/ducasseindustrial.com\/testcl\/wp-content\/uploads\/sites\/27\/2020\/11\/07-espacios-educativos-pinto-portada.jpg\" data-srcset=\"https:\/\/ducasseindustrial.com\/testcl\/wp-content\/uploads\/sites\/27\/2020\/11\/07-espacios-educativos-pinto-portada.jpg 1200w, https:\/\/ducasseindustrial.com\/testcl\/wp-content\/uploads\/sites\/27\/2020\/11\/07-espacios-educativos-pinto-portada-600x400.jpg 600w, https:\/\/ducasseindustrial.com\/testcl\/wp-content\/uploads\/sites\/27\/2020\/11\/07-espacios-educativos-pinto-portada-1024x683.jpg 1024w, https:\/\/ducasseindustrial.com\/testcl\/wp-content\/uploads\/sites\/27\/2020\/11\/07-espacios-educativos-pinto-portada-768x512.jpg 768w, https:\/\/ducasseindustrial.com\/testcl\/wp-content\/uploads\/sites\/27\/2020\/11\/07-espacios-educativos-pinto-portada-500x333.jpg 500w, https:\/\/ducasseindustrial.com\/testcl\/wp-content\/uploads\/sites\/27\/2020\/11\/07-espacios-educativos-pinto-portada-800x533.jpg 800w\" data-sizes=\"auto\" loading=\"eager\">\n\t\t<\/a>\t<\/div>\n<\/div>\n\t<figcaption class=\"vp-portfolio__item-overlay vp-portfolio__item-overlay-text-align-center\">\n\t\t<div class=\"vp-portfolio__item-meta-wrap vp-portfolio__custom-scrollbar\">\n\t\t\t\t<a\n\t\thref=\"https:\/\/ducasseindustrial.com\/testcl\/portfolio\/instituto-pinto\"\n\t\ttabindex=\"-1\" class=\"vp-portfolio__item-meta\" aria-label=\"Instituto Pinto\" \t>\n\t\n\n<div class=\"vp-portfolio__item-meta-categories\">\n\t\t\t<div class=\"vp-portfolio__item-meta-category\">\n\t\t\t\t<span\t\t\t>\n\tVidrio<\/span>\t\t<\/div>\n\t\t<\/div>\n\n\n<h2 class=\"vp-portfolio__item-meta-title\">\n\tInstituto Pinto<\/h2>\n<\/a>\t\t<\/div>\n\t<\/figcaption>\n\t\t\t<\/figure>\n\t\t\t\t\t<\/article>\n\t\t\n\t\t<article\t\tclass=\"vp-portfolio__item-wrap post-18420 portfolio type-portfolio status-publish format-standard has-post-thumbnail hentry portfolio_category-madera-espacios-educativos portfolio_tag-apilable vp-portfolio__item-uid-56c6bfd1\" data-vp-filter=\"madera-espacios-educativos\" \t\t>\n\t\t\t\t\t\t\t\t\t<figure class=\"vp-portfolio__item\">\n\t\t\t\t\n<div class=\"vp-portfolio__item-img-wrap\">\n\t<div class=\"vp-portfolio__item-img\">\n\t\t\t<a\n\t\thref=\"https:\/\/ducasseindustrial.com\/testcl\/portfolio\/colegio-labardem\"\n\t\taria-label=\"Colegio Labardem\" \t>\n\t\n\t\t<noscript><img decoding=\"async\" width=\"1474\" height=\"1045\" data-skip-lazy src=\"https:\/\/ducasseindustrial.com\/testcl\/wp-content\/uploads\/sites\/27\/2020\/11\/07-espacios-educativos-portada.jpg\" class=\"wp-image-19153\" alt=\"\" srcset=\"https:\/\/ducasseindustrial.com\/testcl\/wp-content\/uploads\/sites\/27\/2020\/11\/07-espacios-educativos-portada.jpg 1474w, https:\/\/ducasseindustrial.com\/testcl\/wp-content\/uploads\/sites\/27\/2020\/11\/07-espacios-educativos-portada-600x425.jpg 600w, https:\/\/ducasseindustrial.com\/testcl\/wp-content\/uploads\/sites\/27\/2020\/11\/07-espacios-educativos-portada-1024x726.jpg 1024w, https:\/\/ducasseindustrial.com\/testcl\/wp-content\/uploads\/sites\/27\/2020\/11\/07-espacios-educativos-portada-768x544.jpg 768w, https:\/\/ducasseindustrial.com\/testcl\/wp-content\/uploads\/sites\/27\/2020\/11\/07-espacios-educativos-portada-500x354.jpg 500w, https:\/\/ducasseindustrial.com\/testcl\/wp-content\/uploads\/sites\/27\/2020\/11\/07-espacios-educativos-portada-800x567.jpg 800w, https:\/\/ducasseindustrial.com\/testcl\/wp-content\/uploads\/sites\/27\/2020\/11\/07-espacios-educativos-portada-1280x907.jpg 1280w\" sizes=\"(max-width: 1474px) 100vw, 1474px\" \/><\/noscript><img decoding=\"async\" width=\"1474\" height=\"1045\" src=\"https:\/\/ducasseindustrial.com\/testcl\/wp-content\/uploads\/sites\/27\/2020\/11\/07-espacios-educativos-portada.jpg\" class=\"wp-image-19153 vp-lazyload\" alt srcset=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMTQ3NCIgaGVpZ2h0PSIxMDQ1IiB2aWV3Qm94PSIwIDAgMTQ3NCAxMDQ1IiBmaWxsPSJub25lIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" data-src=\"https:\/\/ducasseindustrial.com\/testcl\/wp-content\/uploads\/sites\/27\/2020\/11\/07-espacios-educativos-portada.jpg\" data-srcset=\"https:\/\/ducasseindustrial.com\/testcl\/wp-content\/uploads\/sites\/27\/2020\/11\/07-espacios-educativos-portada.jpg 1474w, https:\/\/ducasseindustrial.com\/testcl\/wp-content\/uploads\/sites\/27\/2020\/11\/07-espacios-educativos-portada-600x425.jpg 600w, https:\/\/ducasseindustrial.com\/testcl\/wp-content\/uploads\/sites\/27\/2020\/11\/07-espacios-educativos-portada-1024x726.jpg 1024w, https:\/\/ducasseindustrial.com\/testcl\/wp-content\/uploads\/sites\/27\/2020\/11\/07-espacios-educativos-portada-768x544.jpg 768w, https:\/\/ducasseindustrial.com\/testcl\/wp-content\/uploads\/sites\/27\/2020\/11\/07-espacios-educativos-portada-500x354.jpg 500w, https:\/\/ducasseindustrial.com\/testcl\/wp-content\/uploads\/sites\/27\/2020\/11\/07-espacios-educativos-portada-800x567.jpg 800w, https:\/\/ducasseindustrial.com\/testcl\/wp-content\/uploads\/sites\/27\/2020\/11\/07-espacios-educativos-portada-1280x907.jpg 1280w\" data-sizes=\"auto\" loading=\"eager\">\n\t\t<\/a>\t<\/div>\n<\/div>\n\t<figcaption class=\"vp-portfolio__item-overlay vp-portfolio__item-overlay-text-align-center\">\n\t\t<div class=\"vp-portfolio__item-meta-wrap vp-portfolio__custom-scrollbar\">\n\t\t\t\t<a\n\t\thref=\"https:\/\/ducasseindustrial.com\/testcl\/portfolio\/colegio-labardem\"\n\t\ttabindex=\"-1\" class=\"vp-portfolio__item-meta\" aria-label=\"Colegio Labardem\" \t>\n\t\n\n<div class=\"vp-portfolio__item-meta-categories\">\n\t\t\t<div class=\"vp-portfolio__item-meta-category\">\n\t\t\t\t<span\t\t\t>\n\tMadera<\/span>\t\t<\/div>\n\t\t<\/div>\n\n\n<h2 class=\"vp-portfolio__item-meta-title\">\n\tColegio Labardem<\/h2>\n<\/a>\t\t<\/div>\n\t<\/figcaption>\n\t\t\t<\/figure>\n\t\t\t\t\t<\/article>\n\t\t\n\t\t<article\t\tclass=\"vp-portfolio__item-wrap post-18402 portfolio type-portfolio status-publish format-standard has-post-thumbnail hentry portfolio_category-madera-espacios-educativos portfolio_tag-apilable vp-portfolio__item-uid-8afebc7f\" data-vp-filter=\"madera-espacios-educativos\" \t\t>\n\t\t\t\t\t\t\t\t\t<figure class=\"vp-portfolio__item\">\n\t\t\t\t\n<div class=\"vp-portfolio__item-img-wrap\">\n\t<div class=\"vp-portfolio__item-img\">\n\t\t\t<a\n\t\thref=\"https:\/\/ducasseindustrial.com\/testcl\/portfolio\/liceo-del-valle\"\n\t\taria-label=\"Liceo del Valle\" \t>\n\t\n\t\t<noscript><img decoding=\"async\" width=\"900\" height=\"800\" data-skip-lazy src=\"https:\/\/ducasseindustrial.com\/testcl\/wp-content\/uploads\/sites\/27\/2020\/11\/07-espacios-educativos-delvalle-portada.jpg\" class=\"wp-image-19163\" alt=\"\" srcset=\"https:\/\/ducasseindustrial.com\/testcl\/wp-content\/uploads\/sites\/27\/2020\/11\/07-espacios-educativos-delvalle-portada.jpg 900w, https:\/\/ducasseindustrial.com\/testcl\/wp-content\/uploads\/sites\/27\/2020\/11\/07-espacios-educativos-delvalle-portada-600x533.jpg 600w, https:\/\/ducasseindustrial.com\/testcl\/wp-content\/uploads\/sites\/27\/2020\/11\/07-espacios-educativos-delvalle-portada-768x683.jpg 768w, https:\/\/ducasseindustrial.com\/testcl\/wp-content\/uploads\/sites\/27\/2020\/11\/07-espacios-educativos-delvalle-portada-500x444.jpg 500w, https:\/\/ducasseindustrial.com\/testcl\/wp-content\/uploads\/sites\/27\/2020\/11\/07-espacios-educativos-delvalle-portada-800x711.jpg 800w\" sizes=\"(max-width: 900px) 100vw, 900px\" \/><\/noscript><img decoding=\"async\" width=\"900\" height=\"800\" src=\"https:\/\/ducasseindustrial.com\/testcl\/wp-content\/uploads\/sites\/27\/2020\/11\/07-espacios-educativos-delvalle-portada.jpg\" class=\"wp-image-19163 vp-lazyload\" alt srcset=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iOTAwIiBoZWlnaHQ9IjgwMCIgdmlld0JveD0iMCAwIDkwMCA4MDAiIGZpbGw9Im5vbmUiIHhtbG5zPSJodHRwOi8vd3d3LnczLm9yZy8yMDAwL3N2ZyI+PC9zdmc+\" data-src=\"https:\/\/ducasseindustrial.com\/testcl\/wp-content\/uploads\/sites\/27\/2020\/11\/07-espacios-educativos-delvalle-portada.jpg\" data-srcset=\"https:\/\/ducasseindustrial.com\/testcl\/wp-content\/uploads\/sites\/27\/2020\/11\/07-espacios-educativos-delvalle-portada.jpg 900w, https:\/\/ducasseindustrial.com\/testcl\/wp-content\/uploads\/sites\/27\/2020\/11\/07-espacios-educativos-delvalle-portada-600x533.jpg 600w, https:\/\/ducasseindustrial.com\/testcl\/wp-content\/uploads\/sites\/27\/2020\/11\/07-espacios-educativos-delvalle-portada-768x683.jpg 768w, https:\/\/ducasseindustrial.com\/testcl\/wp-content\/uploads\/sites\/27\/2020\/11\/07-espacios-educativos-delvalle-portada-500x444.jpg 500w, https:\/\/ducasseindustrial.com\/testcl\/wp-content\/uploads\/sites\/27\/2020\/11\/07-espacios-educativos-delvalle-portada-800x711.jpg 800w\" data-sizes=\"auto\" loading=\"eager\">\n\t\t<\/a>\t<\/div>\n<\/div>\n\t<figcaption class=\"vp-portfolio__item-overlay vp-portfolio__item-overlay-text-align-center\">\n\t\t<div class=\"vp-portfolio__item-meta-wrap vp-portfolio__custom-scrollbar\">\n\t\t\t\t<a\n\t\thref=\"https:\/\/ducasseindustrial.com\/testcl\/portfolio\/liceo-del-valle\"\n\t\ttabindex=\"-1\" class=\"vp-portfolio__item-meta\" aria-label=\"Liceo del Valle\" \t>\n\t\n\n<div class=\"vp-portfolio__item-meta-categories\">\n\t\t\t<div class=\"vp-portfolio__item-meta-category\">\n\t\t\t\t<span\t\t\t>\n\tMadera<\/span>\t\t<\/div>\n\t\t<\/div>\n\n\n<h2 class=\"vp-portfolio__item-meta-title\">\n\tLiceo del Valle<\/h2>\n<\/a>\t\t<\/div>\n\t<\/figcaption>\n\t\t\t<\/figure>\n\t\t\t\t\t<\/article>\n\t\t\n<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"vp-portfolio__layout-elements vp-portfolio__layout-elements-bottom vp-portfolio__layout-elements-align-center\">\n\t\t\t\t<div class=\"vp-portfolio__pagination-wrap\">\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\n<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-section elementor-top-section elementor-element elementor-element-918aef9 elementor-section-height-min-height elementor-section-full_width elementor-section-content-bottom elementor-section-height-default elementor-section-items-middle\" data-id=\"918aef9\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-60adc0c\" data-id=\"60adc0c\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Espacios Educativos Sistemas corredizos para adaptar espacios educativos Configurar espacios educativos a partir de sistemas corredizos de vidrio o madera permite adaptar el entorno en un ambiente visualmente agradable. El uso de estos sistemas hace que los recintos puedan transformarse de manera muy simple y \u00e1gil, considerando la ultima tecnolog\u00eda utilizada en los sistemas para [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":19377,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_uag_custom_page_level_css":"","site-sidebar-layout":"no-sidebar","site-content-layout":"page-builder","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"disabled","ast-breadcrumbs-content":"","ast-featured-img":"disabled","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"default","adv-header-id-meta":"","stick-header-meta":"default","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"default","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"_vp_format_video_url":"","_vp_image_focal_point":[],"footnotes":""},"class_list":["post-18406","page","type-page","status-publish","hentry"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 5.0.0.1 - aioseo.com -->\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/ducasseindustrial.com\/testcl\/portfolio\/liceo-del-valle\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 5.0.0.1\" \/>\n\t\t<meta property=\"og:locale\" content=\"es_ES\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Test Chile | Somos una empresa Chilena, con m\u00e1s de 50 a\u00f1os de experiencia en la fabricaci\u00f3n de herrajes para la industria del mueble y la construcci\u00f3n, satisfaciendo necesidades tanto en mercados locales como extranjeros.\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Liceo del Valle | Test Chile\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/ducasseindustrial.com\/testcl\/portfolio\/liceo-del-valle\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/ducasseindustrial.com\/testcl\/wp-content\/uploads\/sites\/27\/2024\/04\/logo_web_ducasse.svg\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/ducasseindustrial.com\/testcl\/wp-content\/uploads\/sites\/27\/2024\/04\/logo_web_ducasse.svg\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2020-10-29T15:46:23+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2020-11-12T14:47:37+00:00\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Liceo del Valle | Test Chile\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/ducasseindustrial.com\/testcl\/wp-content\/uploads\/sites\/27\/2024\/04\/logo_web_ducasse.svg\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/ducasseindustrial.com\\\/testcl\\\/portfolio\\\/liceo-del-valle#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ducasseindustrial.com\\\/testcl#listItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\\\/\\\/ducasseindustrial.com\\\/testcl\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ducasseindustrial.com\\\/testcl\\\/arquitectura#listItem\",\"name\":\"Arquitectura\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ducasseindustrial.com\\\/testcl\\\/arquitectura#listItem\",\"position\":2,\"name\":\"Arquitectura\",\"item\":\"https:\\\/\\\/ducasseindustrial.com\\\/testcl\\\/arquitectura\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ducasseindustrial.com\\\/testcl\\\/arquitectura\\\/espacios-educativos#listItem\",\"name\":\"Espacios Educativos\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ducasseindustrial.com\\\/testcl#listItem\",\"name\":\"Inicio\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ducasseindustrial.com\\\/testcl\\\/arquitectura\\\/espacios-educativos#listItem\",\"position\":3,\"name\":\"Espacios Educativos\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ducasseindustrial.com\\\/testcl\\\/arquitectura#listItem\",\"name\":\"Arquitectura\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/ducasseindustrial.com\\\/testcl\\\/#organization\",\"name\":\"Test Chile\",\"description\":\"Somos una empresa Chilena, con m\\u00e1s de 50 a\\u00f1os de experiencia en la fabricaci\\u00f3n de herrajes para la industria del mueble y la construcci\\u00f3n, satisfaciendo necesidades tanto en mercados locales como extranjeros.\",\"url\":\"https:\\\/\\\/ducasseindustrial.com\\\/testcl\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/ducasseindustrial.com\\\/testcl\\\/wp-content\\\/uploads\\\/sites\\\/27\\\/2024\\\/04\\\/logo_web_ducasse.svg\",\"@id\":\"https:\\\/\\\/ducasseindustrial.com\\\/testcl\\\/portfolio\\\/liceo-del-valle\\\/#organizationLogo\",\"width\":1004,\"height\":294},\"image\":{\"@id\":\"https:\\\/\\\/ducasseindustrial.com\\\/testcl\\\/portfolio\\\/liceo-del-valle\\\/#organizationLogo\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/ducasseindustrial.com\\\/testcl\\\/archivo\\\/author\\\/user#author\",\"url\":\"https:\\\/\\\/ducasseindustrial.com\\\/testcl\\\/archivo\\\/author\\\/user\",\"name\":\"user\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/ducasseindustrial.com\\\/testcl\\\/portfolio\\\/liceo-del-valle#authorImage\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/e0057e34c56ef6dca6089650e4668a215ff462ec200b8030e4df3adf4bdc9df4?s=96&d=mm&r=g\",\"width\":96,\"height\":96,\"caption\":\"user\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/ducasseindustrial.com\\\/testcl\\\/portfolio\\\/liceo-del-valle#webpage\",\"url\":\"https:\\\/\\\/ducasseindustrial.com\\\/testcl\\\/portfolio\\\/liceo-del-valle#webpage\",\"name\":\"Liceo del Valle | Test Chile\",\"inLanguage\":\"es-CL\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/ducasseindustrial.com\\\/testcl\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/ducasseindustrial.com\\\/testcl\\\/portfolio\\\/liceo-del-valle#webpage\"},\"author\":{\"@id\":\"https:\\\/\\\/ducasseindustrial.com\\\/testcl\\\/archivo\\\/author\\\/user#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/ducasseindustrial.com\\\/testcl\\\/archivo\\\/author\\\/user#author\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/ducasseindustrial.com\\\/testcl\\\/wp-content\\\/uploads\\\/sites\\\/27\\\/2020\\\/11\\\/07-espacios-educativos-delvalle-portada.jpg\",\"@id\":\"https:\\\/\\\/ducasseindustrial.com\\\/testcl\\\/portfolio\\\/liceo-del-valle\\\/#mainImage\",\"width\":900,\"height\":800,\"caption\":\"SAMSUNG CSC\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/ducasseindustrial.com\\\/testcl\\\/portfolio\\\/liceo-del-valle#mainImage\"},\"datePublished\":\"2020-10-29T11:46:23-04:00\",\"dateModified\":\"2020-11-12T10:47:37-04:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/ducasseindustrial.com\\\/testcl\\\/#website\",\"url\":\"https:\\\/\\\/ducasseindustrial.com\\\/testcl\\\/\",\"name\":\"Test Chile\",\"description\":\"Somos una empresa Chilena, con m\\u00e1s de 50 a\\u00f1os de experiencia en la fabricaci\\u00f3n de herrajes para la industria del mueble y la construcci\\u00f3n, satisfaciendo necesidades tanto en mercados locales como extranjeros.\",\"inLanguage\":\"es-CL\",\"publisher\":{\"@id\":\"https:\\\/\\\/ducasseindustrial.com\\\/testcl\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"Liceo del Valle | Test Chile","description":"","canonical_url":"https:\/\/ducasseindustrial.com\/testcl\/portfolio\/liceo-del-valle","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BreadcrumbList","@id":"https:\/\/ducasseindustrial.com\/testcl\/portfolio\/liceo-del-valle#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/ducasseindustrial.com\/testcl#listItem","position":1,"name":"Inicio","item":"https:\/\/ducasseindustrial.com\/testcl","nextItem":{"@type":"ListItem","@id":"https:\/\/ducasseindustrial.com\/testcl\/arquitectura#listItem","name":"Arquitectura"}},{"@type":"ListItem","@id":"https:\/\/ducasseindustrial.com\/testcl\/arquitectura#listItem","position":2,"name":"Arquitectura","item":"https:\/\/ducasseindustrial.com\/testcl\/arquitectura","nextItem":{"@type":"ListItem","@id":"https:\/\/ducasseindustrial.com\/testcl\/arquitectura\/espacios-educativos#listItem","name":"Espacios Educativos"},"previousItem":{"@type":"ListItem","@id":"https:\/\/ducasseindustrial.com\/testcl#listItem","name":"Inicio"}},{"@type":"ListItem","@id":"https:\/\/ducasseindustrial.com\/testcl\/arquitectura\/espacios-educativos#listItem","position":3,"name":"Espacios Educativos","previousItem":{"@type":"ListItem","@id":"https:\/\/ducasseindustrial.com\/testcl\/arquitectura#listItem","name":"Arquitectura"}}]},{"@type":"Organization","@id":"https:\/\/ducasseindustrial.com\/testcl\/#organization","name":"Test Chile","description":"Somos una empresa Chilena, con m\u00e1s de 50 a\u00f1os de experiencia en la fabricaci\u00f3n de herrajes para la industria del mueble y la construcci\u00f3n, satisfaciendo necesidades tanto en mercados locales como extranjeros.","url":"https:\/\/ducasseindustrial.com\/testcl\/","logo":{"@type":"ImageObject","url":"https:\/\/ducasseindustrial.com\/testcl\/wp-content\/uploads\/sites\/27\/2024\/04\/logo_web_ducasse.svg","@id":"https:\/\/ducasseindustrial.com\/testcl\/portfolio\/liceo-del-valle\/#organizationLogo","width":1004,"height":294},"image":{"@id":"https:\/\/ducasseindustrial.com\/testcl\/portfolio\/liceo-del-valle\/#organizationLogo"}},{"@type":"Person","@id":"https:\/\/ducasseindustrial.com\/testcl\/archivo\/author\/user#author","url":"https:\/\/ducasseindustrial.com\/testcl\/archivo\/author\/user","name":"user","image":{"@type":"ImageObject","@id":"https:\/\/ducasseindustrial.com\/testcl\/portfolio\/liceo-del-valle#authorImage","url":"https:\/\/secure.gravatar.com\/avatar\/e0057e34c56ef6dca6089650e4668a215ff462ec200b8030e4df3adf4bdc9df4?s=96&d=mm&r=g","width":96,"height":96,"caption":"user"}},{"@type":"WebPage","@id":"https:\/\/ducasseindustrial.com\/testcl\/portfolio\/liceo-del-valle#webpage","url":"https:\/\/ducasseindustrial.com\/testcl\/portfolio\/liceo-del-valle#webpage","name":"Liceo del Valle | Test Chile","inLanguage":"es-CL","isPartOf":{"@id":"https:\/\/ducasseindustrial.com\/testcl\/#website"},"breadcrumb":{"@id":"https:\/\/ducasseindustrial.com\/testcl\/portfolio\/liceo-del-valle#webpage"},"author":{"@id":"https:\/\/ducasseindustrial.com\/testcl\/archivo\/author\/user#author"},"creator":{"@id":"https:\/\/ducasseindustrial.com\/testcl\/archivo\/author\/user#author"},"image":{"@type":"ImageObject","url":"https:\/\/ducasseindustrial.com\/testcl\/wp-content\/uploads\/sites\/27\/2020\/11\/07-espacios-educativos-delvalle-portada.jpg","@id":"https:\/\/ducasseindustrial.com\/testcl\/portfolio\/liceo-del-valle\/#mainImage","width":900,"height":800,"caption":"SAMSUNG CSC"},"primaryImageOfPage":{"@id":"https:\/\/ducasseindustrial.com\/testcl\/portfolio\/liceo-del-valle#mainImage"},"datePublished":"2020-10-29T11:46:23-04:00","dateModified":"2020-11-12T10:47:37-04:00"},{"@type":"WebSite","@id":"https:\/\/ducasseindustrial.com\/testcl\/#website","url":"https:\/\/ducasseindustrial.com\/testcl\/","name":"Test Chile","description":"Somos una empresa Chilena, con m\u00e1s de 50 a\u00f1os de experiencia en la fabricaci\u00f3n de herrajes para la industria del mueble y la construcci\u00f3n, satisfaciendo necesidades tanto en mercados locales como extranjeros.","inLanguage":"es-CL","publisher":{"@id":"https:\/\/ducasseindustrial.com\/testcl\/#organization"}}]},"og:locale":"es_ES","og:site_name":"Test Chile | Somos una empresa Chilena, con m\u00e1s de 50 a\u00f1os de experiencia en la fabricaci\u00f3n de herrajes para la industria del mueble y la construcci\u00f3n, satisfaciendo necesidades tanto en mercados locales como extranjeros.","og:type":"article","og:title":"Liceo del Valle | Test Chile","og:url":"https:\/\/ducasseindustrial.com\/testcl\/portfolio\/liceo-del-valle","og:image":"https:\/\/ducasseindustrial.com\/testcl\/wp-content\/uploads\/sites\/27\/2024\/04\/logo_web_ducasse.svg","og:image:secure_url":"https:\/\/ducasseindustrial.com\/testcl\/wp-content\/uploads\/sites\/27\/2024\/04\/logo_web_ducasse.svg","article:published_time":"2020-10-29T15:46:23+00:00","article:modified_time":"2020-11-12T14:47:37+00:00","twitter:card":"summary","twitter:title":"Liceo del Valle | Test Chile","twitter:image":"https:\/\/ducasseindustrial.com\/testcl\/wp-content\/uploads\/sites\/27\/2024\/04\/logo_web_ducasse.svg"},"aioseo_meta_data":{"post_id":"18406","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":null,"isEnabled":true},"graphs":[]},"schema_type":null,"schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","priority":null,"frequency":null,"local_seo":null,"breadcrumb_settings":null,"limit_modified_date":false,"ai":null,"created":"2021-03-01 10:53:13","updated":"2025-11-01 10:34:24","focus_keyword":null,"additional_keywords":null,"truseo_locale":null,"seo_analyzer_scan_date":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/ducasseindustrial.com\/testcl\" title=\"Inicio\">Inicio<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">\u00bb<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/ducasseindustrial.com\/testcl\/arquitectura\" title=\"Arquitectura\">Arquitectura<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">\u00bb<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tEspacios Educativos\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Inicio","link":"https:\/\/ducasseindustrial.com\/testcl"},{"label":"Arquitectura","link":"https:\/\/ducasseindustrial.com\/testcl\/arquitectura"},{"label":"Espacios Educativos","link":"https:\/\/ducasseindustrial.com\/testcl\/arquitectura\/espacios-educativos"}],"uagb_featured_image_src":{"full":false,"thumbnail":false,"medium":false,"medium_large":false,"large":false,"1536x1536":false,"2048x2048":false,"vp_sm":false,"vp_md":false,"vp_lg":false,"vp_xl":false,"vp_sm_popup":false,"vp_md_popup":false,"vp_xl_popup":false,"woocommerce_thumbnail":false,"woocommerce_single":false,"woocommerce_gallery_thumbnail":false,"variation_swatches_image_size":false,"variation_swatches_tooltip_size":false},"uagb_author_info":{"display_name":"user","author_link":"https:\/\/ducasseindustrial.com\/testcl\/archivo\/author\/user"},"uagb_comment_info":0,"uagb_excerpt":"Espacios Educativos Sistemas corredizos para adaptar espacios educativos Configurar espacios educativos a partir de sistemas corredizos de vidrio o madera permite adaptar el entorno en un ambiente visualmente agradable. El uso de estos sistemas hace que los recintos puedan transformarse de manera muy simple y \u00e1gil, considerando la ultima tecnolog\u00eda utilizada en los sistemas para&hellip;","_links":{"self":[{"href":"https:\/\/ducasseindustrial.com\/testcl\/wp-json\/wp\/v2\/pages\/18406","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ducasseindustrial.com\/testcl\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/ducasseindustrial.com\/testcl\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/ducasseindustrial.com\/testcl\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/ducasseindustrial.com\/testcl\/wp-json\/wp\/v2\/comments?post=18406"}],"version-history":[{"count":3,"href":"https:\/\/ducasseindustrial.com\/testcl\/wp-json\/wp\/v2\/pages\/18406\/revisions"}],"predecessor-version":[{"id":20062,"href":"https:\/\/ducasseindustrial.com\/testcl\/wp-json\/wp\/v2\/pages\/18406\/revisions\/20062"}],"up":[{"embeddable":true,"href":"https:\/\/ducasseindustrial.com\/testcl\/wp-json\/wp\/v2\/pages\/19377"}],"wp:attachment":[{"href":"https:\/\/ducasseindustrial.com\/testcl\/wp-json\/wp\/v2\/media?parent=18406"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}