{"id":3096,"date":"2020-09-07T12:58:50","date_gmt":"2020-09-07T16:58:50","guid":{"rendered":"https:\/\/ducasseindustrial.com\/testcl\/?post_type=portfolio&#038;p=3096"},"modified":"2020-11-12T11:13:42","modified_gmt":"2020-11-12T15:13:42","slug":"casa-a-2","status":"publish","type":"portfolio","link":"https:\/\/ducasseindustrial.com\/testcl\/portfolio\/casa-a-2","title":{"rendered":"Casa A."},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"3096\" class=\"elementor elementor-3096\" data-elementor-post-type=\"portfolio\">\n\t\t\t\t\t\t<section data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-section elementor-top-section elementor-element elementor-element-a32bf88 elementor-section-height-min-height elementor-section-boxed elementor-section-height-default elementor-section-items-middle\" data-id=\"a32bf88\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-7ac7215c\" data-id=\"7ac7215c\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-section elementor-top-section elementor-element elementor-element-75f49c5a elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"75f49c5a\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-67877158\" data-id=\"67877158\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1108bc30 elementor-widget elementor-widget-shortcode\" data-id=\"1108bc30\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"shortcode.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-shortcode\">\t\t<div data-elementor-type=\"archive\" data-elementor-id=\"19940\" class=\"elementor elementor-19940\" data-elementor-post-type=\"elementor_library\">\n\t\t\t\t\t<section data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-section elementor-inner-section elementor-element elementor-element-ca1dfdd elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"ca1dfdd\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-68cc1118\" data-id=\"68cc1118\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-114e4b55 elementor-widget__width-initial elementor-hidden-phone eael_advanced_menu_hamburger_disable_selected_menu_no eael-advanced-menu-hamburger-align-right eael-advanced-menu--no eael-hamburger--tablet elementor-widget elementor-widget-eael-advanced-menu\" data-id=\"114e4b55\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"eael-advanced-menu.skin-two\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<style>\n                        @media screen and (max-width: 1024px) {\n                            .eael-hamburger--tablet {\n                                .eael-advanced-menu-horizontal,\n                                .eael-advanced-menu-vertical {\n                                    display: none;\n                                }\n                            }\n                            .eael-hamburger--tablet {\n                                .eael-advanced-menu-container .eael-advanced-menu-toggle {\n                                    display: block;\n                                }\n                            }\n                        }\n                    <\/style>            <div data-hamburger-icon=\"&lt;i aria-hidden=&quot;true&quot; class=&quot;fas fa-bars&quot;&gt;&lt;\/i&gt;\" data-indicator-class=\"&lt;i aria-hidden=&quot;true&quot; class=&quot;fas fa-angle-down&quot;&gt;&lt;\/i&gt;\" data-dropdown-indicator-class=\"&lt;i aria-hidden=&quot;true&quot; class=&quot;fas fa-angle-down&quot;&gt;&lt;\/i&gt;\" class=\"eael-advanced-menu-container eael-advanced-menu-align-left eael-advanced-menu-dropdown-align-left\" data-hamburger-breakpoints=\"{&quot;mobile&quot;:&quot;M\\u00f3vil vertical (&gt; 767px)&quot;,&quot;tablet&quot;:&quot;Tableta vertical (&gt; 1024px)&quot;,&quot;desktop&quot;:&quot;Desktop (&gt; 2400px)&quot;,&quot;none&quot;:&quot;None&quot;}\" data-hamburger-device=\"tablet\">\n                <ul id=\"menu-arquitectura\" class=\"eael-advanced-menu eael-advanced-menu-dropdown-animate-zoom-in eael-advanced-menu-indicator eael-advanced-menu-vertical\"><li id=\"menu-item-19381\" class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-19381\"><a href=\"https:\/\/ducasseindustrial.com\/testcl\/arquitectura\" class=\"menu-link\">Arquitectura<\/a><\/li>\n<li id=\"menu-item-2935\" class=\"menu-item menu-item-type-custom menu-item-object-custom menu-item-has-children menu-item-2935\"><a aria-expanded=\"false\" href=\"#\" class=\"menu-link\">soluciones<\/a>\n<ul class=\"sub-menu\">\n\t<li id=\"menu-item-19394\" class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-19394\"><a href=\"https:\/\/ducasseindustrial.com\/testcl\/arquitectura\/quinchos-y-galerias\" class=\"menu-link\">quinchos y galer\u00edas<\/a><\/li>\n\t<li id=\"menu-item-19384\" class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-19384\"><a href=\"https:\/\/ducasseindustrial.com\/testcl\/arquitectura\/division-de-ambientes\" class=\"menu-link\">divisi\u00f3n de ambientes<\/a><\/li>\n\t<li id=\"menu-item-19392\" class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-19392\"><a href=\"https:\/\/ducasseindustrial.com\/testcl\/arquitectura\/puertas-de-paso\" class=\"menu-link\">Puertas de paso<\/a><\/li>\n\t<li id=\"menu-item-19385\" class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-19385\"><a href=\"https:\/\/ducasseindustrial.com\/testcl\/arquitectura\/espacios-corporativos\" class=\"menu-link\">Espacios Corporativos<\/a><\/li>\n\t<li id=\"menu-item-19393\" class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-19393\"><a href=\"https:\/\/ducasseindustrial.com\/testcl\/arquitectura\/soluciones-bancarias\" class=\"menu-link\">Soluciones Bancarias<\/a><\/li>\n\t<li id=\"menu-item-19383\" class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-19383\"><a href=\"https:\/\/ducasseindustrial.com\/testcl\/arquitectura\/arquitectura-hospitalaria\" class=\"menu-link\">Arquitectura Hospitalaria<\/a><\/li>\n\t<li id=\"menu-item-19387\" class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-19387\"><a href=\"https:\/\/ducasseindustrial.com\/testcl\/arquitectura\/espacios-educativos\" class=\"menu-link\">Espacios Educativos<\/a><\/li>\n\t<li id=\"menu-item-19389\" class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-19389\"><a href=\"https:\/\/ducasseindustrial.com\/testcl\/arquitectura\/frentes-comerciales\" class=\"menu-link\">Frentes Comerciales<\/a><\/li>\n\t<li id=\"menu-item-19395\" class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-19395\"><a href=\"https:\/\/ducasseindustrial.com\/testcl\/arquitectura\/usos-multiples\" class=\"menu-link\">Usos M\u00faltiples<\/a><\/li>\n\t<li id=\"menu-item-19391\" class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-19391\"><a href=\"https:\/\/ducasseindustrial.com\/testcl\/arquitectura\/parasoles\" class=\"menu-link\">Parasoles<\/a><\/li>\n\t<li id=\"menu-item-19390\" class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-19390\"><a href=\"https:\/\/ducasseindustrial.com\/testcl\/arquitectura\/hoteleria\" class=\"menu-link\">Hoteler\u00eda<\/a><\/li>\n\t<li id=\"menu-item-19382\" class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-19382\"><a href=\"https:\/\/ducasseindustrial.com\/testcl\/arquitectura\/arquitectura-deportiva\" class=\"menu-link\">Arquitectura Deportiva<\/a><\/li>\n\t<li id=\"menu-item-19386\" class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-19386\"><a href=\"https:\/\/ducasseindustrial.com\/testcl\/arquitectura\/espacios-culturales\" class=\"menu-link\">Espacios Culturales<\/a><\/li>\n<\/ul>\n<\/li>\n<li id=\"menu-item-19388\" class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-19388\"><a href=\"https:\/\/ducasseindustrial.com\/testcl\/arquitectura\/faqs\" class=\"menu-link\">FAQs<\/a><\/li>\n<\/ul>                <button class=\"eael-advanced-menu-toggle\" aria-label=\"Essential Addons Toggle Menu\">\n                    <i aria-hidden=\"true\" class=\"fas fa-bars\"><\/i>                <\/button>\n            <\/div>\n            \t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-266d8a56 elementor-widget__width-initial elementor-hidden-desktop elementor-hidden-tablet eael_advanced_menu_hamburger_disable_selected_menu_no eael-advanced-menu-hamburger-align-right eael-advanced-menu--no eael-hamburger--tablet elementor-widget elementor-widget-eael-advanced-menu\" data-id=\"266d8a56\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"eael-advanced-menu.skin-two\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<style>\n                        @media screen and (max-width: 1024px) {\n                            .eael-hamburger--tablet {\n                                .eael-advanced-menu-horizontal,\n                                .eael-advanced-menu-vertical {\n                                    display: none;\n                                }\n                            }\n                            .eael-hamburger--tablet {\n                                .eael-advanced-menu-container .eael-advanced-menu-toggle {\n                                    display: block;\n                                }\n                            }\n                        }\n                    <\/style>            <div data-hamburger-icon=\"&lt;i aria-hidden=&quot;true&quot; class=&quot;fas fa-bars&quot;&gt;&lt;\/i&gt;\" data-indicator-class=\"&lt;i aria-hidden=&quot;true&quot; class=&quot;fas fa-angle-down&quot;&gt;&lt;\/i&gt;\" data-dropdown-indicator-class=\"&lt;i aria-hidden=&quot;true&quot; class=&quot;fas fa-angle-down&quot;&gt;&lt;\/i&gt;\" class=\"eael-advanced-menu-container eael-advanced-menu-align-center eael-advanced-menu-dropdown-align-left\" data-hamburger-breakpoints=\"{&quot;mobile&quot;:&quot;M\\u00f3vil vertical (&gt; 767px)&quot;,&quot;tablet&quot;:&quot;Tableta vertical (&gt; 1024px)&quot;,&quot;desktop&quot;:&quot;Desktop (&gt; 2400px)&quot;,&quot;none&quot;:&quot;None&quot;}\" data-hamburger-device=\"tablet\">\n                <ul id=\"menu-arquitectura-1\" class=\"eael-advanced-menu eael-advanced-menu-dropdown-animate-zoom-in eael-advanced-menu-indicator eael-advanced-menu-vertical\"><li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-19381\"><a href=\"https:\/\/ducasseindustrial.com\/testcl\/arquitectura\" class=\"menu-link\">Arquitectura<\/a><\/li>\n<li class=\"menu-item menu-item-type-custom menu-item-object-custom menu-item-has-children menu-item-2935\"><a aria-expanded=\"false\" href=\"#\" class=\"menu-link\">soluciones<\/a>\n<ul class=\"sub-menu\">\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-19394\"><a href=\"https:\/\/ducasseindustrial.com\/testcl\/arquitectura\/quinchos-y-galerias\" class=\"menu-link\">quinchos y galer\u00edas<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-19384\"><a href=\"https:\/\/ducasseindustrial.com\/testcl\/arquitectura\/division-de-ambientes\" class=\"menu-link\">divisi\u00f3n de ambientes<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-19392\"><a href=\"https:\/\/ducasseindustrial.com\/testcl\/arquitectura\/puertas-de-paso\" class=\"menu-link\">Puertas de paso<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-19385\"><a href=\"https:\/\/ducasseindustrial.com\/testcl\/arquitectura\/espacios-corporativos\" class=\"menu-link\">Espacios Corporativos<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-19393\"><a href=\"https:\/\/ducasseindustrial.com\/testcl\/arquitectura\/soluciones-bancarias\" class=\"menu-link\">Soluciones Bancarias<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-19383\"><a href=\"https:\/\/ducasseindustrial.com\/testcl\/arquitectura\/arquitectura-hospitalaria\" class=\"menu-link\">Arquitectura Hospitalaria<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-19387\"><a href=\"https:\/\/ducasseindustrial.com\/testcl\/arquitectura\/espacios-educativos\" class=\"menu-link\">Espacios Educativos<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-19389\"><a href=\"https:\/\/ducasseindustrial.com\/testcl\/arquitectura\/frentes-comerciales\" class=\"menu-link\">Frentes Comerciales<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-19395\"><a href=\"https:\/\/ducasseindustrial.com\/testcl\/arquitectura\/usos-multiples\" class=\"menu-link\">Usos M\u00faltiples<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-19391\"><a href=\"https:\/\/ducasseindustrial.com\/testcl\/arquitectura\/parasoles\" class=\"menu-link\">Parasoles<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-19390\"><a href=\"https:\/\/ducasseindustrial.com\/testcl\/arquitectura\/hoteleria\" class=\"menu-link\">Hoteler\u00eda<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-19382\"><a href=\"https:\/\/ducasseindustrial.com\/testcl\/arquitectura\/arquitectura-deportiva\" class=\"menu-link\">Arquitectura Deportiva<\/a><\/li>\n\t<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-19386\"><a href=\"https:\/\/ducasseindustrial.com\/testcl\/arquitectura\/espacios-culturales\" class=\"menu-link\">Espacios Culturales<\/a><\/li>\n<\/ul>\n<\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-19388\"><a href=\"https:\/\/ducasseindustrial.com\/testcl\/arquitectura\/faqs\" class=\"menu-link\">FAQs<\/a><\/li>\n<\/ul>                <button class=\"eael-advanced-menu-toggle\" aria-label=\"Essential Addons Toggle Menu\">\n                    <i aria-hidden=\"true\" class=\"fas fa-bars\"><\/i>                <\/button>\n            <\/div>\n            \t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-section elementor-inner-section elementor-element elementor-element-12e18af5 elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"12e18af5\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-3fc32064\" data-id=\"3fc32064\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-2cd0fc12 eael-dual-header-content-mobile-align-center elementor-widget elementor-widget-eael-dual-color-header\" data-id=\"2cd0fc12\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"eael-dual-color-header.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t<div class=\"eael-dual-header\">\n\t\t\t\t<span class=\"title eael-dch-title\"><span class=\"eael-dch-title-text eael-dch-title-lead lead solid-color\">\u00bfNecesit\u00e1s<\/span> <span class=\"eael-dch-title-text\">asesoramiento?<\/span><\/span>\t\t\t<\/div>\n\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4c22d574 elementor-button-align-start elementor-mobile-button-align-center elementor-widget elementor-widget-form\" data-id=\"4c22d574\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;step_next_label&quot;:&quot;Seguir&quot;,&quot;step_previous_label&quot;:&quot;Volver&quot;,&quot;button_width&quot;:&quot;50&quot;,&quot;step_type&quot;:&quot;number&quot;,&quot;step_icon_shape&quot;:&quot;circle&quot;}\" data-widget_type=\"form.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<form class=\"elementor-form\" method=\"post\" name=\"Arquitectura \" aria-label=\"Arquitectura \">\n\t\t\t<input type=\"hidden\" name=\"post_id\" value=\"19940\"\/>\n\t\t\t<input type=\"hidden\" name=\"form_id\" value=\"4c22d574\"\/>\n\t\t\t<input type=\"hidden\" name=\"referer_title\" value=\"Casa CG. | Test Chile\" \/>\n\n\t\t\t\t\t\t\t<input type=\"hidden\" name=\"queried_id\" value=\"19326\"\/>\n\t\t\t\n\t\t\t<div class=\"elementor-form-fields-wrapper elementor-labels-above\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-type-step elementor-field-group elementor-column elementor-field-group-field_46f88d1 elementor-col-100\">\n\t\t\t\t\t\t\t<div class=\"e-field-step elementor-hidden\" data-label=\"\" data-previousButton=\"\" data-nextButton=\"\" data-iconUrl=\"\" data-iconLibrary=\"fas fa-star\" data-icon=\"\" ><\/div>\n\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-type-text elementor-field-group elementor-column elementor-field-group-field_40b0d8d elementor-col-100 elementor-field-required elementor-mark-required\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<input size=\"1\" type=\"text\" name=\"form_fields[field_40b0d8d]\" id=\"form-field-field_40b0d8d\" class=\"elementor-field elementor-size-xs  elementor-field-textual\" placeholder=\"Nombre\" required=\"required\">\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-type-email elementor-field-group elementor-column elementor-field-group-email elementor-col-100 elementor-field-required elementor-mark-required\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<input size=\"1\" type=\"email\" name=\"form_fields[email]\" id=\"form-field-email\" class=\"elementor-field elementor-size-xs  elementor-field-textual\" placeholder=\"Email\" required=\"required\">\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-type-tel elementor-field-group elementor-column elementor-field-group-field_dcc9d34 elementor-col-100 elementor-field-required elementor-mark-required\">\n\t\t\t\t\t\t\t<input size=\"1\" type=\"tel\" name=\"form_fields[field_dcc9d34]\" id=\"form-field-field_dcc9d34\" class=\"elementor-field elementor-size-xs  elementor-field-textual\" placeholder=\"Tel\u00e9fono\" required=\"required\" pattern=\"[0-9()#&amp;+*-=.]+\" title=\"Only numbers and phone characters (#, -, *, etc) are accepted.\">\n\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-type-step elementor-field-group elementor-column elementor-field-group-field_15d101f elementor-col-100\">\n\t\t\t\t\t\t\t<div class=\"e-field-step elementor-hidden\" data-label=\"\" data-previousButton=\"\" data-nextButton=\"\" data-iconUrl=\"\" data-iconLibrary=\"fas fa-star\" data-icon=\"\" ><\/div>\n\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-type-select elementor-field-group elementor-column elementor-field-group-field_8fa11e1 elementor-col-100\">\n\t\t\t\t\t\t\t\t\t\t\t\t<label for=\"form-field-field_8fa11e1\" class=\"elementor-field-label\">\n\t\t\t\t\t\t\t\tTipo de emrpesa\t\t\t\t\t\t\t<\/label>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field elementor-select-wrapper remove-before \">\n\t\t\t<div class=\"select-caret-down-wrapper\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"eicon-caret-down\"><\/i>\t\t\t<\/div>\n\t\t\t<select name=\"form_fields[field_8fa11e1]\" id=\"form-field-field_8fa11e1\" class=\"elementor-field-textual elementor-size-xs\">\n\t\t\t\t\t\t\t\t\t<option value=\"Elija una opci\u00f3n -- - - &gt;\">Elija una opci\u00f3n -- - - &gt;<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"Estudio de Arquitectura\/Arquitecto\">Estudio de Arquitectura\/Arquitecto<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"Constructora \">Constructora <\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"Carpinter\u00eda de obra\/ Vidrier\u00eda\">Carpinter\u00eda de obra\/ Vidrier\u00eda<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"Carpinter\u00eda de obra\/ Madera\">Carpinter\u00eda de obra\/ Madera<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"Usuario final\">Usuario final<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"Otro\">Otro<\/option>\n\t\t\t\t\t\t\t<\/select>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-type-select elementor-field-group elementor-column elementor-field-group-field_3e7ed83 elementor-col-100\">\n\t\t\t\t\t\t\t\t\t\t\t\t<label for=\"form-field-field_3e7ed83\" class=\"elementor-field-label\">\n\t\t\t\t\t\t\t\t\u00bfC\u00f3mo nos conoci\u00f3?\t\t\t\t\t\t\t<\/label>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field elementor-select-wrapper remove-before \">\n\t\t\t<div class=\"select-caret-down-wrapper\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"eicon-caret-down\"><\/i>\t\t\t<\/div>\n\t\t\t<select name=\"form_fields[field_3e7ed83]\" id=\"form-field-field_3e7ed83\" class=\"elementor-field-textual elementor-size-xs\">\n\t\t\t\t\t\t\t\t\t<option value=\"Elija una opci\u00f3n -- - - &gt;\">Elija una opci\u00f3n -- - - &gt;<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"Google\">Google<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"Revista LIVING\">Revista LIVING<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"Otras Revista\">Otras Revista<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"Recomendaci\u00f3n\">Recomendaci\u00f3n<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"Redes sociales\">Redes sociales<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"Otro\">Otro<\/option>\n\t\t\t\t\t\t\t<\/select>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-type-step elementor-field-group elementor-column elementor-field-group-field_f625ad2 elementor-col-100\">\n\t\t\t\t\t\t\t<div class=\"e-field-step elementor-hidden\" data-label=\"\" data-previousButton=\"\" data-nextButton=\"\" data-iconUrl=\"\" data-iconLibrary=\"fas fa-star\" data-icon=\"\" ><\/div>\n\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-type-textarea elementor-field-group elementor-column elementor-field-group-field_023cbb7 elementor-col-100 elementor-field-required elementor-mark-required\">\n\t\t\t\t\t<textarea class=\"elementor-field-textual elementor-field  elementor-size-xs\" name=\"form_fields[field_023cbb7]\" id=\"form-field-field_023cbb7\" rows=\"4\" placeholder=\"Mensaje\" required=\"required\"><\/textarea>\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-group elementor-column elementor-field-type-submit elementor-col-50 e-form__buttons\">\n\t\t\t\t\t<button class=\"elementor-button elementor-size-md\" type=\"submit\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Enviar<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/button>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/form>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-29fc6e07\" data-id=\"29fc6e07\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;motion_fx_motion_fx_mouse&quot;:&quot;yes&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-545d7c46 elementor-widget elementor-widget-heading\" data-id=\"545d7c46\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\"><a href=\"https:\/\/ducasseindustrial.com\/testcl\/arquitectura\/https:\/\/ducasseindustrial.com\/testcl\/ar\/arquitectura\/division-de-ambientes\/\">DIVISI\u00d3N DE AMBIENTES<\/a><\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1e6b650c elementor-widget elementor-widget-heading\" data-id=\"1e6b650c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h1 class=\"elementor-heading-title elementor-size-default\">CASA A.<\/h1>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-622d974 elementor-widget elementor-widget-image\" data-id=\"622d974\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/ducasseindustrial.com\/testcl\/wp-content\/uploads\/sites\/27\/2020\/09\/mov-apilable.svg\" title=\"mov-apilable\" alt=\"mov-apilable\" loading=\"lazy\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-section elementor-inner-section elementor-element elementor-element-148436ee elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"148436ee\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-1336ca39\" data-id=\"1336ca39\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-29835342 elementor-widget elementor-widget-text-editor\" data-id=\"29835342\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><span style=\"color: #ff6414;\">NOMBRE DE LA OBRA:<br \/><\/span><span style=\"color: #ff6414;\">SISTEMA INSTALADO:<br \/><\/span><span style=\"color: #ff6414;\">UBICACI\u00d3N:<\/span><br \/><span style=\"color: #ff6414;\">A\u00d1O:<\/span><br \/><span style=\"color: #ff6414;\">ARQ. \/ ESTUDIO:<\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-46983e0a\" data-id=\"46983e0a\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-5beb9ac1 elementor-widget elementor-widget-text-editor\" data-id=\"5beb9ac1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Casa A.<br \/>Sigma VD y TWIN TEL VD<br \/>CABA, Argentina.<br \/>2015.<br \/>Arq. Vivian Avella Longhi.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<div class=\"elementor-element elementor-element-407d152b elementor-invisible elementor-widget elementor-widget-text-editor\" data-id=\"407d152b\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInUp&quot;,&quot;_animation_delay&quot;:50}\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><strong>Memoria Descriptiva<\/strong><\/p><p>El proyecto se propone dar soluci\u00f3n a una divisi\u00f3n interior de los espacios del \u00e1rea social, en un departamento en una zona residencial exclusiva de la zona de Parque Las Heras.<\/p><p>El sistemas SIGMA VD, compartimenta la zona de estar de grandes dimensiones (8 m de longitud) con una \u00e1rea social ganada al espacio de la terraza. En este sistema se realiz\u00f3 un dimensionado especial del \u00e1rea de apilado para que coincidiera con una mocheta perteneciente a la estructura del edificio, de manera tal que las hojas queden agrupadas y contenidas detr\u00e1s de la mencionada mocheta \u00a0en un apilado a 90\u00ba.<br \/>La puerta pivot del sistema sirve de paso para comunicar los espacios cuando el sistema se encuentra cerrado.<\/p><p>El trabajo de garganta en cielorraso, involucr\u00f3 un trabajo de dise\u00f1o especial coordinado con el estudio.<\/p><p>Un sector m\u00e1s peque\u00f1o de 3,30 de ancho, consistente en el escritorio del propietario, pod\u00eda integrarse o apartarse del \u00e1rea social a trav\u00e9s de un sistema TWIN telesc\u00f3pico para vidrio. Este sistema se encuentra tras un tabique en una misma l\u00ednea con el sistema SIGMA VD, para lo cual se unificaron las alturas de los z\u00f3calos superiores de los mismos.<\/p><p>\u00a0<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-section elementor-inner-section elementor-element elementor-element-58654826 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"58654826\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-1bd7e50b\" data-id=\"1bd7e50b\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-2930546f bdt-navigation-type-arrows elementor-widget elementor-widget-bdt-advanced-image-gallery\" data-id=\"2930546f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"bdt-advanced-image-gallery.bdt-carousel\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\" bdt-arrows-align-center \" data-bdt-slider=\"{&quot;autoplay&quot;:true,&quot;autoplay-interval&quot;:7000,&quot;finite&quot;:true,&quot;pause-on-hover&quot;:true,&quot;center&quot;:false,&quot;sets&quot;:false}\">\r\n\t\t\t<div id=\"bdt-avdg-2930546f\" class=\"bdt-advanced-image-gallery bdt-skin-carousel bdt-grid bdt-grid-small bdt-slider-items bdt-child-width-1- bdt-child-width-1-@s bdt-child-width-1-4@m\" data-bdt-grid=\"\" data-bdt-lightbox=\"animation: slide\">\r\n\t\t\t\t\t\t\r\n\t\t\t<div class=\"bdt-gallery-item bdt-transition-toggle\">\r\n\t\t\t\t<div class=\"bdt-advanced-image-gallery-inner bdt-image-mask\">\r\n\t\t\t\t\t<div class=\"bdt-gallery-thumbnail bdt-transition-toggle\">\n\t\t\t<img decoding=\"async\"  src=\"https:\/\/ducasseindustrial.com\/testcl\/wp-content\/uploads\/sites\/27\/2020\/09\/03-div-sigma-vd-5-300x300.jpg\" alt=\"03-div-sigma-vd (5)\" class=\"jgalleryImage\">\n\t\t<\/div>\t\t<div class=\"bdt-position-cover bdt-overlay bdt-overlay-default bdt-transition-fade\">\n\t\t\t<div class=\"bdt-advanced-image-gallery-content\">\n\t\t\t\t<div class=\"bdt-advanced-image-gallery-content-inner\">\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"bdt-flex-inline bdt-gallery-item-link-wrapper\">\n\t\t\t\t\t\t\t<a class=\"bdt-gallery-item-link elementor-clickable icon-type-icon\" data-elementor-open-lightbox=\"no\" data-caption=\"\" href=\"https:\/\/ducasseindustrial.com\/testcl\/wp-content\/uploads\/sites\/27\/2020\/09\/03-div-sigma-vd-5.jpg\">\n\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span>\n\t\t\t\t\t\t\t\t\t\t\t<i class=\"ep-plus-2\"><\/i>\n\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\r\n\r\n\t\t\t\t\t\t\t<\/div>\r\n\r\n\t\t\t\t\t\t\r\n\t\t\t<div class=\"bdt-gallery-item bdt-transition-toggle\">\r\n\t\t\t\t<div class=\"bdt-advanced-image-gallery-inner bdt-image-mask\">\r\n\t\t\t\t\t<div class=\"bdt-gallery-thumbnail bdt-transition-toggle\">\n\t\t\t<img decoding=\"async\"  src=\"https:\/\/ducasseindustrial.com\/testcl\/wp-content\/uploads\/sites\/27\/2020\/09\/03-div-sigma-vd-4-300x300.jpg\" alt=\"03-div-sigma-vd (4)\" class=\"jgalleryImage\">\n\t\t<\/div>\t\t<div class=\"bdt-position-cover bdt-overlay bdt-overlay-default bdt-transition-fade\">\n\t\t\t<div class=\"bdt-advanced-image-gallery-content\">\n\t\t\t\t<div class=\"bdt-advanced-image-gallery-content-inner\">\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"bdt-flex-inline bdt-gallery-item-link-wrapper\">\n\t\t\t\t\t\t\t<a class=\"bdt-gallery-item-link elementor-clickable icon-type-icon\" data-elementor-open-lightbox=\"no\" data-caption=\"\" href=\"https:\/\/ducasseindustrial.com\/testcl\/wp-content\/uploads\/sites\/27\/2020\/09\/03-div-sigma-vd-4.jpg\">\n\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span>\n\t\t\t\t\t\t\t\t\t\t\t<i class=\"ep-plus-2\"><\/i>\n\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\r\n\r\n\t\t\t\t\t\t\t<\/div>\r\n\r\n\t\t\t\t\t\t\r\n\t\t\t<div class=\"bdt-gallery-item bdt-transition-toggle\">\r\n\t\t\t\t<div class=\"bdt-advanced-image-gallery-inner bdt-image-mask\">\r\n\t\t\t\t\t<div class=\"bdt-gallery-thumbnail bdt-transition-toggle\">\n\t\t\t<img decoding=\"async\"  src=\"https:\/\/ducasseindustrial.com\/testcl\/wp-content\/uploads\/sites\/27\/2020\/09\/03-div-sigma-vd-3-300x300.jpg\" alt=\"03-div-sigma-vd (3)\" class=\"jgalleryImage\">\n\t\t<\/div>\t\t<div class=\"bdt-position-cover bdt-overlay bdt-overlay-default bdt-transition-fade\">\n\t\t\t<div class=\"bdt-advanced-image-gallery-content\">\n\t\t\t\t<div class=\"bdt-advanced-image-gallery-content-inner\">\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"bdt-flex-inline bdt-gallery-item-link-wrapper\">\n\t\t\t\t\t\t\t<a class=\"bdt-gallery-item-link elementor-clickable icon-type-icon\" data-elementor-open-lightbox=\"no\" data-caption=\"\" href=\"https:\/\/ducasseindustrial.com\/testcl\/wp-content\/uploads\/sites\/27\/2020\/09\/03-div-sigma-vd-3.jpg\">\n\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span>\n\t\t\t\t\t\t\t\t\t\t\t<i class=\"ep-plus-2\"><\/i>\n\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\r\n\r\n\t\t\t\t\t\t\t<\/div>\r\n\r\n\t\t\t\t\t\t\r\n\t\t\t<div class=\"bdt-gallery-item bdt-transition-toggle\">\r\n\t\t\t\t<div class=\"bdt-advanced-image-gallery-inner bdt-image-mask\">\r\n\t\t\t\t\t<div class=\"bdt-gallery-thumbnail bdt-transition-toggle\">\n\t\t\t<img decoding=\"async\"  src=\"https:\/\/ducasseindustrial.com\/testcl\/wp-content\/uploads\/sites\/27\/2020\/09\/03-div-sigma-vd-2-300x300.jpg\" alt=\"03-div-sigma-vd (2)\" class=\"jgalleryImage\">\n\t\t<\/div>\t\t<div class=\"bdt-position-cover bdt-overlay bdt-overlay-default bdt-transition-fade\">\n\t\t\t<div class=\"bdt-advanced-image-gallery-content\">\n\t\t\t\t<div class=\"bdt-advanced-image-gallery-content-inner\">\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"bdt-flex-inline bdt-gallery-item-link-wrapper\">\n\t\t\t\t\t\t\t<a class=\"bdt-gallery-item-link elementor-clickable icon-type-icon\" data-elementor-open-lightbox=\"no\" data-caption=\"\" href=\"https:\/\/ducasseindustrial.com\/testcl\/wp-content\/uploads\/sites\/27\/2020\/09\/03-div-sigma-vd-2.jpg\">\n\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span>\n\t\t\t\t\t\t\t\t\t\t\t<i class=\"ep-plus-2\"><\/i>\n\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\r\n\r\n\t\t\t\t\t\t\t<\/div>\r\n\r\n\t\t\t\t\t\t\r\n\t\t\t<div class=\"bdt-gallery-item bdt-transition-toggle\">\r\n\t\t\t\t<div class=\"bdt-advanced-image-gallery-inner bdt-image-mask\">\r\n\t\t\t\t\t<div class=\"bdt-gallery-thumbnail bdt-transition-toggle\">\n\t\t\t<img decoding=\"async\"  src=\"https:\/\/ducasseindustrial.com\/testcl\/wp-content\/uploads\/sites\/27\/2020\/09\/03-div-sigma-vd-6-300x300.jpg\" alt=\"03-div-sigma-vd (6)\" class=\"jgalleryImage\">\n\t\t<\/div>\t\t<div class=\"bdt-position-cover bdt-overlay bdt-overlay-default bdt-transition-fade\">\n\t\t\t<div class=\"bdt-advanced-image-gallery-content\">\n\t\t\t\t<div class=\"bdt-advanced-image-gallery-content-inner\">\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"bdt-flex-inline bdt-gallery-item-link-wrapper\">\n\t\t\t\t\t\t\t<a class=\"bdt-gallery-item-link elementor-clickable icon-type-icon\" data-elementor-open-lightbox=\"no\" data-caption=\"\" href=\"https:\/\/ducasseindustrial.com\/testcl\/wp-content\/uploads\/sites\/27\/2020\/09\/03-div-sigma-vd-6.jpg\">\n\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span>\n\t\t\t\t\t\t\t\t\t\t\t<i class=\"ep-plus-2\"><\/i>\n\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\r\n\r\n\t\t\t\t\t\t\t<\/div>\r\n\r\n\t\t\t\t\t\t\r\n\t\t\t<div class=\"bdt-gallery-item bdt-transition-toggle\">\r\n\t\t\t\t<div class=\"bdt-advanced-image-gallery-inner bdt-image-mask\">\r\n\t\t\t\t\t<div class=\"bdt-gallery-thumbnail bdt-transition-toggle\">\n\t\t\t<img decoding=\"async\"  src=\"https:\/\/ducasseindustrial.com\/testcl\/wp-content\/uploads\/sites\/27\/2020\/09\/03-div-sigma-vd-1-300x300.jpg\" alt=\"03-div-sigma-vd (1)\" class=\"jgalleryImage\">\n\t\t<\/div>\t\t<div class=\"bdt-position-cover bdt-overlay bdt-overlay-default bdt-transition-fade\">\n\t\t\t<div class=\"bdt-advanced-image-gallery-content\">\n\t\t\t\t<div class=\"bdt-advanced-image-gallery-content-inner\">\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"bdt-flex-inline bdt-gallery-item-link-wrapper\">\n\t\t\t\t\t\t\t<a class=\"bdt-gallery-item-link elementor-clickable icon-type-icon\" data-elementor-open-lightbox=\"no\" data-caption=\"\" href=\"https:\/\/ducasseindustrial.com\/testcl\/wp-content\/uploads\/sites\/27\/2020\/09\/03-div-sigma-vd-1.jpg\">\n\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span>\n\t\t\t\t\t\t\t\t\t\t\t<i class=\"ep-plus-2\"><\/i>\n\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\r\n\r\n\t\t\t\t\t\t\t<\/div>\r\n\r\n\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t<div class=\"bdt-position-z-index bdt-position-center bdt-visible@m\">\r\n\t\t\t<div class=\"bdt-arrows-container bdt-slidenav-container\">\r\n\t\t\t\t<a href=\"\" class=\"bdt-navigation-prev bdt-slidenav-previous bdt-slidenav\" data-bdt-slider-item=\"previous\">\r\n\t\t\t\t\t<i class=\"ep-arrow-left-5\" aria-hidden=\"true\"><\/i>\r\n\t\t\t\t<\/a>\r\n\t\t\t\t<a href=\"\" class=\"bdt-navigation-next bdt-slidenav-next bdt-slidenav\" data-bdt-slider-item=\"next\">\r\n\t\t\t\t\t<i class=\"ep-arrow-right-5\" aria-hidden=\"true\"><\/i>\r\n\t\t\t\t<\/a>\r\n\t\t\t<\/div>\r\n\t\t<\/div>\r\n\t\t\t\t\t<\/div>\r\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section data-particle_enable=\"false\" data-particle-mobile-disabled=\"false\" class=\"elementor-section elementor-top-section elementor-element elementor-element-499080c0 elementor-section-height-min-height elementor-section-boxed elementor-section-height-default elementor-section-items-middle\" data-id=\"499080c0\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-66d26104\" data-id=\"66d26104\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>DIVISI\u00d3N DE AMBIENTES CASA A. NOMBRE DE LA OBRA:SISTEMA INSTALADO:UBICACI\u00d3N:A\u00d1O:ARQ. \/ ESTUDIO: Casa A.Sigma VD y TWIN TEL VDCABA, Argentina.2015.Arq. Vivian Avella Longhi. Memoria Descriptiva El proyecto se propone dar soluci\u00f3n a una divisi\u00f3n interior de los espacios del \u00e1rea social, en un departamento en una zona residencial exclusiva de la zona de Parque Las [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":3098,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"elementor_header_footer","format":"standard","meta":{"_uag_custom_page_level_css":"","site-sidebar-layout":"no-sidebar","site-content-layout":"page-builder","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"disabled","ast-breadcrumbs-content":"","ast-featured-img":"disabled","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"default","adv-header-id-meta":"","stick-header-meta":"default","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"default","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"_vp_format_video_url":"","_vp_image_focal_point":[],"footnotes":""},"portfolio_category":[362],"portfolio_tag":[389],"class_list":["post-3096","portfolio","type-portfolio","status-publish","format-standard","has-post-thumbnail","hentry","portfolio_category-apilable","portfolio_tag-apilable"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 5.0.0.1 - aioseo.com -->\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"user\"\/>\n\t<link rel=\"canonical\" href=\"https:\/\/ducasseindustrial.com\/testcl\/portfolio\/casa-a-2\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 5.0.0.1\" \/>\n\t\t<meta property=\"og:locale\" content=\"es_ES\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Test Chile | Somos una empresa Chilena, con m\u00e1s de 50 a\u00f1os de experiencia en la fabricaci\u00f3n de herrajes para la industria del mueble y la construcci\u00f3n, satisfaciendo necesidades tanto en mercados locales como extranjeros.\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Casa A. | Test Chile\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/ducasseindustrial.com\/testcl\/portfolio\/casa-a-2\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/ducasseindustrial.com\/testcl\/wp-content\/uploads\/sites\/27\/2024\/04\/logo_web_ducasse.svg\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/ducasseindustrial.com\/testcl\/wp-content\/uploads\/sites\/27\/2024\/04\/logo_web_ducasse.svg\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2020-09-07T16:58:50+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2020-11-12T15:13:42+00:00\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Casa A. | Test Chile\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/ducasseindustrial.com\/testcl\/wp-content\/uploads\/sites\/27\/2024\/04\/logo_web_ducasse.svg\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/ducasseindustrial.com\\\/testcl\\\/portfolio\\\/casa-a-2#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ducasseindustrial.com\\\/testcl#listItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\\\/\\\/ducasseindustrial.com\\\/testcl\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ducasseindustrial.com\\\/testcl\\\/portfolio#listItem\",\"name\":\"Portfolio\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ducasseindustrial.com\\\/testcl\\\/portfolio#listItem\",\"position\":2,\"name\":\"Portfolio\",\"item\":\"https:\\\/\\\/ducasseindustrial.com\\\/testcl\\\/portfolio\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ducasseindustrial.com\\\/testcl\\\/archivo\\\/portfolio-category\\\/divisiones-de-ambiente#listItem\",\"name\":\"Divisiones de Ambiente\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ducasseindustrial.com\\\/testcl#listItem\",\"name\":\"Inicio\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ducasseindustrial.com\\\/testcl\\\/archivo\\\/portfolio-category\\\/divisiones-de-ambiente#listItem\",\"position\":3,\"name\":\"Divisiones de Ambiente\",\"item\":\"https:\\\/\\\/ducasseindustrial.com\\\/testcl\\\/archivo\\\/portfolio-category\\\/divisiones-de-ambiente\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ducasseindustrial.com\\\/testcl\\\/archivo\\\/portfolio-category\\\/apilable#listItem\",\"name\":\"Apilable\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ducasseindustrial.com\\\/testcl\\\/portfolio#listItem\",\"name\":\"Portfolio\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ducasseindustrial.com\\\/testcl\\\/archivo\\\/portfolio-category\\\/apilable#listItem\",\"position\":4,\"name\":\"Apilable\",\"item\":\"https:\\\/\\\/ducasseindustrial.com\\\/testcl\\\/archivo\\\/portfolio-category\\\/apilable\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ducasseindustrial.com\\\/testcl\\\/portfolio\\\/casa-a-2#listItem\",\"name\":\"Casa A.\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ducasseindustrial.com\\\/testcl\\\/archivo\\\/portfolio-category\\\/divisiones-de-ambiente#listItem\",\"name\":\"Divisiones de Ambiente\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ducasseindustrial.com\\\/testcl\\\/portfolio\\\/casa-a-2#listItem\",\"position\":5,\"name\":\"Casa A.\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ducasseindustrial.com\\\/testcl\\\/archivo\\\/portfolio-category\\\/apilable#listItem\",\"name\":\"Apilable\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/ducasseindustrial.com\\\/testcl\\\/#organization\",\"name\":\"Test Chile\",\"description\":\"Somos una empresa Chilena, con m\\u00e1s de 50 a\\u00f1os de experiencia en la fabricaci\\u00f3n de herrajes para la industria del mueble y la construcci\\u00f3n, satisfaciendo necesidades tanto en mercados locales como extranjeros.\",\"url\":\"https:\\\/\\\/ducasseindustrial.com\\\/testcl\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/ducasseindustrial.com\\\/testcl\\\/wp-content\\\/uploads\\\/sites\\\/27\\\/2024\\\/04\\\/logo_web_ducasse.svg\",\"@id\":\"https:\\\/\\\/ducasseindustrial.com\\\/testcl\\\/portfolio\\\/casa-a-2\\\/#organizationLogo\",\"width\":1004,\"height\":294},\"image\":{\"@id\":\"https:\\\/\\\/ducasseindustrial.com\\\/testcl\\\/portfolio\\\/casa-a-2\\\/#organizationLogo\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/ducasseindustrial.com\\\/testcl\\\/archivo\\\/author\\\/user#author\",\"url\":\"https:\\\/\\\/ducasseindustrial.com\\\/testcl\\\/archivo\\\/author\\\/user\",\"name\":\"user\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/ducasseindustrial.com\\\/testcl\\\/portfolio\\\/casa-a-2#authorImage\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/e0057e34c56ef6dca6089650e4668a215ff462ec200b8030e4df3adf4bdc9df4?s=96&d=mm&r=g\",\"width\":96,\"height\":96,\"caption\":\"user\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/ducasseindustrial.com\\\/testcl\\\/portfolio\\\/casa-a-2#webpage\",\"url\":\"https:\\\/\\\/ducasseindustrial.com\\\/testcl\\\/portfolio\\\/casa-a-2#webpage\",\"name\":\"Casa A. | Test Chile\",\"inLanguage\":\"es-CL\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/ducasseindustrial.com\\\/testcl\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/ducasseindustrial.com\\\/testcl\\\/portfolio\\\/casa-a-2#webpage\"},\"author\":{\"@id\":\"https:\\\/\\\/ducasseindustrial.com\\\/testcl\\\/archivo\\\/author\\\/user#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/ducasseindustrial.com\\\/testcl\\\/archivo\\\/author\\\/user#author\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/ducasseindustrial.com\\\/testcl\\\/wp-content\\\/uploads\\\/sites\\\/27\\\/2020\\\/09\\\/03-division-ambientes.jpg\",\"@id\":\"https:\\\/\\\/ducasseindustrial.com\\\/testcl\\\/portfolio\\\/casa-a-2\\\/#mainImage\",\"width\":900,\"height\":600},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/ducasseindustrial.com\\\/testcl\\\/portfolio\\\/casa-a-2#mainImage\"},\"datePublished\":\"2020-09-07T12:58:50-04:00\",\"dateModified\":\"2020-11-12T11:13:42-04:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/ducasseindustrial.com\\\/testcl\\\/#website\",\"url\":\"https:\\\/\\\/ducasseindustrial.com\\\/testcl\\\/\",\"name\":\"Test Chile\",\"description\":\"Somos una empresa Chilena, con m\\u00e1s de 50 a\\u00f1os de experiencia en la fabricaci\\u00f3n de herrajes para la industria del mueble y la construcci\\u00f3n, satisfaciendo necesidades tanto en mercados locales como extranjeros.\",\"inLanguage\":\"es-CL\",\"publisher\":{\"@id\":\"https:\\\/\\\/ducasseindustrial.com\\\/testcl\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"Casa A. | Test Chile","description":"","canonical_url":"https:\/\/ducasseindustrial.com\/testcl\/portfolio\/casa-a-2","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BreadcrumbList","@id":"https:\/\/ducasseindustrial.com\/testcl\/portfolio\/casa-a-2#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/ducasseindustrial.com\/testcl#listItem","position":1,"name":"Inicio","item":"https:\/\/ducasseindustrial.com\/testcl","nextItem":{"@type":"ListItem","@id":"https:\/\/ducasseindustrial.com\/testcl\/portfolio#listItem","name":"Portfolio"}},{"@type":"ListItem","@id":"https:\/\/ducasseindustrial.com\/testcl\/portfolio#listItem","position":2,"name":"Portfolio","item":"https:\/\/ducasseindustrial.com\/testcl\/portfolio","nextItem":{"@type":"ListItem","@id":"https:\/\/ducasseindustrial.com\/testcl\/archivo\/portfolio-category\/divisiones-de-ambiente#listItem","name":"Divisiones de Ambiente"},"previousItem":{"@type":"ListItem","@id":"https:\/\/ducasseindustrial.com\/testcl#listItem","name":"Inicio"}},{"@type":"ListItem","@id":"https:\/\/ducasseindustrial.com\/testcl\/archivo\/portfolio-category\/divisiones-de-ambiente#listItem","position":3,"name":"Divisiones de Ambiente","item":"https:\/\/ducasseindustrial.com\/testcl\/archivo\/portfolio-category\/divisiones-de-ambiente","nextItem":{"@type":"ListItem","@id":"https:\/\/ducasseindustrial.com\/testcl\/archivo\/portfolio-category\/apilable#listItem","name":"Apilable"},"previousItem":{"@type":"ListItem","@id":"https:\/\/ducasseindustrial.com\/testcl\/portfolio#listItem","name":"Portfolio"}},{"@type":"ListItem","@id":"https:\/\/ducasseindustrial.com\/testcl\/archivo\/portfolio-category\/apilable#listItem","position":4,"name":"Apilable","item":"https:\/\/ducasseindustrial.com\/testcl\/archivo\/portfolio-category\/apilable","nextItem":{"@type":"ListItem","@id":"https:\/\/ducasseindustrial.com\/testcl\/portfolio\/casa-a-2#listItem","name":"Casa A."},"previousItem":{"@type":"ListItem","@id":"https:\/\/ducasseindustrial.com\/testcl\/archivo\/portfolio-category\/divisiones-de-ambiente#listItem","name":"Divisiones de Ambiente"}},{"@type":"ListItem","@id":"https:\/\/ducasseindustrial.com\/testcl\/portfolio\/casa-a-2#listItem","position":5,"name":"Casa A.","previousItem":{"@type":"ListItem","@id":"https:\/\/ducasseindustrial.com\/testcl\/archivo\/portfolio-category\/apilable#listItem","name":"Apilable"}}]},{"@type":"Organization","@id":"https:\/\/ducasseindustrial.com\/testcl\/#organization","name":"Test Chile","description":"Somos una empresa Chilena, con m\u00e1s de 50 a\u00f1os de experiencia en la fabricaci\u00f3n de herrajes para la industria del mueble y la construcci\u00f3n, satisfaciendo necesidades tanto en mercados locales como extranjeros.","url":"https:\/\/ducasseindustrial.com\/testcl\/","logo":{"@type":"ImageObject","url":"https:\/\/ducasseindustrial.com\/testcl\/wp-content\/uploads\/sites\/27\/2024\/04\/logo_web_ducasse.svg","@id":"https:\/\/ducasseindustrial.com\/testcl\/portfolio\/casa-a-2\/#organizationLogo","width":1004,"height":294},"image":{"@id":"https:\/\/ducasseindustrial.com\/testcl\/portfolio\/casa-a-2\/#organizationLogo"}},{"@type":"Person","@id":"https:\/\/ducasseindustrial.com\/testcl\/archivo\/author\/user#author","url":"https:\/\/ducasseindustrial.com\/testcl\/archivo\/author\/user","name":"user","image":{"@type":"ImageObject","@id":"https:\/\/ducasseindustrial.com\/testcl\/portfolio\/casa-a-2#authorImage","url":"https:\/\/secure.gravatar.com\/avatar\/e0057e34c56ef6dca6089650e4668a215ff462ec200b8030e4df3adf4bdc9df4?s=96&d=mm&r=g","width":96,"height":96,"caption":"user"}},{"@type":"WebPage","@id":"https:\/\/ducasseindustrial.com\/testcl\/portfolio\/casa-a-2#webpage","url":"https:\/\/ducasseindustrial.com\/testcl\/portfolio\/casa-a-2#webpage","name":"Casa A. | Test Chile","inLanguage":"es-CL","isPartOf":{"@id":"https:\/\/ducasseindustrial.com\/testcl\/#website"},"breadcrumb":{"@id":"https:\/\/ducasseindustrial.com\/testcl\/portfolio\/casa-a-2#webpage"},"author":{"@id":"https:\/\/ducasseindustrial.com\/testcl\/archivo\/author\/user#author"},"creator":{"@id":"https:\/\/ducasseindustrial.com\/testcl\/archivo\/author\/user#author"},"image":{"@type":"ImageObject","url":"https:\/\/ducasseindustrial.com\/testcl\/wp-content\/uploads\/sites\/27\/2020\/09\/03-division-ambientes.jpg","@id":"https:\/\/ducasseindustrial.com\/testcl\/portfolio\/casa-a-2\/#mainImage","width":900,"height":600},"primaryImageOfPage":{"@id":"https:\/\/ducasseindustrial.com\/testcl\/portfolio\/casa-a-2#mainImage"},"datePublished":"2020-09-07T12:58:50-04:00","dateModified":"2020-11-12T11:13:42-04:00"},{"@type":"WebSite","@id":"https:\/\/ducasseindustrial.com\/testcl\/#website","url":"https:\/\/ducasseindustrial.com\/testcl\/","name":"Test Chile","description":"Somos una empresa Chilena, con m\u00e1s de 50 a\u00f1os de experiencia en la fabricaci\u00f3n de herrajes para la industria del mueble y la construcci\u00f3n, satisfaciendo necesidades tanto en mercados locales como extranjeros.","inLanguage":"es-CL","publisher":{"@id":"https:\/\/ducasseindustrial.com\/testcl\/#organization"}}]},"og:locale":"es_ES","og:site_name":"Test Chile | Somos una empresa Chilena, con m\u00e1s de 50 a\u00f1os de experiencia en la fabricaci\u00f3n de herrajes para la industria del mueble y la construcci\u00f3n, satisfaciendo necesidades tanto en mercados locales como extranjeros.","og:type":"article","og:title":"Casa A. | Test Chile","og:url":"https:\/\/ducasseindustrial.com\/testcl\/portfolio\/casa-a-2","og:image":"https:\/\/ducasseindustrial.com\/testcl\/wp-content\/uploads\/sites\/27\/2024\/04\/logo_web_ducasse.svg","og:image:secure_url":"https:\/\/ducasseindustrial.com\/testcl\/wp-content\/uploads\/sites\/27\/2024\/04\/logo_web_ducasse.svg","article:published_time":"2020-09-07T16:58:50+00:00","article:modified_time":"2020-11-12T15:13:42+00:00","twitter:card":"summary","twitter:title":"Casa A. | Test Chile","twitter:image":"https:\/\/ducasseindustrial.com\/testcl\/wp-content\/uploads\/sites\/27\/2024\/04\/logo_web_ducasse.svg"},"aioseo_meta_data":{"post_id":"3096","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":null,"isEnabled":true},"graphs":[]},"schema_type":null,"schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","priority":null,"frequency":null,"local_seo":null,"breadcrumb_settings":null,"limit_modified_date":false,"ai":null,"created":"2021-03-01 10:55:38","updated":"2025-11-01 10:39:37","focus_keyword":null,"additional_keywords":null,"truseo_locale":null,"seo_analyzer_scan_date":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/ducasseindustrial.com\/testcl\" title=\"Inicio\">Inicio<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">\u00bb<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/ducasseindustrial.com\/testcl\/portfolio\" title=\"Portfolio\">Portfolio<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">\u00bb<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/ducasseindustrial.com\/testcl\/archivo\/portfolio-category\/divisiones-de-ambiente\" title=\"Divisiones de Ambiente\">Divisiones de Ambiente<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">\u00bb<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/ducasseindustrial.com\/testcl\/archivo\/portfolio-category\/apilable\" title=\"Apilable\">Apilable<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">\u00bb<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tCasa A.\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Inicio","link":"https:\/\/ducasseindustrial.com\/testcl"},{"label":"Portfolio","link":"https:\/\/ducasseindustrial.com\/testcl\/portfolio"},{"label":"Divisiones de Ambiente","link":"https:\/\/ducasseindustrial.com\/testcl\/archivo\/portfolio-category\/divisiones-de-ambiente"},{"label":"Apilable","link":"https:\/\/ducasseindustrial.com\/testcl\/archivo\/portfolio-category\/apilable"},{"label":"Casa A.","link":"https:\/\/ducasseindustrial.com\/testcl\/portfolio\/casa-a-2"}],"uagb_featured_image_src":{"full":["https:\/\/ducasseindustrial.com\/testcl\/wp-content\/uploads\/sites\/27\/2020\/09\/03-division-ambientes.jpg",900,600,false],"thumbnail":["https:\/\/ducasseindustrial.com\/testcl\/wp-content\/uploads\/sites\/27\/2020\/09\/03-division-ambientes-300x300.jpg",300,300,true],"medium":["https:\/\/ducasseindustrial.com\/testcl\/wp-content\/uploads\/sites\/27\/2020\/09\/03-division-ambientes-600x400.jpg",600,400,true],"medium_large":["https:\/\/ducasseindustrial.com\/testcl\/wp-content\/uploads\/sites\/27\/2020\/09\/03-division-ambientes-768x512.jpg",768,512,true],"large":["https:\/\/ducasseindustrial.com\/testcl\/wp-content\/uploads\/sites\/27\/2020\/09\/03-division-ambientes.jpg",900,600,false],"1536x1536":["https:\/\/ducasseindustrial.com\/testcl\/wp-content\/uploads\/sites\/27\/2020\/09\/03-division-ambientes.jpg",900,600,false],"2048x2048":["https:\/\/ducasseindustrial.com\/testcl\/wp-content\/uploads\/sites\/27\/2020\/09\/03-division-ambientes.jpg",900,600,false],"vp_sm":["https:\/\/ducasseindustrial.com\/testcl\/wp-content\/uploads\/sites\/27\/2020\/09\/03-division-ambientes-500x333.jpg",500,333,true],"vp_md":["https:\/\/ducasseindustrial.com\/testcl\/wp-content\/uploads\/sites\/27\/2020\/09\/03-division-ambientes-800x533.jpg",800,533,true],"vp_lg":["https:\/\/ducasseindustrial.com\/testcl\/wp-content\/uploads\/sites\/27\/2020\/09\/03-division-ambientes.jpg",900,600,false],"vp_xl":["https:\/\/ducasseindustrial.com\/testcl\/wp-content\/uploads\/sites\/27\/2020\/09\/03-division-ambientes.jpg",900,600,false],"vp_sm_popup":["https:\/\/ducasseindustrial.com\/testcl\/wp-content\/uploads\/sites\/27\/2020\/09\/03-division-ambientes-500x333.jpg",500,333,true],"vp_md_popup":["https:\/\/ducasseindustrial.com\/testcl\/wp-content\/uploads\/sites\/27\/2020\/09\/03-division-ambientes-800x533.jpg",800,533,true],"vp_xl_popup":["https:\/\/ducasseindustrial.com\/testcl\/wp-content\/uploads\/sites\/27\/2020\/09\/03-division-ambientes.jpg",900,600,false],"woocommerce_thumbnail":["https:\/\/ducasseindustrial.com\/testcl\/wp-content\/uploads\/sites\/27\/2020\/09\/03-division-ambientes-300x300.jpg",300,300,true],"woocommerce_single":["https:\/\/ducasseindustrial.com\/testcl\/wp-content\/uploads\/sites\/27\/2020\/09\/03-division-ambientes.jpg",900,600,false],"woocommerce_gallery_thumbnail":["https:\/\/ducasseindustrial.com\/testcl\/wp-content\/uploads\/sites\/27\/2020\/09\/03-division-ambientes-100x100.jpg",100,100,true],"variation_swatches_image_size":["https:\/\/ducasseindustrial.com\/testcl\/wp-content\/uploads\/sites\/27\/2020\/09\/03-division-ambientes.jpg",50,33,false],"variation_swatches_tooltip_size":["https:\/\/ducasseindustrial.com\/testcl\/wp-content\/uploads\/sites\/27\/2020\/09\/03-division-ambientes.jpg",100,67,false]},"uagb_author_info":{"display_name":"user","author_link":"https:\/\/ducasseindustrial.com\/testcl\/archivo\/author\/user"},"uagb_comment_info":0,"uagb_excerpt":"DIVISI\u00d3N DE AMBIENTES CASA A. NOMBRE DE LA OBRA:SISTEMA INSTALADO:UBICACI\u00d3N:A\u00d1O:ARQ. \/ ESTUDIO: Casa A.Sigma VD y TWIN TEL VDCABA, Argentina.2015.Arq. Vivian Avella Longhi. Memoria Descriptiva El proyecto se propone dar soluci\u00f3n a una divisi\u00f3n interior de los espacios del \u00e1rea social, en un departamento en una zona residencial exclusiva de la zona de Parque Las&hellip;","_links":{"self":[{"href":"https:\/\/ducasseindustrial.com\/testcl\/wp-json\/wp\/v2\/portfolio\/3096","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ducasseindustrial.com\/testcl\/wp-json\/wp\/v2\/portfolio"}],"about":[{"href":"https:\/\/ducasseindustrial.com\/testcl\/wp-json\/wp\/v2\/types\/portfolio"}],"author":[{"embeddable":true,"href":"https:\/\/ducasseindustrial.com\/testcl\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/ducasseindustrial.com\/testcl\/wp-json\/wp\/v2\/comments?post=3096"}],"version-history":[{"count":3,"href":"https:\/\/ducasseindustrial.com\/testcl\/wp-json\/wp\/v2\/portfolio\/3096\/revisions"}],"predecessor-version":[{"id":20050,"href":"https:\/\/ducasseindustrial.com\/testcl\/wp-json\/wp\/v2\/portfolio\/3096\/revisions\/20050"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ducasseindustrial.com\/testcl\/wp-json\/wp\/v2\/media\/3098"}],"wp:attachment":[{"href":"https:\/\/ducasseindustrial.com\/testcl\/wp-json\/wp\/v2\/media?parent=3096"}],"wp:term":[{"taxonomy":"portfolio_category","embeddable":true,"href":"https:\/\/ducasseindustrial.com\/testcl\/wp-json\/wp\/v2\/portfolio_category?post=3096"},{"taxonomy":"portfolio_tag","embeddable":true,"href":"https:\/\/ducasseindustrial.com\/testcl\/wp-json\/wp\/v2\/portfolio_tag?post=3096"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}