{"id":9838,"date":"2021-01-06T00:20:33","date_gmt":"2021-01-06T04:20:33","guid":{"rendered":"https:\/\/ducasseindustrial.com\/testcl\/producto\/plegaduc-pro-2-hojas"},"modified":"2021-01-06T00:20:36","modified_gmt":"2021-01-06T04:20:36","slug":"plegaduc-pro-2-hojas","status":"publish","type":"product","link":"https:\/\/ducasseindustrial.com\/testcl\/producto\/plegaduc-pro-2-hojas","title":{"rendered":"PLEGADUC PRO 2 HOJAS"},"content":{"rendered":"<p>Sistema de pivotes para montar dos puertas plegables de cl\u00f3set de hasta 15KG cada puerta, en base a un eje vertical. Permite ser instalado sin necesidad de laterales gracias a su fijaci\u00f3n con pivotes. Posee sistema de freno y retenci\u00f3n, haciendo que las puertas se mantengan cerradas, evitando una apertura accidental. Sistema se utiliza con gu\u00eda canal CD-50 AL.<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Sistema de pivotes para montar dos puertas plegables de cl\u00f3set de hasta 15KG cada puerta, en base a un eje vertical. Permite ser instalado sin necesidad de laterales gracias a su fijaci\u00f3n con pivotes. Posee sistema de freno y retenci\u00f3n, haciendo que las puertas se mantengan cerradas, evitando una apertura accidental. Sistema se utiliza con [&hellip;]<\/p>\n","protected":false},"featured_media":3827,"comment_status":"closed","ping_status":"open","template":"","meta":{"_uag_custom_page_level_css":"","site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"default","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"_vp_format_video_url":"","_vp_image_focal_point":[]},"product_brand":[],"product_cat":[17,227,260],"product_tag":[230,198,199,240,355],"class_list":{"0":"post-9838","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-productos","7":"product_cat-closet","8":"product_cat-sistemas-plegables","9":"product_tag-closet","10":"product_tag-ducasse","11":"product_tag-industrial","12":"product_tag-plegable","13":"product_tag-plegaduc","14":"desktop-align-left","15":"tablet-align-left","16":"mobile-align-left","17":"ast-product-gallery-layout-horizontal","18":"ast-product-tabs-layout-horizontal","20":"first","21":"instock","22":"sold-individually","23":"purchasable","24":"product-type-simple"},"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 5.0.0.1 - aioseo.com -->\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/ducasseindustrial.com\/testcl\/producto\/plegaduc-pro-2-hojas\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 5.0.0.1\" \/>\n\t\t<meta property=\"og:locale\" content=\"es_ES\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Test Chile | Somos una empresa Chilena, con m\u00e1s de 50 a\u00f1os de experiencia en la fabricaci\u00f3n de herrajes para la industria del mueble y la construcci\u00f3n, satisfaciendo necesidades tanto en mercados locales como extranjeros.\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"PLEGADUC PRO 2 HOJAS | Test Chile\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/ducasseindustrial.com\/testcl\/producto\/plegaduc-pro-2-hojas\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/ducasseindustrial.com\/testcl\/wp-content\/uploads\/sites\/27\/2024\/04\/logo_web_ducasse.svg\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/ducasseindustrial.com\/testcl\/wp-content\/uploads\/sites\/27\/2024\/04\/logo_web_ducasse.svg\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2021-01-06T04:20:33+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2021-01-06T04:20:36+00:00\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary\" \/>\n\t\t<meta name=\"twitter:title\" content=\"PLEGADUC PRO 2 HOJAS | Test Chile\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/ducasseindustrial.com\/testcl\/wp-content\/uploads\/sites\/27\/2024\/04\/logo_web_ducasse.svg\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/ducasseindustrial.com\\\/testcl\\\/producto\\\/plegaduc-pro-2-hojas#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ducasseindustrial.com\\\/testcl#listItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\\\/\\\/ducasseindustrial.com\\\/testcl\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ducasseindustrial.com\\\/testcl\\\/shop#listItem\",\"name\":\"Shop\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ducasseindustrial.com\\\/testcl\\\/shop#listItem\",\"position\":2,\"name\":\"Shop\",\"item\":\"https:\\\/\\\/ducasseindustrial.com\\\/testcl\\\/shop\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ducasseindustrial.com\\\/testcl\\\/product-category\\\/productos#listItem\",\"name\":\"Productos\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ducasseindustrial.com\\\/testcl#listItem\",\"name\":\"Inicio\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ducasseindustrial.com\\\/testcl\\\/product-category\\\/productos#listItem\",\"position\":3,\"name\":\"Productos\",\"item\":\"https:\\\/\\\/ducasseindustrial.com\\\/testcl\\\/product-category\\\/productos\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ducasseindustrial.com\\\/testcl\\\/product-category\\\/productos\\\/closet#listItem\",\"name\":\"CL\\u00d3SET\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ducasseindustrial.com\\\/testcl\\\/shop#listItem\",\"name\":\"Shop\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ducasseindustrial.com\\\/testcl\\\/product-category\\\/productos\\\/closet#listItem\",\"position\":4,\"name\":\"CL\\u00d3SET\",\"item\":\"https:\\\/\\\/ducasseindustrial.com\\\/testcl\\\/product-category\\\/productos\\\/closet\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ducasseindustrial.com\\\/testcl\\\/product-category\\\/productos\\\/closet\\\/sistemas-plegables#listItem\",\"name\":\"SISTEMAS PLEGABLES\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ducasseindustrial.com\\\/testcl\\\/product-category\\\/productos#listItem\",\"name\":\"Productos\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ducasseindustrial.com\\\/testcl\\\/product-category\\\/productos\\\/closet\\\/sistemas-plegables#listItem\",\"position\":5,\"name\":\"SISTEMAS PLEGABLES\",\"item\":\"https:\\\/\\\/ducasseindustrial.com\\\/testcl\\\/product-category\\\/productos\\\/closet\\\/sistemas-plegables\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ducasseindustrial.com\\\/testcl\\\/producto\\\/plegaduc-pro-2-hojas#listItem\",\"name\":\"PLEGADUC PRO 2 HOJAS\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ducasseindustrial.com\\\/testcl\\\/product-category\\\/productos\\\/closet#listItem\",\"name\":\"CL\\u00d3SET\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ducasseindustrial.com\\\/testcl\\\/producto\\\/plegaduc-pro-2-hojas#listItem\",\"position\":6,\"name\":\"PLEGADUC PRO 2 HOJAS\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ducasseindustrial.com\\\/testcl\\\/product-category\\\/productos\\\/closet\\\/sistemas-plegables#listItem\",\"name\":\"SISTEMAS PLEGABLES\"}}]},{\"@type\":\"ItemPage\",\"@id\":\"https:\\\/\\\/ducasseindustrial.com\\\/testcl\\\/producto\\\/plegaduc-pro-2-hojas#itempage\",\"url\":\"https:\\\/\\\/ducasseindustrial.com\\\/testcl\\\/producto\\\/plegaduc-pro-2-hojas\",\"name\":\"PLEGADUC PRO 2 HOJAS | Test Chile\",\"inLanguage\":\"es-CL\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/ducasseindustrial.com\\\/testcl\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/ducasseindustrial.com\\\/testcl\\\/producto\\\/plegaduc-pro-2-hojas#breadcrumblist\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/ducasseindustrial.com\\\/testcl\\\/wp-content\\\/uploads\\\/sites\\\/27\\\/2020\\\/09\\\/CL_10100253062_IMG_PROD1_BL.jpg\",\"@id\":\"https:\\\/\\\/ducasseindustrial.com\\\/testcl\\\/producto\\\/plegaduc-pro-2-hojas\\\/#mainImage\",\"width\":1920,\"height\":1080},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/ducasseindustrial.com\\\/testcl\\\/producto\\\/plegaduc-pro-2-hojas#mainImage\"},\"datePublished\":\"2021-01-06T00:20:33-04:00\",\"dateModified\":\"2021-01-06T00:20:36-04:00\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/ducasseindustrial.com\\\/testcl\\\/#organization\",\"name\":\"Test Chile\",\"description\":\"Somos una empresa Chilena, con m\\u00e1s de 50 a\\u00f1os de experiencia en la fabricaci\\u00f3n de herrajes para la industria del mueble y la construcci\\u00f3n, satisfaciendo necesidades tanto en mercados locales como extranjeros.\",\"url\":\"https:\\\/\\\/ducasseindustrial.com\\\/testcl\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/ducasseindustrial.com\\\/testcl\\\/wp-content\\\/uploads\\\/sites\\\/27\\\/2024\\\/04\\\/logo_web_ducasse.svg\",\"@id\":\"https:\\\/\\\/ducasseindustrial.com\\\/testcl\\\/producto\\\/plegaduc-pro-2-hojas\\\/#organizationLogo\",\"width\":1004,\"height\":294},\"image\":{\"@id\":\"https:\\\/\\\/ducasseindustrial.com\\\/testcl\\\/producto\\\/plegaduc-pro-2-hojas\\\/#organizationLogo\"}},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/ducasseindustrial.com\\\/testcl\\\/#website\",\"url\":\"https:\\\/\\\/ducasseindustrial.com\\\/testcl\\\/\",\"name\":\"Test Chile\",\"description\":\"Somos una empresa Chilena, con m\\u00e1s de 50 a\\u00f1os de experiencia en la fabricaci\\u00f3n de herrajes para la industria del mueble y la construcci\\u00f3n, satisfaciendo necesidades tanto en mercados locales como extranjeros.\",\"inLanguage\":\"es-CL\",\"publisher\":{\"@id\":\"https:\\\/\\\/ducasseindustrial.com\\\/testcl\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"PLEGADUC PRO 2 HOJAS | Test Chile","description":"","canonical_url":"https:\/\/ducasseindustrial.com\/testcl\/producto\/plegaduc-pro-2-hojas","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BreadcrumbList","@id":"https:\/\/ducasseindustrial.com\/testcl\/producto\/plegaduc-pro-2-hojas#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/ducasseindustrial.com\/testcl#listItem","position":1,"name":"Inicio","item":"https:\/\/ducasseindustrial.com\/testcl","nextItem":{"@type":"ListItem","@id":"https:\/\/ducasseindustrial.com\/testcl\/shop#listItem","name":"Shop"}},{"@type":"ListItem","@id":"https:\/\/ducasseindustrial.com\/testcl\/shop#listItem","position":2,"name":"Shop","item":"https:\/\/ducasseindustrial.com\/testcl\/shop","nextItem":{"@type":"ListItem","@id":"https:\/\/ducasseindustrial.com\/testcl\/product-category\/productos#listItem","name":"Productos"},"previousItem":{"@type":"ListItem","@id":"https:\/\/ducasseindustrial.com\/testcl#listItem","name":"Inicio"}},{"@type":"ListItem","@id":"https:\/\/ducasseindustrial.com\/testcl\/product-category\/productos#listItem","position":3,"name":"Productos","item":"https:\/\/ducasseindustrial.com\/testcl\/product-category\/productos","nextItem":{"@type":"ListItem","@id":"https:\/\/ducasseindustrial.com\/testcl\/product-category\/productos\/closet#listItem","name":"CL\u00d3SET"},"previousItem":{"@type":"ListItem","@id":"https:\/\/ducasseindustrial.com\/testcl\/shop#listItem","name":"Shop"}},{"@type":"ListItem","@id":"https:\/\/ducasseindustrial.com\/testcl\/product-category\/productos\/closet#listItem","position":4,"name":"CL\u00d3SET","item":"https:\/\/ducasseindustrial.com\/testcl\/product-category\/productos\/closet","nextItem":{"@type":"ListItem","@id":"https:\/\/ducasseindustrial.com\/testcl\/product-category\/productos\/closet\/sistemas-plegables#listItem","name":"SISTEMAS PLEGABLES"},"previousItem":{"@type":"ListItem","@id":"https:\/\/ducasseindustrial.com\/testcl\/product-category\/productos#listItem","name":"Productos"}},{"@type":"ListItem","@id":"https:\/\/ducasseindustrial.com\/testcl\/product-category\/productos\/closet\/sistemas-plegables#listItem","position":5,"name":"SISTEMAS PLEGABLES","item":"https:\/\/ducasseindustrial.com\/testcl\/product-category\/productos\/closet\/sistemas-plegables","nextItem":{"@type":"ListItem","@id":"https:\/\/ducasseindustrial.com\/testcl\/producto\/plegaduc-pro-2-hojas#listItem","name":"PLEGADUC PRO 2 HOJAS"},"previousItem":{"@type":"ListItem","@id":"https:\/\/ducasseindustrial.com\/testcl\/product-category\/productos\/closet#listItem","name":"CL\u00d3SET"}},{"@type":"ListItem","@id":"https:\/\/ducasseindustrial.com\/testcl\/producto\/plegaduc-pro-2-hojas#listItem","position":6,"name":"PLEGADUC PRO 2 HOJAS","previousItem":{"@type":"ListItem","@id":"https:\/\/ducasseindustrial.com\/testcl\/product-category\/productos\/closet\/sistemas-plegables#listItem","name":"SISTEMAS PLEGABLES"}}]},{"@type":"ItemPage","@id":"https:\/\/ducasseindustrial.com\/testcl\/producto\/plegaduc-pro-2-hojas#itempage","url":"https:\/\/ducasseindustrial.com\/testcl\/producto\/plegaduc-pro-2-hojas","name":"PLEGADUC PRO 2 HOJAS | Test Chile","inLanguage":"es-CL","isPartOf":{"@id":"https:\/\/ducasseindustrial.com\/testcl\/#website"},"breadcrumb":{"@id":"https:\/\/ducasseindustrial.com\/testcl\/producto\/plegaduc-pro-2-hojas#breadcrumblist"},"image":{"@type":"ImageObject","url":"https:\/\/ducasseindustrial.com\/testcl\/wp-content\/uploads\/sites\/27\/2020\/09\/CL_10100253062_IMG_PROD1_BL.jpg","@id":"https:\/\/ducasseindustrial.com\/testcl\/producto\/plegaduc-pro-2-hojas\/#mainImage","width":1920,"height":1080},"primaryImageOfPage":{"@id":"https:\/\/ducasseindustrial.com\/testcl\/producto\/plegaduc-pro-2-hojas#mainImage"},"datePublished":"2021-01-06T00:20:33-04:00","dateModified":"2021-01-06T00:20:36-04:00"},{"@type":"Organization","@id":"https:\/\/ducasseindustrial.com\/testcl\/#organization","name":"Test Chile","description":"Somos una empresa Chilena, con m\u00e1s de 50 a\u00f1os de experiencia en la fabricaci\u00f3n de herrajes para la industria del mueble y la construcci\u00f3n, satisfaciendo necesidades tanto en mercados locales como extranjeros.","url":"https:\/\/ducasseindustrial.com\/testcl\/","logo":{"@type":"ImageObject","url":"https:\/\/ducasseindustrial.com\/testcl\/wp-content\/uploads\/sites\/27\/2024\/04\/logo_web_ducasse.svg","@id":"https:\/\/ducasseindustrial.com\/testcl\/producto\/plegaduc-pro-2-hojas\/#organizationLogo","width":1004,"height":294},"image":{"@id":"https:\/\/ducasseindustrial.com\/testcl\/producto\/plegaduc-pro-2-hojas\/#organizationLogo"}},{"@type":"WebSite","@id":"https:\/\/ducasseindustrial.com\/testcl\/#website","url":"https:\/\/ducasseindustrial.com\/testcl\/","name":"Test Chile","description":"Somos una empresa Chilena, con m\u00e1s de 50 a\u00f1os de experiencia en la fabricaci\u00f3n de herrajes para la industria del mueble y la construcci\u00f3n, satisfaciendo necesidades tanto en mercados locales como extranjeros.","inLanguage":"es-CL","publisher":{"@id":"https:\/\/ducasseindustrial.com\/testcl\/#organization"}}]},"og:locale":"es_ES","og:site_name":"Test Chile | Somos una empresa Chilena, con m\u00e1s de 50 a\u00f1os de experiencia en la fabricaci\u00f3n de herrajes para la industria del mueble y la construcci\u00f3n, satisfaciendo necesidades tanto en mercados locales como extranjeros.","og:type":"article","og:title":"PLEGADUC PRO 2 HOJAS | Test Chile","og:url":"https:\/\/ducasseindustrial.com\/testcl\/producto\/plegaduc-pro-2-hojas","og:image":"https:\/\/ducasseindustrial.com\/testcl\/wp-content\/uploads\/sites\/27\/2024\/04\/logo_web_ducasse.svg","og:image:secure_url":"https:\/\/ducasseindustrial.com\/testcl\/wp-content\/uploads\/sites\/27\/2024\/04\/logo_web_ducasse.svg","article:published_time":"2021-01-06T04:20:33+00:00","article:modified_time":"2021-01-06T04:20:36+00:00","twitter:card":"summary","twitter:title":"PLEGADUC PRO 2 HOJAS | Test Chile","twitter:image":"https:\/\/ducasseindustrial.com\/testcl\/wp-content\/uploads\/sites\/27\/2024\/04\/logo_web_ducasse.svg"},"aioseo_meta_data":{"post_id":"9838","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":null,"isEnabled":true},"graphs":[]},"schema_type":null,"schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","priority":null,"frequency":null,"local_seo":null,"breadcrumb_settings":null,"limit_modified_date":false,"ai":null,"created":"2021-03-01 11:17:03","updated":"2025-11-01 11:04:23","focus_keyword":null,"additional_keywords":null,"truseo_locale":null,"seo_analyzer_scan_date":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/ducasseindustrial.com\/testcl\" title=\"Inicio\">Inicio<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">\u00bb<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/ducasseindustrial.com\/testcl\/shop\" title=\"Shop\">Shop<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">\u00bb<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/ducasseindustrial.com\/testcl\/product-category\/productos\" title=\"Productos\">Productos<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">\u00bb<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/ducasseindustrial.com\/testcl\/product-category\/productos\/closet\" title=\"CL\u00d3SET\">CL\u00d3SET<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">\u00bb<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/ducasseindustrial.com\/testcl\/product-category\/productos\/closet\/sistemas-plegables\" title=\"SISTEMAS PLEGABLES\">SISTEMAS PLEGABLES<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">\u00bb<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tPLEGADUC PRO 2 HOJAS\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Inicio","link":"https:\/\/ducasseindustrial.com\/testcl"},{"label":"Shop","link":"https:\/\/ducasseindustrial.com\/testcl\/shop"},{"label":"Productos","link":"https:\/\/ducasseindustrial.com\/testcl\/product-category\/productos"},{"label":"CL\u00d3SET","link":"https:\/\/ducasseindustrial.com\/testcl\/product-category\/productos\/closet"},{"label":"SISTEMAS PLEGABLES","link":"https:\/\/ducasseindustrial.com\/testcl\/product-category\/productos\/closet\/sistemas-plegables"},{"label":"PLEGADUC PRO 2 HOJAS","link":"https:\/\/ducasseindustrial.com\/testcl\/producto\/plegaduc-pro-2-hojas"}],"uagb_featured_image_src":{"full":["https:\/\/ducasseindustrial.com\/testcl\/wp-content\/uploads\/sites\/27\/2020\/09\/CL_10100253062_IMG_PROD1_BL.jpg",1920,1080,false],"thumbnail":["https:\/\/ducasseindustrial.com\/testcl\/wp-content\/uploads\/sites\/27\/2020\/09\/CL_10100253062_IMG_PROD1_BL-300x300.jpg",300,300,true],"medium":["https:\/\/ducasseindustrial.com\/testcl\/wp-content\/uploads\/sites\/27\/2020\/09\/CL_10100253062_IMG_PROD1_BL-600x338.jpg",600,338,true],"medium_large":["https:\/\/ducasseindustrial.com\/testcl\/wp-content\/uploads\/sites\/27\/2020\/09\/CL_10100253062_IMG_PROD1_BL-768x432.jpg",768,432,true],"large":["https:\/\/ducasseindustrial.com\/testcl\/wp-content\/uploads\/sites\/27\/2020\/09\/CL_10100253062_IMG_PROD1_BL-1024x576.jpg",1024,576,true],"1536x1536":["https:\/\/ducasseindustrial.com\/testcl\/wp-content\/uploads\/sites\/27\/2020\/09\/CL_10100253062_IMG_PROD1_BL-1536x864.jpg",1536,864,true],"2048x2048":["https:\/\/ducasseindustrial.com\/testcl\/wp-content\/uploads\/sites\/27\/2020\/09\/CL_10100253062_IMG_PROD1_BL.jpg",1920,1080,false],"vp_sm":["https:\/\/ducasseindustrial.com\/testcl\/wp-content\/uploads\/sites\/27\/2020\/09\/CL_10100253062_IMG_PROD1_BL-500x281.jpg",500,281,true],"vp_md":["https:\/\/ducasseindustrial.com\/testcl\/wp-content\/uploads\/sites\/27\/2020\/09\/CL_10100253062_IMG_PROD1_BL-800x450.jpg",800,450,true],"vp_lg":["https:\/\/ducasseindustrial.com\/testcl\/wp-content\/uploads\/sites\/27\/2020\/09\/CL_10100253062_IMG_PROD1_BL-1280x720.jpg",1280,720,true],"vp_xl":["https:\/\/ducasseindustrial.com\/testcl\/wp-content\/uploads\/sites\/27\/2020\/09\/CL_10100253062_IMG_PROD1_BL.jpg",1920,1080,false],"vp_sm_popup":["https:\/\/ducasseindustrial.com\/testcl\/wp-content\/uploads\/sites\/27\/2020\/09\/CL_10100253062_IMG_PROD1_BL-500x281.jpg",500,281,true],"vp_md_popup":["https:\/\/ducasseindustrial.com\/testcl\/wp-content\/uploads\/sites\/27\/2020\/09\/CL_10100253062_IMG_PROD1_BL-800x450.jpg",800,450,true],"vp_xl_popup":["https:\/\/ducasseindustrial.com\/testcl\/wp-content\/uploads\/sites\/27\/2020\/09\/CL_10100253062_IMG_PROD1_BL.jpg",1920,1080,false],"woocommerce_thumbnail":["https:\/\/ducasseindustrial.com\/testcl\/wp-content\/uploads\/sites\/27\/2020\/09\/CL_10100253062_IMG_PROD1_BL-300x300.jpg",300,300,true],"woocommerce_single":["https:\/\/ducasseindustrial.com\/testcl\/wp-content\/uploads\/sites\/27\/2020\/09\/CL_10100253062_IMG_PROD1_BL-1024x576.jpg",1024,576,true],"woocommerce_gallery_thumbnail":["https:\/\/ducasseindustrial.com\/testcl\/wp-content\/uploads\/sites\/27\/2020\/09\/CL_10100253062_IMG_PROD1_BL-100x100.jpg",100,100,true],"variation_swatches_image_size":["https:\/\/ducasseindustrial.com\/testcl\/wp-content\/uploads\/sites\/27\/2020\/09\/CL_10100253062_IMG_PROD1_BL.jpg",50,28,false],"variation_swatches_tooltip_size":["https:\/\/ducasseindustrial.com\/testcl\/wp-content\/uploads\/sites\/27\/2020\/09\/CL_10100253062_IMG_PROD1_BL.jpg",100,56,false]},"uagb_author_info":{"display_name":"user","author_link":"https:\/\/ducasseindustrial.com\/testcl\/archivo\/author"},"uagb_comment_info":0,"uagb_excerpt":"Sistema de pivotes para montar dos puertas plegables de cl\u00f3set de hasta 15KG cada puerta, en base a un eje vertical. Permite ser instalado sin necesidad de laterales gracias a su fijaci\u00f3n con pivotes. Posee sistema de freno y retenci\u00f3n, haciendo que las puertas se mantengan cerradas, evitando una apertura accidental. Sistema se utiliza con&hellip;","_links":{"self":[{"href":"https:\/\/ducasseindustrial.com\/testcl\/wp-json\/wp\/v2\/product\/9838","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ducasseindustrial.com\/testcl\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/ducasseindustrial.com\/testcl\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/ducasseindustrial.com\/testcl\/wp-json\/wp\/v2\/comments?post=9838"}],"version-history":[{"count":3,"href":"https:\/\/ducasseindustrial.com\/testcl\/wp-json\/wp\/v2\/product\/9838\/revisions"}],"predecessor-version":[{"id":17302,"href":"https:\/\/ducasseindustrial.com\/testcl\/wp-json\/wp\/v2\/product\/9838\/revisions\/17302"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ducasseindustrial.com\/testcl\/wp-json\/wp\/v2\/media\/3827"}],"wp:attachment":[{"href":"https:\/\/ducasseindustrial.com\/testcl\/wp-json\/wp\/v2\/media?parent=9838"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/ducasseindustrial.com\/testcl\/wp-json\/wp\/v2\/product_brand?post=9838"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/ducasseindustrial.com\/testcl\/wp-json\/wp\/v2\/product_cat?post=9838"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/ducasseindustrial.com\/testcl\/wp-json\/wp\/v2\/product_tag?post=9838"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}