{"id":9965,"date":"2021-01-06T00:20:22","date_gmt":"2021-01-06T04:20:22","guid":{"rendered":"https:\/\/ducasseindustrial.com\/testcl\/producto\/cd-50-s"},"modified":"2021-01-06T00:20:25","modified_gmt":"2021-01-06T04:20:25","slug":"cd-50-s","status":"publish","type":"product","link":"https:\/\/ducasseindustrial.com\/testcl\/producto\/cd-50-s","title":{"rendered":"CD 50 S"},"content":{"rendered":"<p>Sistema corredizo al piso para puertas de cl\u00f3set, con rodamiento premium, para puertas de 15kgs hasta 50kgs. Instalaci\u00f3n sobrepuesta. Se puede usar para configuraciones de 2 o m\u00e1s puertas. Se utiliza con perfil gu\u00eda GO-30 y dependiento del requerimiento de su dise\u00f1o puede ser utilizado con: Riel embutido CX, Riel AL CD-50 CX, Riel Doble CX 30<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Sistema corredizo al piso para puertas de cl\u00f3set, con rodamiento premium, para puertas de 15kgs hasta 50kgs. Instalaci\u00f3n sobrepuesta. Se puede usar para configuraciones de 2 o m\u00e1s puertas. Se utiliza con perfil gu\u00eda GO-30 y dependiento del requerimiento de su dise\u00f1o puede ser utilizado con: Riel embutido CX, Riel AL CD-50 CX, Riel Doble [&hellip;]<\/p>\n","protected":false},"featured_media":11184,"comment_status":"closed","ping_status":"open","template":"","meta":{"_uag_custom_page_level_css":"","site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"default","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"_vp_format_video_url":"","_vp_image_focal_point":[]},"product_brand":[],"product_cat":[17,227,276],"product_tag":[282,280,281,230,207,231,198,199,206,277,278],"class_list":{"0":"post-9965","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-productos","7":"product_cat-closet","8":"product_cat-sistemas-al-piso","9":"product_tag-antidescarrilamiento","10":"product_tag-cd-50","11":"product_tag-cd50","12":"product_tag-closet","13":"product_tag-corredera","14":"product_tag-corredizo","15":"product_tag-ducasse","16":"product_tag-industrial","17":"product_tag-puerta","18":"product_tag-silencioso","19":"product_tag-suave","20":"desktop-align-left","21":"tablet-align-left","22":"mobile-align-left","23":"ast-product-gallery-layout-horizontal","24":"ast-product-tabs-layout-horizontal","26":"first","27":"instock","28":"sold-individually","29":"purchasable","30":"product-type-simple"},"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 5.0.0.1 - aioseo.com -->\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/ducasseindustrial.com\/testcl\/producto\/cd-50-s\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 5.0.0.1\" \/>\n\t\t<meta property=\"og:locale\" content=\"es_ES\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Test Chile | Somos una empresa Chilena, con m\u00e1s de 50 a\u00f1os de experiencia en la fabricaci\u00f3n de herrajes para la industria del mueble y la construcci\u00f3n, satisfaciendo necesidades tanto en mercados locales como extranjeros.\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"CD 50 S | Test Chile\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/ducasseindustrial.com\/testcl\/producto\/cd-50-s\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/ducasseindustrial.com\/testcl\/wp-content\/uploads\/sites\/27\/2024\/04\/logo_web_ducasse.svg\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/ducasseindustrial.com\/testcl\/wp-content\/uploads\/sites\/27\/2024\/04\/logo_web_ducasse.svg\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2021-01-06T04:20:22+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2021-01-06T04:20:25+00:00\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary\" \/>\n\t\t<meta name=\"twitter:title\" content=\"CD 50 S | Test Chile\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/ducasseindustrial.com\/testcl\/wp-content\/uploads\/sites\/27\/2024\/04\/logo_web_ducasse.svg\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/ducasseindustrial.com\\\/testcl\\\/producto\\\/cd-50-s#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ducasseindustrial.com\\\/testcl#listItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\\\/\\\/ducasseindustrial.com\\\/testcl\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ducasseindustrial.com\\\/testcl\\\/shop#listItem\",\"name\":\"Shop\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ducasseindustrial.com\\\/testcl\\\/shop#listItem\",\"position\":2,\"name\":\"Shop\",\"item\":\"https:\\\/\\\/ducasseindustrial.com\\\/testcl\\\/shop\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ducasseindustrial.com\\\/testcl\\\/product-category\\\/productos#listItem\",\"name\":\"Productos\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ducasseindustrial.com\\\/testcl#listItem\",\"name\":\"Inicio\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ducasseindustrial.com\\\/testcl\\\/product-category\\\/productos#listItem\",\"position\":3,\"name\":\"Productos\",\"item\":\"https:\\\/\\\/ducasseindustrial.com\\\/testcl\\\/product-category\\\/productos\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ducasseindustrial.com\\\/testcl\\\/product-category\\\/productos\\\/closet#listItem\",\"name\":\"CL\\u00d3SET\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ducasseindustrial.com\\\/testcl\\\/shop#listItem\",\"name\":\"Shop\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ducasseindustrial.com\\\/testcl\\\/product-category\\\/productos\\\/closet#listItem\",\"position\":4,\"name\":\"CL\\u00d3SET\",\"item\":\"https:\\\/\\\/ducasseindustrial.com\\\/testcl\\\/product-category\\\/productos\\\/closet\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ducasseindustrial.com\\\/testcl\\\/product-category\\\/productos\\\/closet\\\/sistemas-al-piso#listItem\",\"name\":\"SISTEMAS AL PISO\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ducasseindustrial.com\\\/testcl\\\/product-category\\\/productos#listItem\",\"name\":\"Productos\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ducasseindustrial.com\\\/testcl\\\/product-category\\\/productos\\\/closet\\\/sistemas-al-piso#listItem\",\"position\":5,\"name\":\"SISTEMAS AL PISO\",\"item\":\"https:\\\/\\\/ducasseindustrial.com\\\/testcl\\\/product-category\\\/productos\\\/closet\\\/sistemas-al-piso\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ducasseindustrial.com\\\/testcl\\\/producto\\\/cd-50-s#listItem\",\"name\":\"CD 50 S\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ducasseindustrial.com\\\/testcl\\\/product-category\\\/productos\\\/closet#listItem\",\"name\":\"CL\\u00d3SET\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ducasseindustrial.com\\\/testcl\\\/producto\\\/cd-50-s#listItem\",\"position\":6,\"name\":\"CD 50 S\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/ducasseindustrial.com\\\/testcl\\\/product-category\\\/productos\\\/closet\\\/sistemas-al-piso#listItem\",\"name\":\"SISTEMAS AL PISO\"}}]},{\"@type\":\"ItemPage\",\"@id\":\"https:\\\/\\\/ducasseindustrial.com\\\/testcl\\\/producto\\\/cd-50-s#itempage\",\"url\":\"https:\\\/\\\/ducasseindustrial.com\\\/testcl\\\/producto\\\/cd-50-s\",\"name\":\"CD 50 S | Test Chile\",\"inLanguage\":\"es-CL\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/ducasseindustrial.com\\\/testcl\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/ducasseindustrial.com\\\/testcl\\\/producto\\\/cd-50-s#breadcrumblist\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/ducasseindustrial.com\\\/testcl\\\/wp-content\\\/uploads\\\/sites\\\/27\\\/2020\\\/09\\\/CL_10100106560_IMG_PROD1_BL.jpg\",\"@id\":\"https:\\\/\\\/ducasseindustrial.com\\\/testcl\\\/producto\\\/cd-50-s\\\/#mainImage\",\"width\":1920,\"height\":1080},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/ducasseindustrial.com\\\/testcl\\\/producto\\\/cd-50-s#mainImage\"},\"datePublished\":\"2021-01-06T00:20:22-04:00\",\"dateModified\":\"2021-01-06T00:20:25-04:00\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/ducasseindustrial.com\\\/testcl\\\/#organization\",\"name\":\"Test Chile\",\"description\":\"Somos una empresa Chilena, con m\\u00e1s de 50 a\\u00f1os de experiencia en la fabricaci\\u00f3n de herrajes para la industria del mueble y la construcci\\u00f3n, satisfaciendo necesidades tanto en mercados locales como extranjeros.\",\"url\":\"https:\\\/\\\/ducasseindustrial.com\\\/testcl\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/ducasseindustrial.com\\\/testcl\\\/wp-content\\\/uploads\\\/sites\\\/27\\\/2024\\\/04\\\/logo_web_ducasse.svg\",\"@id\":\"https:\\\/\\\/ducasseindustrial.com\\\/testcl\\\/producto\\\/cd-50-s\\\/#organizationLogo\",\"width\":1004,\"height\":294},\"image\":{\"@id\":\"https:\\\/\\\/ducasseindustrial.com\\\/testcl\\\/producto\\\/cd-50-s\\\/#organizationLogo\"}},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/ducasseindustrial.com\\\/testcl\\\/#website\",\"url\":\"https:\\\/\\\/ducasseindustrial.com\\\/testcl\\\/\",\"name\":\"Test Chile\",\"description\":\"Somos una empresa Chilena, con m\\u00e1s de 50 a\\u00f1os de experiencia en la fabricaci\\u00f3n de herrajes para la industria del mueble y la construcci\\u00f3n, satisfaciendo necesidades tanto en mercados locales como extranjeros.\",\"inLanguage\":\"es-CL\",\"publisher\":{\"@id\":\"https:\\\/\\\/ducasseindustrial.com\\\/testcl\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"CD 50 S | Test Chile","description":"","canonical_url":"https:\/\/ducasseindustrial.com\/testcl\/producto\/cd-50-s","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BreadcrumbList","@id":"https:\/\/ducasseindustrial.com\/testcl\/producto\/cd-50-s#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/ducasseindustrial.com\/testcl#listItem","position":1,"name":"Inicio","item":"https:\/\/ducasseindustrial.com\/testcl","nextItem":{"@type":"ListItem","@id":"https:\/\/ducasseindustrial.com\/testcl\/shop#listItem","name":"Shop"}},{"@type":"ListItem","@id":"https:\/\/ducasseindustrial.com\/testcl\/shop#listItem","position":2,"name":"Shop","item":"https:\/\/ducasseindustrial.com\/testcl\/shop","nextItem":{"@type":"ListItem","@id":"https:\/\/ducasseindustrial.com\/testcl\/product-category\/productos#listItem","name":"Productos"},"previousItem":{"@type":"ListItem","@id":"https:\/\/ducasseindustrial.com\/testcl#listItem","name":"Inicio"}},{"@type":"ListItem","@id":"https:\/\/ducasseindustrial.com\/testcl\/product-category\/productos#listItem","position":3,"name":"Productos","item":"https:\/\/ducasseindustrial.com\/testcl\/product-category\/productos","nextItem":{"@type":"ListItem","@id":"https:\/\/ducasseindustrial.com\/testcl\/product-category\/productos\/closet#listItem","name":"CL\u00d3SET"},"previousItem":{"@type":"ListItem","@id":"https:\/\/ducasseindustrial.com\/testcl\/shop#listItem","name":"Shop"}},{"@type":"ListItem","@id":"https:\/\/ducasseindustrial.com\/testcl\/product-category\/productos\/closet#listItem","position":4,"name":"CL\u00d3SET","item":"https:\/\/ducasseindustrial.com\/testcl\/product-category\/productos\/closet","nextItem":{"@type":"ListItem","@id":"https:\/\/ducasseindustrial.com\/testcl\/product-category\/productos\/closet\/sistemas-al-piso#listItem","name":"SISTEMAS AL PISO"},"previousItem":{"@type":"ListItem","@id":"https:\/\/ducasseindustrial.com\/testcl\/product-category\/productos#listItem","name":"Productos"}},{"@type":"ListItem","@id":"https:\/\/ducasseindustrial.com\/testcl\/product-category\/productos\/closet\/sistemas-al-piso#listItem","position":5,"name":"SISTEMAS AL PISO","item":"https:\/\/ducasseindustrial.com\/testcl\/product-category\/productos\/closet\/sistemas-al-piso","nextItem":{"@type":"ListItem","@id":"https:\/\/ducasseindustrial.com\/testcl\/producto\/cd-50-s#listItem","name":"CD 50 S"},"previousItem":{"@type":"ListItem","@id":"https:\/\/ducasseindustrial.com\/testcl\/product-category\/productos\/closet#listItem","name":"CL\u00d3SET"}},{"@type":"ListItem","@id":"https:\/\/ducasseindustrial.com\/testcl\/producto\/cd-50-s#listItem","position":6,"name":"CD 50 S","previousItem":{"@type":"ListItem","@id":"https:\/\/ducasseindustrial.com\/testcl\/product-category\/productos\/closet\/sistemas-al-piso#listItem","name":"SISTEMAS AL PISO"}}]},{"@type":"ItemPage","@id":"https:\/\/ducasseindustrial.com\/testcl\/producto\/cd-50-s#itempage","url":"https:\/\/ducasseindustrial.com\/testcl\/producto\/cd-50-s","name":"CD 50 S | Test Chile","inLanguage":"es-CL","isPartOf":{"@id":"https:\/\/ducasseindustrial.com\/testcl\/#website"},"breadcrumb":{"@id":"https:\/\/ducasseindustrial.com\/testcl\/producto\/cd-50-s#breadcrumblist"},"image":{"@type":"ImageObject","url":"https:\/\/ducasseindustrial.com\/testcl\/wp-content\/uploads\/sites\/27\/2020\/09\/CL_10100106560_IMG_PROD1_BL.jpg","@id":"https:\/\/ducasseindustrial.com\/testcl\/producto\/cd-50-s\/#mainImage","width":1920,"height":1080},"primaryImageOfPage":{"@id":"https:\/\/ducasseindustrial.com\/testcl\/producto\/cd-50-s#mainImage"},"datePublished":"2021-01-06T00:20:22-04:00","dateModified":"2021-01-06T00:20:25-04:00"},{"@type":"Organization","@id":"https:\/\/ducasseindustrial.com\/testcl\/#organization","name":"Test Chile","description":"Somos una empresa Chilena, con m\u00e1s de 50 a\u00f1os de experiencia en la fabricaci\u00f3n de herrajes para la industria del mueble y la construcci\u00f3n, satisfaciendo necesidades tanto en mercados locales como extranjeros.","url":"https:\/\/ducasseindustrial.com\/testcl\/","logo":{"@type":"ImageObject","url":"https:\/\/ducasseindustrial.com\/testcl\/wp-content\/uploads\/sites\/27\/2024\/04\/logo_web_ducasse.svg","@id":"https:\/\/ducasseindustrial.com\/testcl\/producto\/cd-50-s\/#organizationLogo","width":1004,"height":294},"image":{"@id":"https:\/\/ducasseindustrial.com\/testcl\/producto\/cd-50-s\/#organizationLogo"}},{"@type":"WebSite","@id":"https:\/\/ducasseindustrial.com\/testcl\/#website","url":"https:\/\/ducasseindustrial.com\/testcl\/","name":"Test Chile","description":"Somos una empresa Chilena, con m\u00e1s de 50 a\u00f1os de experiencia en la fabricaci\u00f3n de herrajes para la industria del mueble y la construcci\u00f3n, satisfaciendo necesidades tanto en mercados locales como extranjeros.","inLanguage":"es-CL","publisher":{"@id":"https:\/\/ducasseindustrial.com\/testcl\/#organization"}}]},"og:locale":"es_ES","og:site_name":"Test Chile | Somos una empresa Chilena, con m\u00e1s de 50 a\u00f1os de experiencia en la fabricaci\u00f3n de herrajes para la industria del mueble y la construcci\u00f3n, satisfaciendo necesidades tanto en mercados locales como extranjeros.","og:type":"article","og:title":"CD 50 S | Test Chile","og:url":"https:\/\/ducasseindustrial.com\/testcl\/producto\/cd-50-s","og:image":"https:\/\/ducasseindustrial.com\/testcl\/wp-content\/uploads\/sites\/27\/2024\/04\/logo_web_ducasse.svg","og:image:secure_url":"https:\/\/ducasseindustrial.com\/testcl\/wp-content\/uploads\/sites\/27\/2024\/04\/logo_web_ducasse.svg","article:published_time":"2021-01-06T04:20:22+00:00","article:modified_time":"2021-01-06T04:20:25+00:00","twitter:card":"summary","twitter:title":"CD 50 S | Test Chile","twitter:image":"https:\/\/ducasseindustrial.com\/testcl\/wp-content\/uploads\/sites\/27\/2024\/04\/logo_web_ducasse.svg"},"aioseo_meta_data":{"post_id":"9965","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":null,"isEnabled":true},"graphs":[]},"schema_type":null,"schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","priority":null,"frequency":null,"local_seo":null,"breadcrumb_settings":null,"limit_modified_date":false,"ai":null,"created":"2021-03-01 11:05:20","updated":"2025-11-01 10:59:26","focus_keyword":null,"additional_keywords":null,"truseo_locale":null,"seo_analyzer_scan_date":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/ducasseindustrial.com\/testcl\" title=\"Inicio\">Inicio<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">\u00bb<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/ducasseindustrial.com\/testcl\/shop\" title=\"Shop\">Shop<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">\u00bb<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/ducasseindustrial.com\/testcl\/product-category\/productos\" title=\"Productos\">Productos<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">\u00bb<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/ducasseindustrial.com\/testcl\/product-category\/productos\/closet\" title=\"CL\u00d3SET\">CL\u00d3SET<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">\u00bb<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/ducasseindustrial.com\/testcl\/product-category\/productos\/closet\/sistemas-al-piso\" title=\"SISTEMAS AL PISO\">SISTEMAS AL PISO<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">\u00bb<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tCD 50 S\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Inicio","link":"https:\/\/ducasseindustrial.com\/testcl"},{"label":"Shop","link":"https:\/\/ducasseindustrial.com\/testcl\/shop"},{"label":"Productos","link":"https:\/\/ducasseindustrial.com\/testcl\/product-category\/productos"},{"label":"CL\u00d3SET","link":"https:\/\/ducasseindustrial.com\/testcl\/product-category\/productos\/closet"},{"label":"SISTEMAS AL PISO","link":"https:\/\/ducasseindustrial.com\/testcl\/product-category\/productos\/closet\/sistemas-al-piso"},{"label":"CD 50 S","link":"https:\/\/ducasseindustrial.com\/testcl\/producto\/cd-50-s"}],"uagb_featured_image_src":{"full":["https:\/\/ducasseindustrial.com\/testcl\/wp-content\/uploads\/sites\/27\/2020\/09\/CL_10100106560_IMG_PROD1_BL.jpg",1920,1080,false],"thumbnail":["https:\/\/ducasseindustrial.com\/testcl\/wp-content\/uploads\/sites\/27\/2020\/09\/CL_10100106560_IMG_PROD1_BL-300x300.jpg",300,300,true],"medium":["https:\/\/ducasseindustrial.com\/testcl\/wp-content\/uploads\/sites\/27\/2020\/09\/CL_10100106560_IMG_PROD1_BL-600x338.jpg",600,338,true],"medium_large":["https:\/\/ducasseindustrial.com\/testcl\/wp-content\/uploads\/sites\/27\/2020\/09\/CL_10100106560_IMG_PROD1_BL-768x432.jpg",768,432,true],"large":["https:\/\/ducasseindustrial.com\/testcl\/wp-content\/uploads\/sites\/27\/2020\/09\/CL_10100106560_IMG_PROD1_BL-1024x576.jpg",1024,576,true],"1536x1536":["https:\/\/ducasseindustrial.com\/testcl\/wp-content\/uploads\/sites\/27\/2020\/09\/CL_10100106560_IMG_PROD1_BL-1536x864.jpg",1536,864,true],"2048x2048":["https:\/\/ducasseindustrial.com\/testcl\/wp-content\/uploads\/sites\/27\/2020\/09\/CL_10100106560_IMG_PROD1_BL.jpg",1920,1080,false],"vp_sm":["https:\/\/ducasseindustrial.com\/testcl\/wp-content\/uploads\/sites\/27\/2020\/09\/CL_10100106560_IMG_PROD1_BL-500x281.jpg",500,281,true],"vp_md":["https:\/\/ducasseindustrial.com\/testcl\/wp-content\/uploads\/sites\/27\/2020\/09\/CL_10100106560_IMG_PROD1_BL-800x450.jpg",800,450,true],"vp_lg":["https:\/\/ducasseindustrial.com\/testcl\/wp-content\/uploads\/sites\/27\/2020\/09\/CL_10100106560_IMG_PROD1_BL-1280x720.jpg",1280,720,true],"vp_xl":["https:\/\/ducasseindustrial.com\/testcl\/wp-content\/uploads\/sites\/27\/2020\/09\/CL_10100106560_IMG_PROD1_BL.jpg",1920,1080,false],"vp_sm_popup":["https:\/\/ducasseindustrial.com\/testcl\/wp-content\/uploads\/sites\/27\/2020\/09\/CL_10100106560_IMG_PROD1_BL-500x281.jpg",500,281,true],"vp_md_popup":["https:\/\/ducasseindustrial.com\/testcl\/wp-content\/uploads\/sites\/27\/2020\/09\/CL_10100106560_IMG_PROD1_BL-800x450.jpg",800,450,true],"vp_xl_popup":["https:\/\/ducasseindustrial.com\/testcl\/wp-content\/uploads\/sites\/27\/2020\/09\/CL_10100106560_IMG_PROD1_BL.jpg",1920,1080,false],"woocommerce_thumbnail":["https:\/\/ducasseindustrial.com\/testcl\/wp-content\/uploads\/sites\/27\/2020\/09\/CL_10100106560_IMG_PROD1_BL-300x300.jpg",300,300,true],"woocommerce_single":["https:\/\/ducasseindustrial.com\/testcl\/wp-content\/uploads\/sites\/27\/2020\/09\/CL_10100106560_IMG_PROD1_BL-1024x576.jpg",1024,576,true],"woocommerce_gallery_thumbnail":["https:\/\/ducasseindustrial.com\/testcl\/wp-content\/uploads\/sites\/27\/2020\/09\/CL_10100106560_IMG_PROD1_BL-100x100.jpg",100,100,true],"variation_swatches_image_size":["https:\/\/ducasseindustrial.com\/testcl\/wp-content\/uploads\/sites\/27\/2020\/09\/CL_10100106560_IMG_PROD1_BL.jpg",50,28,false],"variation_swatches_tooltip_size":["https:\/\/ducasseindustrial.com\/testcl\/wp-content\/uploads\/sites\/27\/2020\/09\/CL_10100106560_IMG_PROD1_BL.jpg",100,56,false]},"uagb_author_info":{"display_name":"user","author_link":"https:\/\/ducasseindustrial.com\/testcl\/archivo\/author"},"uagb_comment_info":0,"uagb_excerpt":"Sistema corredizo al piso para puertas de cl\u00f3set, con rodamiento premium, para puertas de 15kgs hasta 50kgs. Instalaci\u00f3n sobrepuesta. Se puede usar para configuraciones de 2 o m\u00e1s puertas. Se utiliza con perfil gu\u00eda GO-30 y dependiento del requerimiento de su dise\u00f1o puede ser utilizado con: Riel embutido CX, Riel AL CD-50 CX, Riel Doble&hellip;","_links":{"self":[{"href":"https:\/\/ducasseindustrial.com\/testcl\/wp-json\/wp\/v2\/product\/9965","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ducasseindustrial.com\/testcl\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/ducasseindustrial.com\/testcl\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/ducasseindustrial.com\/testcl\/wp-json\/wp\/v2\/comments?post=9965"}],"version-history":[{"count":3,"href":"https:\/\/ducasseindustrial.com\/testcl\/wp-json\/wp\/v2\/product\/9965\/revisions"}],"predecessor-version":[{"id":17282,"href":"https:\/\/ducasseindustrial.com\/testcl\/wp-json\/wp\/v2\/product\/9965\/revisions\/17282"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ducasseindustrial.com\/testcl\/wp-json\/wp\/v2\/media\/11184"}],"wp:attachment":[{"href":"https:\/\/ducasseindustrial.com\/testcl\/wp-json\/wp\/v2\/media?parent=9965"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/ducasseindustrial.com\/testcl\/wp-json\/wp\/v2\/product_brand?post=9965"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/ducasseindustrial.com\/testcl\/wp-json\/wp\/v2\/product_cat?post=9965"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/ducasseindustrial.com\/testcl\/wp-json\/wp\/v2\/product_tag?post=9965"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}